{"id":62027,"date":"2021-08-15T14:26:35","date_gmt":"2021-08-15T12:26:35","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=62027"},"modified":"2021-08-15T14:26:42","modified_gmt":"2021-08-15T12:26:42","slug":"ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/","title":{"rendered":"Ferragosto, la Polizia intensifica i servizi di controllo del territorio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Durante il weekend di ferragosto i controlli della Polizia di Stato sono stati notevolmente intensificati <\/strong>e rivolti soprattutto verso quelle localit\u00e0 che da sempre, in questi giorni, rappresentano i luoghi scelti per le tradizionali gite fuori porta. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con ordinanza della Questura, che fornisce concretezza alle indicazioni date dal Prefetto, sono state aumentate le pattuglie, in particolare nelle giornate di sabato e domenica,\u00a0cos\u00ec da elevare al massimo livello l\u2019attivit\u00e0 di controllo del territorio sia ai fini della prevenzione dei reati,\u00a0sia per garantire ulteriormente la sicurezza dei viaggiatori.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In tutta la provincia \u00e8 previsto un massiccio impiego degli agenti della Polizia Stradale, che svolgeranno controlli capillari lungo la rete autostradale e lungo le arterie che conducono alle localit\u00e0 di villeggiatura balneari e montane.&nbsp;Nelle stazioni e a bordo dei treni, a cura della Polizia Ferroviaria, saranno vigilati gli spostamenti dei passeggeri. Come previsto anche dalle indicazioni diffuse dal Viminale sar\u00e0 dedicata particolare attenzione ai controlli sul \u201cGreen Pass\u201d per l\u2019accesso ai luoghi per i quali \u00e8 previsto il possesso della certificazione verde. L&#8217;invito che la Polizia di Stato rivolge a tutti i cittadini della nostra provincia, che finora hanno sempre rispettato con attenzione le regole per il contenimento della pandemia, \u00e8 di continuare a seguire le indicazioni impartite per evitare il propagarsi del virus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsserci sempre\u201d \u00e8 la nostra parola d\u2019ordine ed anche in questi giorni di festa la Polizia di Stato&nbsp;si adopera con sempre crescente impegno per la tranquillit\u00e0 dei cittadini, come ha sottolineato oggi il Questore,&nbsp;in occasione della visita del Prefetto di Frosinone, dott.&nbsp;Ignazio Portelli, presso la Sala Operativa della Questura, il cuore pulsante del controllo del territorio che non si ferma mai, nemmeno in questa giornata dedicata fin dall\u2019antichit\u00e0 allo svago ed al riposo. La presenza del Prefetto ha voluto confermare l\u2019apprezzamento per l\u2019impegno quotidiano che le donne e gli uomini della Polizia di Stato profondono per garantire la sicurezza dei cittadini, come dimostrano anche i risultati ottenuti nell\u2019ultimo anno, riassunti in un rapporto appositamente realizzato dall\u2019Ufficio di Gabinetto della Questura. Dallo stesso emergono dati significativi di un generale decremento dei reati cosiddetti \u201cpredatori\u201d e, per contro, una crescita dei reati informatici o commessi attraverso la rete, tipici dell\u2019intensificazione delle attivit\u00e0 informatiche dovuta alla pandemia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019impegno degli agenti emerge chiaramente dai dati che evidenziano un immutato impegno delle varie articolazioni della Questura, tra cui Squadra Mobile, Digos e Commissariati, nel contrasto alle attivit\u00e0 illecite legate allo spaccio di stupefacenti, alla truffa ed al riciclaggio di denaro, al favoreggiamento dell\u2019immigrazione clandestina, al contrasto del dilagante fenomeno del \u201crevenge porn\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante il weekend di ferragosto i controlli della Polizia di Stato sono stati notevolmente intensificati e rivolti soprattutto verso quelle<\/p>\n","protected":false},"author":26,"featured_media":62028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[94,3683,93,291],"class_list":["post-62027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-ciociaria","tag-controlli-polizia","tag-frosinone","tag-polizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ferragosto, la Polizia intensifica i servizi di controllo del territorio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferragosto, la Polizia intensifica i servizi di controllo del territorio\" \/>\n<meta property=\"og:description\" content=\"Durante il weekend di ferragosto i controlli della Polizia di Stato sono stati notevolmente intensificati e rivolti soprattutto verso quelle\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-15T12:26:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-15T12:26:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/Polish_20210815_142437853.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1912\" \/>\n\t<meta property=\"og:image:height\" content=\"1147\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Ferragosto, la Polizia intensifica i servizi di controllo del territorio\",\"datePublished\":\"2021-08-15T12:26:35+00:00\",\"dateModified\":\"2021-08-15T12:26:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/\"},\"wordCount\":446,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/Polish_20210815_142437853.jpg\",\"keywords\":[\"Ciociaria\",\"Controlli polizia\",\"Frosinone\",\"polizia\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/\",\"name\":\"Ferragosto, la Polizia intensifica i servizi di controllo del territorio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/Polish_20210815_142437853.jpg\",\"datePublished\":\"2021-08-15T12:26:35+00:00\",\"dateModified\":\"2021-08-15T12:26:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/Polish_20210815_142437853.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/Polish_20210815_142437853.jpg\",\"width\":1912,\"height\":1147},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferragosto, la Polizia intensifica i servizi di controllo del territorio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/15\\\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ferragosto, la Polizia intensifica i servizi di controllo del territorio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/","og_locale":"it_IT","og_type":"article","og_title":"Ferragosto, la Polizia intensifica i servizi di controllo del territorio","og_description":"Durante il weekend di ferragosto i controlli della Polizia di Stato sono stati notevolmente intensificati e rivolti soprattutto verso quelle","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-08-15T12:26:35+00:00","article_modified_time":"2021-08-15T12:26:42+00:00","og_image":[{"width":1912,"height":1147,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/Polish_20210815_142437853.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Ferragosto, la Polizia intensifica i servizi di controllo del territorio","datePublished":"2021-08-15T12:26:35+00:00","dateModified":"2021-08-15T12:26:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/"},"wordCount":446,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/Polish_20210815_142437853.jpg","keywords":["Ciociaria","Controlli polizia","Frosinone","polizia"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/","name":"Ferragosto, la Polizia intensifica i servizi di controllo del territorio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/Polish_20210815_142437853.jpg","datePublished":"2021-08-15T12:26:35+00:00","dateModified":"2021-08-15T12:26:42+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/Polish_20210815_142437853.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/Polish_20210815_142437853.jpg","width":1912,"height":1147},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ferragosto, la Polizia intensifica i servizi di controllo del territorio"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/15\/ferragosto-la-polizia-intensifica-i-servizi-di-controllo-del-territorio\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=62027"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62027\/revisions"}],"predecessor-version":[{"id":62029,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62027\/revisions\/62029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/62028"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=62027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=62027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=62027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}