{"id":61636,"date":"2021-08-04T16:15:54","date_gmt":"2021-08-04T14:15:54","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=61636"},"modified":"2021-08-04T16:15:58","modified_gmt":"2021-08-04T14:15:58","slug":"fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/","title":{"rendered":"Fondi per Caregiver alle Asp, approvato l&#8217;emendamento della Battisti"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>\u201cAbbiamo appena approvato in aula l\u2019emendamento che ho presentato al collegato \u2013 PL 294\/2021 \u2013 per stanziare delle risorse alle asp, le nuove aziende pubbliche di servizi alla persona, finalizzate a dare un sostegno economico concreto per i servizi di cura&#8221; <strong>Cos\u00ec in una nota la Presidente della ICCP Enti Locali, Sara Battisti.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Attraverso questo dettato, infatti, almeno il 50% delle risorse regionali potranno essere destinate alle asp per i percorsi di formazione dei caregiver familiari, avvalendosi di enti di formazione accreditati.\u00a0Le asp rappresentano una grande opportunit\u00e0 per i territori: le vecchie IPAB, infatti, sono state razionalizzate negli organigrammi e nei costi, ed ora rappresentano un ente efficiente per offrire rinnovati servizi ai nostri cittadini&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Si tratta di un ruolo di grande importanza per la riorganizzazione di un welfare solidale. Servizi sociali integrati e garantiti nella continuit\u00e0, che operino in prossimit\u00e0 con i territori per non lasciare davvero indietro nessuno: queste le esigenze a cui, attraverso le asp, intendiamo dare una risposta fattiva. I caregiver sono una risorsa preziosa nel nostro sistema sociale, come Regione Lazio abbiamo assunto l\u2019impegno di formalizzare nei loro confronti il sostegno e l\u2019attenzione di cui hanno bisogno per rendere in maniera attenta, competente e sicura, il loro immenso servizio per le nostre comunit\u00e0. In particolare, insieme al collega Ciani, abbiamo presentato una proposta di legge per promuovere il ruolo dei caregiver che metter\u00e0 in moto un sistema concreto di aiuti per questa figura&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">.&#8221;Con questo emendamento, nelle more dell\u2019approvazione della legge, si crea sin da ora un sistema integrato con la legge. Formare i caregiver vuol dire offrire loro gli strumenti per prendersi cura dei loro cari con competenza, rispettandone le esigenze e valorizzando da subito il loro percorso, anche in ottica futura. Le asp rappresentano gli enti pi\u00f9 idonei per garantire l\u2019esito della formazione di chi ne ha davvero bisogno. Ringrazio il Presidente Zingaretti e la Giunta regionale per questo risultato.\u201d <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cAbbiamo appena approvato in aula l\u2019emendamento che ho presentato al collegato \u2013 PL 294\/2021 \u2013 per stanziare delle risorse alle<\/p>\n","protected":false},"author":26,"featured_media":34689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[13108,94,93,562,11200],"class_list":["post-61636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-asp","tag-ciociaria","tag-frosinone","tag-regione-lazio","tag-sara-battisti-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fondi per Caregiver alle Asp, approvato l&#039;emendamento della Battisti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fondi per Caregiver alle Asp, approvato l&#039;emendamento della Battisti\" \/>\n<meta property=\"og:description\" content=\"\u201cAbbiamo appena approvato in aula l\u2019emendamento che ho presentato al collegato \u2013 PL 294\/2021 \u2013 per stanziare delle risorse alle\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-04T14:15:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-04T14:15:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/sara-battisti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"627\" \/>\n\t<meta property=\"og:image:height\" content=\"452\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Fondi per Caregiver alle Asp, approvato l&#8217;emendamento della Battisti\",\"datePublished\":\"2021-08-04T14:15:54+00:00\",\"dateModified\":\"2021-08-04T14:15:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/\"},\"wordCount\":331,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/sara-battisti.jpg\",\"keywords\":[\"asp\",\"Ciociaria\",\"Frosinone\",\"regione lazio\",\"Sar\u00e0 battisti\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/\",\"name\":\"Fondi per Caregiver alle Asp, approvato l'emendamento della Battisti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/sara-battisti.jpg\",\"datePublished\":\"2021-08-04T14:15:54+00:00\",\"dateModified\":\"2021-08-04T14:15:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/sara-battisti.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/sara-battisti.jpg\",\"width\":627,\"height\":452,\"caption\":\"La consigliera regionale del Pd Sara Battisti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fondi per Caregiver alle Asp, approvato l&#8217;emendamento della Battisti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fondi per Caregiver alle Asp, approvato l'emendamento della Battisti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/","og_locale":"it_IT","og_type":"article","og_title":"Fondi per Caregiver alle Asp, approvato l'emendamento della Battisti","og_description":"\u201cAbbiamo appena approvato in aula l\u2019emendamento che ho presentato al collegato \u2013 PL 294\/2021 \u2013 per stanziare delle risorse alle","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-08-04T14:15:54+00:00","article_modified_time":"2021-08-04T14:15:58+00:00","og_image":[{"width":627,"height":452,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/sara-battisti.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Fondi per Caregiver alle Asp, approvato l&#8217;emendamento della Battisti","datePublished":"2021-08-04T14:15:54+00:00","dateModified":"2021-08-04T14:15:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/"},"wordCount":331,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/sara-battisti.jpg","keywords":["asp","Ciociaria","Frosinone","regione lazio","Sar\u00e0 battisti"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/","name":"Fondi per Caregiver alle Asp, approvato l'emendamento della Battisti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/sara-battisti.jpg","datePublished":"2021-08-04T14:15:54+00:00","dateModified":"2021-08-04T14:15:58+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/sara-battisti.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/sara-battisti.jpg","width":627,"height":452,"caption":"La consigliera regionale del Pd Sara Battisti"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Fondi per Caregiver alle Asp, approvato l&#8217;emendamento della Battisti"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/fondi-per-caregiver-alle-asp-approvato-lemendamento-della-battisti\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/61636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=61636"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/61636\/revisions"}],"predecessor-version":[{"id":61637,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/61636\/revisions\/61637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/34689"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=61636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=61636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=61636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}