{"id":61628,"date":"2021-08-04T08:21:24","date_gmt":"2021-08-04T06:21:24","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=61628"},"modified":"2021-08-04T08:26:46","modified_gmt":"2021-08-04T06:26:46","slug":"elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/","title":{"rendered":"Elezioni, alle urne il 3 e il 4 ottobre: ecco Comuni al voto Ciociaria"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il ministro dell\u2019Interno,&nbsp;<strong>Luciana Lamorgese,<\/strong>&nbsp;ha adottato il decreto che fissa la data del turno ordinario annuale delle&nbsp;elezioni amministrative (comunali e circoscrizionali) nei comuni delle regioni a statuto ordinario. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le consultazioni elettorali si svolgeranno nei giorni di domenica 3 ottobre e di luned\u00ec 4 ottobre 2021, con eventuale turno di ballottaggio per l\u2019elezione diretta dei sindaci nei giorni di domenica 17 ottobre e di luned\u00ec 18 ottobre 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ventidue i comuni della provincia di\u00a0<strong>Frosinone\u00a0<\/strong>:\u00a0Alatri, Sora, Acquafondata, Alvito, Casalattico, Castro dei Volsci, Castrocielo, Collepardo, Esperia, Fumone, Monte San Giovanni Campano, Pastena, Roccasecca, Sgurgola, Supino, Terelle, Torre Cajetani, Torrice, Trivigliano, Vallecorsa, Vicalvi e Viticuso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il ministro dell\u2019Interno,&nbsp;Luciana Lamorgese,&nbsp;ha adottato il decreto che fissa la data del turno ordinario annuale delle&nbsp;elezioni amministrative (comunali e circoscrizionali)<\/p>\n","protected":false},"author":26,"featured_media":11947,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[94,80,581,93],"class_list":["post-61628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-ciociaria","tag-elezioni","tag-elezioni-comunali","tag-frosinone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Elezioni, alle urne il 3 e il 4 ottobre: ecco Comuni al voto Ciociaria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elezioni, alle urne il 3 e il 4 ottobre: ecco Comuni al voto Ciociaria\" \/>\n<meta property=\"og:description\" content=\"Il ministro dell\u2019Interno,&nbsp;Luciana Lamorgese,&nbsp;ha adottato il decreto che fissa la data del turno ordinario annuale delle&nbsp;elezioni amministrative (comunali e circoscrizionali)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-04T06:21:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-04T06:26:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/elezioni-comunali-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"654\" \/>\n\t<meta property=\"og:image:height\" content=\"368\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Elezioni, alle urne il 3 e il 4 ottobre: ecco Comuni al voto Ciociaria\",\"datePublished\":\"2021-08-04T06:21:24+00:00\",\"dateModified\":\"2021-08-04T06:26:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/\"},\"wordCount\":117,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/elezioni-comunali-1.jpg\",\"keywords\":[\"Ciociaria\",\"Elezioni\",\"elezioni comunali\",\"Frosinone\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/\",\"name\":\"Elezioni, alle urne il 3 e il 4 ottobre: ecco Comuni al voto Ciociaria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/elezioni-comunali-1.jpg\",\"datePublished\":\"2021-08-04T06:21:24+00:00\",\"dateModified\":\"2021-08-04T06:26:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/elezioni-comunali-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/elezioni-comunali-1.jpg\",\"width\":654,\"height\":368,\"caption\":\"Urna elezioni comunali\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elezioni, alle urne il 3 e il 4 ottobre: ecco Comuni al voto Ciociaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/04\\\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Elezioni, alle urne il 3 e il 4 ottobre: ecco Comuni al voto Ciociaria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/","og_locale":"it_IT","og_type":"article","og_title":"Elezioni, alle urne il 3 e il 4 ottobre: ecco Comuni al voto Ciociaria","og_description":"Il ministro dell\u2019Interno,&nbsp;Luciana Lamorgese,&nbsp;ha adottato il decreto che fissa la data del turno ordinario annuale delle&nbsp;elezioni amministrative (comunali e circoscrizionali)","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-08-04T06:21:24+00:00","article_modified_time":"2021-08-04T06:26:46+00:00","og_image":[{"width":654,"height":368,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/elezioni-comunali-1.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Elezioni, alle urne il 3 e il 4 ottobre: ecco Comuni al voto Ciociaria","datePublished":"2021-08-04T06:21:24+00:00","dateModified":"2021-08-04T06:26:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/"},"wordCount":117,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/elezioni-comunali-1.jpg","keywords":["Ciociaria","Elezioni","elezioni comunali","Frosinone"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/","name":"Elezioni, alle urne il 3 e il 4 ottobre: ecco Comuni al voto Ciociaria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/elezioni-comunali-1.jpg","datePublished":"2021-08-04T06:21:24+00:00","dateModified":"2021-08-04T06:26:46+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/elezioni-comunali-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/elezioni-comunali-1.jpg","width":654,"height":368,"caption":"Urna elezioni comunali"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Elezioni, alle urne il 3 e il 4 ottobre: ecco Comuni al voto Ciociaria"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/04\/elezioni-alle-urne-il-3-e-il-4-ottobre-ecco-comuni-al-voto-ciociaria\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/61628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=61628"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/61628\/revisions"}],"predecessor-version":[{"id":61631,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/61628\/revisions\/61631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/11947"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=61628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=61628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=61628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}