{"id":61496,"date":"2021-07-30T16:02:59","date_gmt":"2021-07-30T14:02:59","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=61496"},"modified":"2021-07-30T16:03:01","modified_gmt":"2021-07-30T14:03:01","slug":"ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/","title":{"rendered":"Ceccano, centinaia  di pesci morti nel fiume Sacco, l&#8217;ira di Del Brocco"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Le immagini che arrivano e rimbalzano sui social nelle ultime ore sono un colpo al cuore di ogni Ceccanese,<\/strong> di ogni abitante della Valle del Sacco, di chi vuole sperare in futuro migliore&#8221;.\u00a0 <strong>Cos\u00ec Riccardo Del Brocco, assessore all\u2019ambiente del Comune di Ceccano, in merito alla moria di pesci nel fiume Sacco.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"376\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/Riccardo-Del-Brocco-670x376-1.jpg\" alt=\"\" class=\"wp-image-39448\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/Riccardo-Del-Brocco-670x376-1.jpg 670w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/Riccardo-Del-Brocco-670x376-1-300x168.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><br>&#8220;<strong>La giornata dell\u2019altro ieri, con temperature record, ha sicuramente fatto la sua parte. Vi dico altrettanto sicuramente che non \u00e8 il fenomeno pi\u00f9 drammatico di morie di pesci che abbiamo visto negli anni,<\/strong> specie quando a morire erano animali come pecore o mucche.\u00a0 C\u2019\u00e8 il sospetto di qualcosa di anomalo che l\u2019autorit\u00e0 investigativa sta valutando, ma sicuramente c\u2019\u00e8 una lentezza ed una latitanza delle istituzioni sovraccomunali sul tema \u201cValle del Sacco\u201d vergognoso.\u00a0 Anni di scartoffie senza soluzione, un fiume di denaro che non ha sortito il bench\u00e9 minimo effetto, non ha bonificato nulla, non ha portato nessuno dietro le sbarre&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0<br>&#8220;Al Governo, alla Regione, abbiamo eletti di questo territorio: l\u2019onorevole Ilaria Fontana \u00e8 ciociara ed \u00e8 sottosegretario alla transizione ecologica: spero davvero faccia qualcosa. Buschini e Battisti? Non pervenuti.\u00a0 <strong>Chieder\u00f2 se sar\u00e0 necessario l\u2019intervento del Senatore Ruspandini, per un\u2019interrogazione parlamentare. L\u2019ennesima che dai banchi d\u2019opposizione urla ad un\u2019aula troppo spesso sorda al grido della nostra terra&#8221;.\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>&#8220;Di una cosa devono essere consapevoli e certi i miei concittadini: stavolta non si faranno sconti, a nessuno. Dal Consorizo industriale, al gestore degli impianti, fino a questi bastardi che inquinano senza piet\u00e0.\u00a0 Abbiamo attivato tutte le procedure, avvisando tutte le autorit\u00e0 preposte a tutti i livelli. Ora resteremo in attesa che l\u2019autorit\u00e0 investigativa e giudiziaria arrivi ad una conclusione, accertando le cause di questa nuova ondata maleodorante con annessa moria di pesci&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>&#8220;Anche sul tema di prevenzione, lotta ed investigazione il nuovo corso dell\u2019assessorato all\u2019ambiente non rester\u00e0 fermo. Il grande lavoro svolto a fianco dei cittadini continuer\u00e0 senza sosta.\u00a0Gi\u00e0 da questo inverno attiveremo, con risorse comunali per quel che possiamo, un\u2019operazione di sorveglianza e controllo lungo il corso del fiume. Droni e termo scanner. Vi stiamo addosso, vi staneremo e per voi sar\u00e0 un brutto giorno.\u00a0 L\u2019ambiente \u00e8 al primo posto. Rivolgo un abbraccio a tutti i miei concittadini, affinch\u00e9 si stringano con noi in questa lotta, che portiamo avanti da anni e che spero avr\u00e0 una fine degna&#8221;.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/pesci.jpg\" alt=\"\" class=\"wp-image-61498\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/pesci.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/pesci-225x300.jpg 225w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Le immagini che arrivano e rimbalzano sui social nelle ultime ore sono un colpo al cuore di ogni Ceccanese, di<\/p>\n","protected":false},"author":26,"featured_media":61497,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[524,988,13562,4964],"class_list":["post-61496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","tag-ceccano","tag-fiume-sacco","tag-pesci-morti","tag-riccardo-del-brocco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ceccano, centinaia di pesci morti nel fiume Sacco, l&#039;ira di Del Brocco - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ceccano, centinaia di pesci morti nel fiume Sacco, l&#039;ira di Del Brocco\" \/>\n<meta property=\"og:description\" content=\"Le immagini che arrivano e rimbalzano sui social nelle ultime ore sono un colpo al cuore di ogni Ceccanese, di\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-30T14:02:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-30T14:03:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/pesci-morti-sacco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"759\" \/>\n\t<meta property=\"og:image:height\" content=\"539\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Ceccano, centinaia di pesci morti nel fiume Sacco, l&#8217;ira di Del Brocco\",\"datePublished\":\"2021-07-30T14:02:59+00:00\",\"dateModified\":\"2021-07-30T14:03:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/\"},\"wordCount\":404,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/pesci-morti-sacco.jpg\",\"keywords\":[\"ceccano\",\"Fiume Sacco\",\"pesci morti\",\"Riccardo del Brocco\"],\"articleSection\":[\"*SLIDE*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/\",\"name\":\"Ceccano, centinaia di pesci morti nel fiume Sacco, l'ira di Del Brocco - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/pesci-morti-sacco.jpg\",\"datePublished\":\"2021-07-30T14:02:59+00:00\",\"dateModified\":\"2021-07-30T14:03:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/pesci-morti-sacco.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/pesci-morti-sacco.jpg\",\"width\":759,\"height\":539},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ceccano, centinaia di pesci morti nel fiume Sacco, l&#8217;ira di Del Brocco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/30\\\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ceccano, centinaia di pesci morti nel fiume Sacco, l'ira di Del Brocco - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/","og_locale":"it_IT","og_type":"article","og_title":"Ceccano, centinaia di pesci morti nel fiume Sacco, l'ira di Del Brocco","og_description":"Le immagini che arrivano e rimbalzano sui social nelle ultime ore sono un colpo al cuore di ogni Ceccanese, di","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-07-30T14:02:59+00:00","article_modified_time":"2021-07-30T14:03:01+00:00","og_image":[{"width":759,"height":539,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/pesci-morti-sacco.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Ceccano, centinaia di pesci morti nel fiume Sacco, l&#8217;ira di Del Brocco","datePublished":"2021-07-30T14:02:59+00:00","dateModified":"2021-07-30T14:03:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/"},"wordCount":404,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/pesci-morti-sacco.jpg","keywords":["ceccano","Fiume Sacco","pesci morti","Riccardo del Brocco"],"articleSection":["*SLIDE*"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/","name":"Ceccano, centinaia di pesci morti nel fiume Sacco, l'ira di Del Brocco - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/pesci-morti-sacco.jpg","datePublished":"2021-07-30T14:02:59+00:00","dateModified":"2021-07-30T14:03:01+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/pesci-morti-sacco.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/pesci-morti-sacco.jpg","width":759,"height":539},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ceccano, centinaia di pesci morti nel fiume Sacco, l&#8217;ira di Del Brocco"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/30\/ceccano-centinaia-di-pesci-morti-nel-fiume-sacco-lira-di-del-brocco\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/61496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=61496"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/61496\/revisions"}],"predecessor-version":[{"id":61499,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/61496\/revisions\/61499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/61497"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=61496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=61496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=61496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}