{"id":60455,"date":"2021-07-05T12:23:30","date_gmt":"2021-07-05T10:23:30","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=60455"},"modified":"2021-07-05T12:27:38","modified_gmt":"2021-07-05T10:27:38","slug":"frosinone-tutto-esaurito-per-il-teatro-tra-le-porte","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/","title":{"rendered":"Frosinone, tutto esaurito per il Teatro tra le porte"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tutto esaurito per il primo appuntamento con il \u201cTeatro tra le porte\u201d, in piazza Vittorio Veneto.<\/strong> La rassegna, organizzata dall\u2019amministrazione Ottaviani in collaborazione con l\u2019Atcl e il contributo della Banca Popolare del Frusinate, ha infatti ospitato, sabato sera, Michele La Ginestra con il suo riuscitissimo spettacolo \u201cM\u2019accompagno da me\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Padrona di casa della serata, il volto dell\u2019estate frusinate per eccellenza: \u00e8 toccato a Mary Segneri, popolare conduttrice Rai, infatti, il compito di introdurre gli ospiti prima dell\u2019ingresso in scena dell\u2019attore romano. Con Mary, sul palco, sono saliti, per un indirizzo di saluto, il sindaco di Frosinone, Nicola Ottaviani, l\u2019assessore al centro storico Rossella Testa e il direttore artistico di ATCL, Alessandro Berdini.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 stata poi la volta del trascinante one-man show di Michele La Ginestra, che ha appassionato ed emozionato il pubblico attraverso momenti di comicit\u00e0, di spensieratezza e anche&nbsp;di riflessione.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"717\" height=\"479\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/teatrotraleporte4.jpg\" alt=\"\" class=\"wp-image-60456\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/teatrotraleporte4.jpg 717w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/teatrotraleporte4-300x200.jpg 300w\" sizes=\"auto, (max-width: 717px) 100vw, 717px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Il Teatro tra le Porte, che riapre i battenti al centro storico di Frosinone &#8211; ha dichiarato il sindaco, Nicola Ottaviani &#8211; rappresenta anche la metafora storica dei nostri tempi. Nella tradizione greca, dopo la tragedia di Sofocle ed Eschilo, prese piede la commedia di Epicarmo e di Aristofane, giungendo a investire il palcoscenico fino al tardo medioevo. E cos\u00ec, oggi, dopo la tragedia della pandemia, la comunit\u00e0 ha bisogno di riavvicinarsi alla cultura e allo spettacolo dal vivo, passando per le rappresentazioni meno impegnative, capaci di suscitare anche qualche sorriso&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il \u201cTeatro tra le porte\u201d prevede un cartellone di alto profilo nazionale, con otto appuntamenti in piazzale Vittorio Veneto, fino al 7 agosto, con inizio alle ore 21.30, nel rispetto delle prescrizioni sanitarie, sempre con ingresso rigorosamente gratuito.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gioved\u00ec 8 luglio \u00e8 in programma \u201cRoma \u2013 io ti racconto e canto\u201d, con Elena Bonelli (voce solista) e Giandomenico Anellino (chitarra). Elena Bonelli, voce di Roma e ambasciatrice della canzone romana nel mondo, da oltre 20 anni \u00e8 impegnata nel&nbsp; difendere e diffondere il grande patrimonio della canzone romana. L\u2019artista torna sulla scena con uno spettacolo completamente nuovo, un viaggio musicale nei 150 anni di storia di \u201cRoma capitale d\u2019Italia\u201d che racconta la societ\u00e0 e la vita di ogni epoca attraverso le canzoni romane pi\u00f9 belle, da \u201cLe Streghe\u201d continuando con i grandi classici come \u201cBarcarolo Romano\u201d, \u201cTanto pe\u2019 cant\u00e0\u201d, \u201cLe Mantellate\u201d, \u201cValzer della toppa\u201d, per arrivare a \u201cMe so \u2018mbriacato\u201d, fino ad Achille Lauro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ingresso libero con prenotazione telefonica obbligatoria, fino ad esaurimento posti, nel rispetto delle norme sanitarie al numero 07751893548 nei seguenti giorni e orari: dal luned\u00ec al venerd\u00ec 9.30 -12.30; sabato 9.30 -12.30 al numero 329 3605704. Il pubblico che avr\u00e0 effettuato la prenotazione sar\u00e0 atteso fino a 15 minuti prima dell&#8217;inizio degli spettacoli, dando la possibilit\u00e0 di ingresso nell&#8217;area agli altri spettatori, in caso di assenza, sempre allo scopo di garantire il distanziamento sociale, che non potr\u00e0 essere inferiore alla misura di un metro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.bpf.it\/\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"500\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/BPF20062019_1700banner300x250.jpg\" alt=\"\" class=\"wp-image-15534\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/BPF20062019_1700banner300x250.jpg 600w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/BPF20062019_1700banner300x250-300x250.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/BPF20062019_1700banner300x250-500x417.jpg 500w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Tutto esaurito per il primo appuntamento con il \u201cTeatro tra le porte\u201d, in piazza Vittorio Veneto. La rassegna, organizzata dall\u2019amministrazione<\/p>\n","protected":false},"author":26,"featured_media":60457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14,1],"tags":[502,3638,4306,5349],"class_list":["post-60455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cultura","category-news","tag-bpf","tag-ciociaria-oggi","tag-rossella-testa","tag-teatro-tra-le-porte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, tutto esaurito per il Teatro tra le porte - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, tutto esaurito per il Teatro tra le porte\" \/>\n<meta property=\"og:description\" content=\"Tutto esaurito per il primo appuntamento con il \u201cTeatro tra le porte\u201d, in piazza Vittorio Veneto. La rassegna, organizzata dall\u2019amministrazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-05T10:23:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-05T10:27:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/teatrotraleporte6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"717\" \/>\n\t<meta property=\"og:image:height\" content=\"404\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Frosinone, tutto esaurito per il Teatro tra le porte\",\"datePublished\":\"2021-07-05T10:23:30+00:00\",\"dateModified\":\"2021-07-05T10:27:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/\"},\"wordCount\":480,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/teatrotraleporte6.jpg\",\"keywords\":[\"bpf\",\"Ciociaria oggi\",\"Rossella Testa\",\"teatro tra le porte\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cultura e Spettacolo\",\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/\",\"name\":\"Frosinone, tutto esaurito per il Teatro tra le porte - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/teatrotraleporte6.jpg\",\"datePublished\":\"2021-07-05T10:23:30+00:00\",\"dateModified\":\"2021-07-05T10:27:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/teatrotraleporte6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/teatrotraleporte6.jpg\",\"width\":717,\"height\":404},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, tutto esaurito per il Teatro tra le porte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/05\\\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, tutto esaurito per il Teatro tra le porte - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, tutto esaurito per il Teatro tra le porte","og_description":"Tutto esaurito per il primo appuntamento con il \u201cTeatro tra le porte\u201d, in piazza Vittorio Veneto. La rassegna, organizzata dall\u2019amministrazione","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-07-05T10:23:30+00:00","article_modified_time":"2021-07-05T10:27:38+00:00","og_image":[{"width":717,"height":404,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/teatrotraleporte6.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Frosinone, tutto esaurito per il Teatro tra le porte","datePublished":"2021-07-05T10:23:30+00:00","dateModified":"2021-07-05T10:27:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/"},"wordCount":480,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/teatrotraleporte6.jpg","keywords":["bpf","Ciociaria oggi","Rossella Testa","teatro tra le porte"],"articleSection":["*PRIMO PIANO*","Cultura e Spettacolo","News"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/","name":"Frosinone, tutto esaurito per il Teatro tra le porte - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/teatrotraleporte6.jpg","datePublished":"2021-07-05T10:23:30+00:00","dateModified":"2021-07-05T10:27:38+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/teatrotraleporte6.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/07\/teatrotraleporte6.jpg","width":717,"height":404},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, tutto esaurito per il Teatro tra le porte"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/05\/frosinone-tutto-esaurito-per-il-teatro-tra-le-porte\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/60455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=60455"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/60455\/revisions"}],"predecessor-version":[{"id":60460,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/60455\/revisions\/60460"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/60457"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=60455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=60455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=60455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}