{"id":60427,"date":"2021-07-04T11:57:06","date_gmt":"2021-07-04T09:57:06","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=60427"},"modified":"2021-07-05T11:45:18","modified_gmt":"2021-07-05T09:45:18","slug":"acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/","title":{"rendered":"Acea Ato 5 parla sempre pi\u00f9 romano e finisce per dimenticare la Ciociaria"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Di Cesidio Vano <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acea Ato 5 volta le spalle all&#8217;universit\u00e0 di Cassino e strizza l&#8217;occhio all&#8217;Ateneo di Tor Vergata<\/strong>. Il gestore del servizio idrico della provincia di Frosinone prende ormai sempre pi\u00f9 le distanze dalla Ciociaria e assume con decisione un volto &#8216;romano&#8217; tagliando rapporti e collaborazioni con il territorio che lo ospita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se fino a qualche anno fa, la sinergia ed i protocolli d&#8217;intesa con l&#8217;ateneo della Citt\u00e0 Martire erano prolifici e numerosi, da fine 2019, con l&#8217;avvento della nuovo management aziendale fortemente voluto dal responsabile dell&#8217;Area Industriale Idrico di Acea Spa nonch\u00e9 presidente di Areti (la societ\u00e0 del gruppo acea che si occupa di distribuzione dell\u2019energia elettrica) Giovanni Papaleo, il gestore idrico dell&#8217;Ato 5 guarda sempre pi\u00f9 alla Capitale estraneandosi dalla realt\u00e0 del territorio per cui lavora e che lo ospita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ultimo segnale in tal senso arriva dal recente bando per uno stage curricolare che Acea Ato 5 ha lanciato alla ricerca di un laureando ingegnere, esperto in telegestione e telecontrollo di reti idriche. L&#8217;avviso \u00e8 comparso solo sul sito della II Universit\u00e0 di Roma Tor Vergata. Sembrano essere cos\u00ec definitivamente tramontati i buoni rapporti con i dipartimenti d&#8217;ingegneria dell&#8217;Universit\u00e0 di Cassino e del Lazio Meridionale, che fino a qualche tempo erano irrobustiti da consulenze, studi e collaborazioni tra Acea Ato 5 e Uniclam. Del resto, Tor Vergata \u00e8 l&#8217;Ateneo che sta strettamente collaborando con Areti (la societ\u00e0 guidata da Papaleo) proprio per implementare sistemi di controllo operativo e tecnico\/qualitativi delle reti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E pensare che fino a pochi mesi fa, da Acea Ato 5 si facevano forti \u2013 basta rileggere le dichiarazioni pubbliche di qualche anno fa \u2013 del fatto che i laureati assunti venivano per la maggior parte proprio dall&#8217;Ateneo di Cassino. Altri tempi, altri uomini al comando. Oggi, il vertice aziendale di Acea Ato 5 e le prime linee di gestione sono tutti romani, lontani dal territorio e poco in sintonia con i bisogni locali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un prima sfaldatura, infatti, si \u00e8 subito registrata nei rapporti con i sindaci e le pubbliche amministrazioni, tanto che tutte le linee di dialogo aperte negli scorsi anni sono saltate, a partire dal tavolo di conciliazione che a novembre 2019 era pronto a chiudere, con una transazione \u201ctombale\u201d, tutti i contenziosi in atto tra Ato 5, Comuni e gestore: un&#8217;operazione che portava pace su conflitti e rivendicazioni che valgono quasi 100 milioni di euro, ora ancora in ballo. Sono saltate le relazioni con i territori e le amministrazioni locali che spesso faticano a rintracciare i referenti Acea per le emergenze giornaliere.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I rapporti con i primi cittadini si sono tanto incrinati che, a marzo scorso, l&#8217;Ente d&#8217;ambito prima e la Conferenza dei sindaci poi, poco soddisfatti della qualit\u00e0 del servizio, hanno bocciato le richieste tariffarie di Acea, non riconoscendo al gestore diversi milioni di euro di costi dichiarati, tanto che dopo 3 anni di pace e concordia, Acea Ato 5 \u00e8 dovuta tornare sulle barricate a far causa a sindaci e Autorit\u00e0 d&#8217;ambito trascinando ben 86 comuni davanti la Tribunale amministrativo pretendendo aumenti di tariffa dell&#8217;8% per ognuno dei prossimi anni. E pensare che nel 2018, il piano economico e finanziario era stato approvato in pieno accordo e senza alcuna polemica o censura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non sembra andare meglio nei rapporti con gli altri attori locali interessati al servizio idrico a partire da determinate categorie produttive e commerciali che erano in attesa di una revisione delle tariffe a loro applicate come in passato si \u00e8 fatto per l&#8217;area industriale.<br>Invece per albergatori e commercianti, in alcuni casi, c&#8217;\u00e8 stata persino la beffa con l&#8217;invio di bollette in stima (!) per il 2020 di migliaia di euro, bench\u00e9 come \u00e8 notorio a tutti \u2013 ma forse non ad Acea \u2013 in quell&#8217;anno tutti sono rimasti chiusi causa lockdown. Il caso \u00e8 stato segnalato anche all&#8217;Otuc (l&#8217;organismo di tutela di utenti e consumatori guidato dall&#8217;avvocato Angelo Terrinoni) che ha avviato verifiche e richieste di correzione fattura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infine, come ulteriore sintomo dell&#8217;estraneazione di Acea Ato 5 dal territorio che la ospita, c&#8217;\u00e8 da registrare la saltata sponsorizzazione del Frosinone Calcio. Ormai si guarda solo a Roma e agli affari  romani. Pi\u00f9 truppa d&#8217;occupazione, che risorsa del territorio.<br><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Di Cesidio Vano Acea Ato 5 volta le spalle all&#8217;universit\u00e0 di Cassino e strizza l&#8217;occhio all&#8217;Ateneo di Tor Vergata. Il<\/p>\n","protected":false},"author":26,"featured_media":45293,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-60427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Acea Ato 5 parla sempre pi\u00f9 romano e finisce per dimenticare la Ciociaria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acea Ato 5 parla sempre pi\u00f9 romano e finisce per dimenticare la Ciociaria\" \/>\n<meta property=\"og:description\" content=\"Di Cesidio Vano Acea Ato 5 volta le spalle all&#8217;universit\u00e0 di Cassino e strizza l&#8217;occhio all&#8217;Ateneo di Tor Vergata. Il\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-04T09:57:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-05T09:45:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/acea-nuova.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"834\" \/>\n\t<meta property=\"og:image:height\" content=\"437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Acea Ato 5 parla sempre pi\u00f9 romano e finisce per dimenticare la Ciociaria\",\"datePublished\":\"2021-07-04T09:57:06+00:00\",\"dateModified\":\"2021-07-05T09:45:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/\"},\"wordCount\":702,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/acea-nuova.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/\",\"name\":\"Acea Ato 5 parla sempre pi\u00f9 romano e finisce per dimenticare la Ciociaria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/acea-nuova.jpg\",\"datePublished\":\"2021-07-04T09:57:06+00:00\",\"dateModified\":\"2021-07-05T09:45:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/acea-nuova.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/acea-nuova.jpg\",\"width\":834,\"height\":437},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acea Ato 5 parla sempre pi\u00f9 romano e finisce per dimenticare la Ciociaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/07\\\/04\\\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Acea Ato 5 parla sempre pi\u00f9 romano e finisce per dimenticare la Ciociaria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/","og_locale":"it_IT","og_type":"article","og_title":"Acea Ato 5 parla sempre pi\u00f9 romano e finisce per dimenticare la Ciociaria","og_description":"Di Cesidio Vano Acea Ato 5 volta le spalle all&#8217;universit\u00e0 di Cassino e strizza l&#8217;occhio all&#8217;Ateneo di Tor Vergata. Il","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-07-04T09:57:06+00:00","article_modified_time":"2021-07-05T09:45:18+00:00","og_image":[{"width":834,"height":437,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/acea-nuova.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Acea Ato 5 parla sempre pi\u00f9 romano e finisce per dimenticare la Ciociaria","datePublished":"2021-07-04T09:57:06+00:00","dateModified":"2021-07-05T09:45:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/"},"wordCount":702,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/acea-nuova.jpg","articleSection":["News"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/","name":"Acea Ato 5 parla sempre pi\u00f9 romano e finisce per dimenticare la Ciociaria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/acea-nuova.jpg","datePublished":"2021-07-04T09:57:06+00:00","dateModified":"2021-07-05T09:45:18+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/acea-nuova.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/acea-nuova.jpg","width":834,"height":437},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Acea Ato 5 parla sempre pi\u00f9 romano e finisce per dimenticare la Ciociaria"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/07\/04\/acea-ato-5-parla-sempre-piu-romano-e-finisce-per-dimenticare-la-ciociaria\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/60427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=60427"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/60427\/revisions"}],"predecessor-version":[{"id":60447,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/60427\/revisions\/60447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/45293"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=60427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=60427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=60427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}