{"id":59498,"date":"2021-06-16T10:30:34","date_gmt":"2021-06-16T08:30:34","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=59498"},"modified":"2021-06-16T15:04:01","modified_gmt":"2021-06-16T13:04:01","slug":"elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/","title":{"rendered":"Elezioni a Sora: Cinquestelle, Pd e #Sipu\u00f2fare aprono i tavoli di lavoro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Come gi\u00e0 annunciato durante la scorsa settimana, la coalizione costituita dal <strong>M5S Sora \u2013 PD Sora e Gruppo #SiPu\u00f2Fare<\/strong>, facendo seguito alle riunioni intercorse fra le compagini politiche e civiche di cui si compone, <strong>\u00e8 pronta a partire con i tavoli tematici<\/strong> che saranno propedeutici alla formulazione e stesura del programma elettorale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">I temi che saranno affrontati<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Dopo un confronto costruttivo e funzionale all\u2019individuazione delle tematiche che saranno oggetto dei tavoli, si \u00e8 deciso di strutturare i medesimi nella seguente maniera: <strong>1) Salute, sanit\u00e0, politiche sociali, scolastiche e formative; 2) Ambiente, opere pubbliche e urbanistica sostenibile; 3) Bilancio, Organizzazione comunale e PNRR; 4) Lavoro e attivit\u00e0 produttive, politiche intercomunali e innovazione; 5) Cultura, arte e spettacolo, turismo e sport, politiche giovanili e pari opportunit\u00e0.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La coalizione sottolinea come la formazione di questi tavoli di lavoro sia stata elaborata al fine di garantire, oltre che una copertura integrale dei settori di interesse affini all\u2019attivit\u00e0 amministrativa comunale, anche il mantenimento di una stretta attinenza riguardo le problematiche e le istanze pi\u00f9 volte lamentate e fatte presenti dai cittadini, in maniera da poter presentare alla citt\u00e0 di Sora un programma dettagliato, concreto e adeguato alle necessit\u00e0 pi\u00f9 volte manifestate.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non sar\u00e0 il solito libro dei sogni ma un documento la cui attuazione sar\u00e0 mossa da criteri di pragmaticit\u00e0 amministrativa, che guardi in maniera accorta e scrupolosa alla gestione degli interessi della comunit\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La coalizione, in virt\u00f9 di quanto fatto presente, invita nuovamente tutti i cittadini sorani, le associazioni di categoria, le associazioni locali e chiunque voglia sostenere questo nuovo ed ambizioso progetto politico-amministrativo, a partecipare attivamente ai lavori dei tavoli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La coalizione costituita dal M5S Sora \u2013 PD Sora e Gruppo #SiPu\u00f2Fare apre i tavoli di lavoro<\/p>\n","protected":false},"author":26,"featured_media":48463,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236,28],"tags":[94,8401,80,93,744,1191,161],"class_list":["post-59498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-politica","tag-ciociaria","tag-coalizione","tag-elezioni","tag-frosinone","tag-movimento-cinquestelle","tag-partito-democratico","tag-sora"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Elezioni a Sora: Cinquestelle, Pd e #Sipu\u00f2fare aprono i tavoli di lavoro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elezioni a Sora: Cinquestelle, Pd e #Sipu\u00f2fare aprono i tavoli di lavoro\" \/>\n<meta property=\"og:description\" content=\"La coalizione costituita dal M5S Sora \u2013 PD Sora e Gruppo #SiPu\u00f2Fare apre i tavoli di lavoro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-16T08:30:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-16T13:04:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/comune-sora.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t<meta property=\"og:image:height\" content=\"767\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Elezioni a Sora: Cinquestelle, Pd e #Sipu\u00f2fare aprono i tavoli di lavoro\",\"datePublished\":\"2021-06-16T08:30:34+00:00\",\"dateModified\":\"2021-06-16T13:04:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/\"},\"wordCount\":276,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/comune-sora.jpg\",\"keywords\":[\"Ciociaria\",\"coalizione\",\"Elezioni\",\"Frosinone\",\"movimento cinquestelle\",\"partito democratico\",\"sora\"],\"articleSection\":[\"Attualit\u00e0\",\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/\",\"name\":\"Elezioni a Sora: Cinquestelle, Pd e #Sipu\u00f2fare aprono i tavoli di lavoro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/comune-sora.jpg\",\"datePublished\":\"2021-06-16T08:30:34+00:00\",\"dateModified\":\"2021-06-16T13:04:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/comune-sora.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/comune-sora.jpg\",\"width\":1366,\"height\":767,\"caption\":\"Il palazzo municipale di Sora\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elezioni a Sora: Cinquestelle, Pd e #Sipu\u00f2fare aprono i tavoli di lavoro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/16\\\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Elezioni a Sora: Cinquestelle, Pd e #Sipu\u00f2fare aprono i tavoli di lavoro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/","og_locale":"it_IT","og_type":"article","og_title":"Elezioni a Sora: Cinquestelle, Pd e #Sipu\u00f2fare aprono i tavoli di lavoro","og_description":"La coalizione costituita dal M5S Sora \u2013 PD Sora e Gruppo #SiPu\u00f2Fare apre i tavoli di lavoro","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-06-16T08:30:34+00:00","article_modified_time":"2021-06-16T13:04:01+00:00","og_image":[{"width":1366,"height":767,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/comune-sora.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Elezioni a Sora: Cinquestelle, Pd e #Sipu\u00f2fare aprono i tavoli di lavoro","datePublished":"2021-06-16T08:30:34+00:00","dateModified":"2021-06-16T13:04:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/"},"wordCount":276,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/comune-sora.jpg","keywords":["Ciociaria","coalizione","Elezioni","Frosinone","movimento cinquestelle","partito democratico","sora"],"articleSection":["Attualit\u00e0","Evidenza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/","name":"Elezioni a Sora: Cinquestelle, Pd e #Sipu\u00f2fare aprono i tavoli di lavoro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/comune-sora.jpg","datePublished":"2021-06-16T08:30:34+00:00","dateModified":"2021-06-16T13:04:01+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/comune-sora.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/comune-sora.jpg","width":1366,"height":767,"caption":"Il palazzo municipale di Sora"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Elezioni a Sora: Cinquestelle, Pd e #Sipu\u00f2fare aprono i tavoli di lavoro"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/16\/elezioni-a-sora-cinquestelle-pd-e-sipuofare-aprono-i-tavoli-di-lavoro\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/59498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=59498"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/59498\/revisions"}],"predecessor-version":[{"id":59499,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/59498\/revisions\/59499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/48463"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=59498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=59498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=59498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}