{"id":59473,"date":"2021-06-15T16:21:06","date_gmt":"2021-06-15T14:21:06","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=59473"},"modified":"2021-06-15T18:36:47","modified_gmt":"2021-06-15T16:36:47","slug":"frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/","title":{"rendered":"Frosinone, stadio del nuoto: Pizzutelli invita il Comune a scongiurare la chiusura"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;<strong>Il 31 luglio scade la Convenzione tra la FIN Federazione Italiana Nuoto ed il Comune di Frosinone <\/strong>per la proroga o rinnovo della stessa, che consentirebbe il proseguio dell\u2019attivit\u00e0 federale natatoria (e sport correlati\u2026) presso lo Stadio del Nuoto Citt\u00e0 di Frosinone&#8221;. <strong>Lo evidenzia Angelo Pizzutelli, capogruppo del Pd<\/strong> <strong>al consiglio comunale.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;appello<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Il bellissimo impianto frusinate, tra i primi in Italia avendo ospitato le Nazionali di Pallanuoto ed eventi iridati ed inaugurato nel 2009 dalla Giunta Marini e la stessa FIN presieduta dal Senatore Paolo Barelli in occasione dei Mondiali di Nuoto di Roma, rischierebbe una clamorosa chiusura nel caso venisse meno tale convenzione. Auspico positivi riscontri da parte del Comune di Frosinone che pare, ad oggi, non abbia dato riscontro alle pec di sollecito inviate dalla Federazione Italiana Nuoto. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Il 31 luglio scade la Convenzione tra la FIN Federazione Italiana Nuoto ed il Comune di Frosinone per la proroga<\/p>\n","protected":false},"author":26,"featured_media":5034,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[1482,94,3507,13322,10691],"class_list":["post-59473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-angelo-pizzutelli","tag-ciociaria","tag-comune-di-frosinone","tag-fin","tag-stadio-del-nuoto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, stadio del nuoto: Pizzutelli invita il Comune a scongiurare la chiusura - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, stadio del nuoto: Pizzutelli invita il Comune a scongiurare la chiusura\" \/>\n<meta property=\"og:description\" content=\"&#8220;Il 31 luglio scade la Convenzione tra la FIN Federazione Italiana Nuoto ed il Comune di Frosinone per la proroga\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-15T14:21:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-15T16:36:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/angelo-pizzutelli-frosinone-e1547732033331.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Frosinone, stadio del nuoto: Pizzutelli invita il Comune a scongiurare la chiusura\",\"datePublished\":\"2021-06-15T14:21:06+00:00\",\"dateModified\":\"2021-06-15T16:36:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/\"},\"wordCount\":143,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/angelo-pizzutelli-frosinone-e1547732033331.jpg\",\"keywords\":[\"angelo pizzutelli\",\"Ciociaria\",\"comune di frosinone\",\"fin\",\"stadio del nuoto\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/\",\"name\":\"Frosinone, stadio del nuoto: Pizzutelli invita il Comune a scongiurare la chiusura - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/angelo-pizzutelli-frosinone-e1547732033331.jpg\",\"datePublished\":\"2021-06-15T14:21:06+00:00\",\"dateModified\":\"2021-06-15T16:36:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/angelo-pizzutelli-frosinone-e1547732033331.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/angelo-pizzutelli-frosinone-e1547732033331.jpg\",\"width\":632,\"height\":467,\"caption\":\"Il consigliere comunale del Pd di Frosinone Angelo Pizzutelli\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, stadio del nuoto: Pizzutelli invita il Comune a scongiurare la chiusura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, stadio del nuoto: Pizzutelli invita il Comune a scongiurare la chiusura - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, stadio del nuoto: Pizzutelli invita il Comune a scongiurare la chiusura","og_description":"&#8220;Il 31 luglio scade la Convenzione tra la FIN Federazione Italiana Nuoto ed il Comune di Frosinone per la proroga","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-06-15T14:21:06+00:00","article_modified_time":"2021-06-15T16:36:47+00:00","og_image":[{"width":632,"height":467,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/angelo-pizzutelli-frosinone-e1547732033331.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Frosinone, stadio del nuoto: Pizzutelli invita il Comune a scongiurare la chiusura","datePublished":"2021-06-15T14:21:06+00:00","dateModified":"2021-06-15T16:36:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/"},"wordCount":143,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/angelo-pizzutelli-frosinone-e1547732033331.jpg","keywords":["angelo pizzutelli","Ciociaria","comune di frosinone","fin","stadio del nuoto"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/","name":"Frosinone, stadio del nuoto: Pizzutelli invita il Comune a scongiurare la chiusura - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/angelo-pizzutelli-frosinone-e1547732033331.jpg","datePublished":"2021-06-15T14:21:06+00:00","dateModified":"2021-06-15T16:36:47+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/angelo-pizzutelli-frosinone-e1547732033331.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/angelo-pizzutelli-frosinone-e1547732033331.jpg","width":632,"height":467,"caption":"Il consigliere comunale del Pd di Frosinone Angelo Pizzutelli"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, stadio del nuoto: Pizzutelli invita il Comune a scongiurare la chiusura"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-stadio-del-nuoto-pizzutelli-invita-il-comune-a-scongiurare-la-chiusura\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/59473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=59473"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/59473\/revisions"}],"predecessor-version":[{"id":59474,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/59473\/revisions\/59474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/5034"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=59473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=59473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=59473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}