{"id":59443,"date":"2021-06-15T12:46:44","date_gmt":"2021-06-15T10:46:44","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=59443"},"modified":"2021-06-15T12:46:46","modified_gmt":"2021-06-15T10:46:46","slug":"frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/","title":{"rendered":"Frosinone: si finge carabiniere e poi fugge rischiando di investire i poliziotti. Denunciata  60enne"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il personale delle Volanti ha denunciato una 60enne per resistenza a pubblico ufficiale e sostituzione di persona. Gli agenti, durante un posto di controllo, <strong>hanno intimato l&#8217;alt ad un&#8217;autovettura condotta da una donna<\/strong>,\u00a0 la quale non ha voluto fornire alcun documento, mostrandosi da subito ostile al controllo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La donna ha millantato di appartenere all&#8217;Arma dei Carabinier<\/strong>i, chiedendo con insistenza ai poliziotti che il controllo fosse sommario e repentino. Dagli accertamenti, <strong>il veicolo \u00e8 risultato privo di copertura assicurativa <\/strong>e gli agenti, viste le tante incongruenze nelle dichiarazioni della donna, le hanno chiesto di seguirli in Questura per effettuare\u00a0controlli pi\u00f9 approfonditi sull&#8217;auto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A quel punto <strong>la conducente ha iniziato a gridar<\/strong>e e, chiudendo velocemente la portiera del veicolo, a gran velocit\u00e0 <strong>ha cercato di fuggire rischiando anche di investire gli operatori che tentavano di fermarla<\/strong>.\u00a0 Gli agenti hanno iniziato l&#8217;inseguimento, terminato presso l&#8217;abitazione della fuggitiva, dove la stessa \u00e8 stata identificata e denunciata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Denunciata una sessantenne per resistenza a pubblico ufficiale e sostituzione di persona<\/p>\n","protected":false},"author":26,"featured_media":59444,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[90,94,245,93,2207,2204,291,3531],"class_list":["post-59443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-carabinieri","tag-ciociaria","tag-denuncia","tag-frosinone","tag-fuga","tag-inseguimento","tag-polizia","tag-volanti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone: si finge carabiniere e poi fugge rischiando di investire i poliziotti. Denunciata 60enne - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone: si finge carabiniere e poi fugge rischiando di investire i poliziotti. Denunciata 60enne\" \/>\n<meta property=\"og:description\" content=\"Denunciata una sessantenne per resistenza a pubblico ufficiale e sostituzione di persona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-15T10:46:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-15T10:46:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/polizia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"758\" \/>\n\t<meta property=\"og:image:height\" content=\"494\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Frosinone: si finge carabiniere e poi fugge rischiando di investire i poliziotti. Denunciata 60enne\",\"datePublished\":\"2021-06-15T10:46:44+00:00\",\"dateModified\":\"2021-06-15T10:46:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/\"},\"wordCount\":171,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/polizia-1.jpg\",\"keywords\":[\"carabinieri\",\"Ciociaria\",\"denuncia\",\"Frosinone\",\"fuga\",\"inseguimento\",\"polizia\",\"volanti\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/\",\"name\":\"Frosinone: si finge carabiniere e poi fugge rischiando di investire i poliziotti. Denunciata 60enne - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/polizia-1.jpg\",\"datePublished\":\"2021-06-15T10:46:44+00:00\",\"dateModified\":\"2021-06-15T10:46:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/polizia-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/polizia-1.jpg\",\"width\":758,\"height\":494,\"caption\":\"polizia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone: si finge carabiniere e poi fugge rischiando di investire i poliziotti. Denunciata 60enne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/15\\\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone: si finge carabiniere e poi fugge rischiando di investire i poliziotti. Denunciata 60enne - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone: si finge carabiniere e poi fugge rischiando di investire i poliziotti. Denunciata 60enne","og_description":"Denunciata una sessantenne per resistenza a pubblico ufficiale e sostituzione di persona","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-06-15T10:46:44+00:00","article_modified_time":"2021-06-15T10:46:46+00:00","og_image":[{"width":758,"height":494,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/polizia-1.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Frosinone: si finge carabiniere e poi fugge rischiando di investire i poliziotti. Denunciata 60enne","datePublished":"2021-06-15T10:46:44+00:00","dateModified":"2021-06-15T10:46:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/"},"wordCount":171,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/polizia-1.jpg","keywords":["carabinieri","Ciociaria","denuncia","Frosinone","fuga","inseguimento","polizia","volanti"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/","name":"Frosinone: si finge carabiniere e poi fugge rischiando di investire i poliziotti. Denunciata 60enne - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/polizia-1.jpg","datePublished":"2021-06-15T10:46:44+00:00","dateModified":"2021-06-15T10:46:46+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/polizia-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/polizia-1.jpg","width":758,"height":494,"caption":"polizia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone: si finge carabiniere e poi fugge rischiando di investire i poliziotti. Denunciata 60enne"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/15\/frosinone-si-finge-carabiniere-e-poi-fugge-rischiando-di-investire-i-poliziotti-denunciata-60enne\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/59443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=59443"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/59443\/revisions"}],"predecessor-version":[{"id":59445,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/59443\/revisions\/59445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/59444"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=59443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=59443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=59443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}