{"id":59114,"date":"2021-06-08T07:57:49","date_gmt":"2021-06-08T05:57:49","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=59114"},"modified":"2021-06-08T08:37:09","modified_gmt":"2021-06-08T06:37:09","slug":"cassino-festival-dei-sentieri-decretato-il-vincitore","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/","title":{"rendered":"Cassino, Festival dei sentieri: decretato il vincitore"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br><strong>Si \u00e8 concluso nei giorni scorsi l\u2019ultimo evento riguardante la prima edizione del Festival dei Sentieri: <\/strong>il contest fotografico per regalare ad uno dei sentieri in concorso una tabella turistica utile per spiegare e far conoscere ancora meglio luoghi incantevoli del nostro territorio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A scegliere \u00e8 stato il web che ha decretato vincitrice il comune di Sant\u2019Elia Fiumerapido per raccontare a turisti e visitatori il \u201cTratturo dei Pellegrini\u201d. A Sant\u2019Ambrogio sul Garigliano il secondo posto con l\u2019originalissimo percorso fluviale.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0009.jpg\" alt=\"\" class=\"wp-image-59115\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0009.jpg 720w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0009-225x300.jpg 225w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>L\u2019Associazione Cassino Citt\u00e0 per la Pace, (<em>Marino Fardelli<\/em> Presidente e <br><em>Nino Rossi<\/em>, Vice Presidente) che ha organizzato la prima edizione, insieme con le tante associazioni del territorio, ha voluto lasciare un segno concreto di questo festival<\/strong> che ha visto un primo momento svolgersi in modalit\u00e0 online a causa della delicata fase pandemica attraversata, grazie alla regia organizzativa della giornalista RaiRadio Live Tiziana Iannarelli. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La giornata del 16 maggio, unica svoltasi in presenza, \u00e8 stata una vera e propria festa a contatto con la natura, a passo lento e concedendosi la possibilit\u00e0 di ammirare quanto abbiamo di bello a km 0 e che spesso, per la vita frenetica di tutti i giorni non notiamo pi\u00f9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"655\" height=\"960\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0012.jpg\" alt=\"\" class=\"wp-image-59119\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0012.jpg 655w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0012-205x300.jpg 205w\" sizes=\"auto, (max-width: 655px) 100vw, 655px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Raccontare il territorio \u00e8 stato il motivo per cui \u00e8 stato chiesto ai comuni di attivarsi nella scelta del sentiero, nel produrre la scheda tecnica, di realizzare una clip video e di organizzare l\u2019escursione. Iniziativa senza precedenti vista la larghissima partecipazione su tutto il territorio a cui \u00e8 stato dedicato il portale www.festivaldeisentieri.it su cui tutto il materiale \u00e8 stato inserito. 14 Comuni coinvolti, diverse Associazioni e Pro Loco locali che hanno animato questa prima edizione del Festival dei Sentieri. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0011.jpg\" alt=\"\" class=\"wp-image-59128\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0011.jpg 960w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0011-300x225.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0011-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Questa l\u2019idea originaria lanciata in sede di conferenza stampa alla presenza delle autorit\u00e0 territoriali e della Consigliera Regionale del Lazio Sara Battisti che ha cos\u00ec commentato <\/strong>\u201cringrazio l\u2019Associazione Cassino Citt\u00e0 per la Pace, e in particolare il presidente, Marino Fardelli, per quanto prodotto in queste settimane per la valorizzazione dei sentieri dei nostri territori. Il turismo green ed esperienziale rappresenta la grande sfida della Ciociaria dei prossimi mesi. Circa un anno fa ho lanciato una call, \u201criparTiAmo \u2013 tourism\u201d, rivolta alle associazioni che credono nelle possibilit\u00e0 di un rilancio del territorio: dobbiamo partire dal basso, dai cittadini, dai volontari, dal mondo della societ\u00e0 civile, in un lavoro sinergico con le istituzioni e le amministrazioni comunali, per costruire una Provincia votata al turismo come volano per la ripartenza. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marino ha accettato la sfida ed \u00e8 sceso in campo con un progetto ambizioso, perfettamente integrato nel mio \u201cProgetto sentieri\u201d con cui sto realizzando, insieme ad Itinarrando, al Cai, al Consorzio industriale e ai Parchi che insistono sulla nostra provincia, 21 sentieri per il turismo outdoor che \u00e8 poi il turismo del futuro prossimo. L\u2019Associazione Cassino Citt\u00e0 per la Pace, con questo Festival, ha valorizzato a pieno il mio progetto, ampliandolo. Credo che questo lavoro sinergico rappresenter\u00e0 il segreto di una nuova stagione per la Ciociaria, che mette al centro un turismo a misura d\u2019uomo e lo declina in possibilit\u00e0 lavorative, economiche, sociali e culturali per il territorio\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"633\" height=\"960\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/1623133875110_0_IMG-20210607-WA0010.jpg\" alt=\"\" class=\"wp-image-59144\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/1623133875110_0_IMG-20210607-WA0010.jpg 633w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/1623133875110_0_IMG-20210607-WA0010-198x300.jpg 198w\" sizes=\"auto, (max-width: 633px) 100vw, 633px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mauro Buschini partecipante alla camminata da Cassino a Montecassino qualche settimana fa proprio nell\u2019iniziativa dell\u2019Associazione Cassino Citt\u00e0 per la Pace ha aggiunto<\/strong> \u201cin maniera fattiva si \u00e8 dimostrato che il nostro territorio pu\u00f2 essere davvero valorizzato attraverso il rapporto con l\u2019ambiente, la natura e la storia. Da queste iniziative riparte una societ\u00e0 post-covid per coniugare turismo, valore economico e sociale di una intera provincia. I complimenti a tutte le Associazioni del territorio che hanno raccolto insieme ai Sindaci l\u2019invito a fare sistema e squadra da parte dell\u2019Associazione Cassino Citt\u00e0 per la Pace\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Nelle prossime settimane si organizzer\u00e0 la consegna della tabella nel comune vincitore a cura del Parco dei Monti Aurunci con il Presidente Marco Delle Cese <\/strong>che ha commentato cos\u00ec i risultati ottenuti di questa prima edizione \u201cun momento nel quale si pone l\u2019accento sulla bellezza e soprattutto sulle bellezze dei nostri territori, l\u2019occasione ci ha evidenziato che abbiamo anche fotografi eccellenti. All\u2019Associazione Cassino Citt\u00e0 per la Pace il merito di aver portato alla luce la ricchezza di un territorio dal punto di vista naturalistico e turistico\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Si guarda gi\u00e0 alla seconda edizione del festival il prossimo anno per continuare il cammino sui sentieri tracciati e scoprirne di altri. Le congratulazioni a tutti i partecipanti per aver aderito all\u2019iniziativa e aver iniziato un percorso di valorizzazione dei luoghi in cui viviamo e una menzione speciale alla nostra amica Cinzia Rizza che ci ha aiutati nella buona riuscita di questo contest che ha avuto il giusto riconoscimento ed apprezzamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Marino Fardelli<\/em> \u2013 Presidente Associazione Cassino Citt\u00e0 per la Pace<br><em>Nino Rossi<\/em> \u2013 Vice Presidente Associazione Cassino Citt\u00e0 per la Pace<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 concluso nei giorni scorsi l\u2019ultimo evento riguardante la prima edizione del Festival dei Sentieri: il contest fotografico per<\/p>\n","protected":false},"author":26,"featured_media":59116,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236,43],"tags":[94,12865,93,1262,1388,1721],"class_list":["post-59114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","category-turismo","tag-ciociaria","tag-festival-dei-sentieri","tag-frosinone","tag-marino-fardelli","tag-mauro-buschini","tag-sara-battisti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cassino, Festival dei sentieri: decretato il vincitore - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cassino, Festival dei sentieri: decretato il vincitore\" \/>\n<meta property=\"og:description\" content=\"Si \u00e8 concluso nei giorni scorsi l\u2019ultimo evento riguardante la prima edizione del Festival dei Sentieri: il contest fotografico per\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-08T05:57:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-08T06:37:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0008.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Cassino, Festival dei sentieri: decretato il vincitore\",\"datePublished\":\"2021-06-08T05:57:49+00:00\",\"dateModified\":\"2021-06-08T06:37:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/\"},\"wordCount\":789,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/0_IMG-20210607-WA0008.jpg\",\"keywords\":[\"Ciociaria\",\"Festival dei sentieri\",\"Frosinone\",\"marino fardelli\",\"mauro buschini\",\"Sara Battisti\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\",\"Turismo\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/\",\"name\":\"Cassino, Festival dei sentieri: decretato il vincitore - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/0_IMG-20210607-WA0008.jpg\",\"datePublished\":\"2021-06-08T05:57:49+00:00\",\"dateModified\":\"2021-06-08T06:37:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/0_IMG-20210607-WA0008.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/0_IMG-20210607-WA0008.jpg\",\"width\":480,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cassino, Festival dei sentieri: decretato il vincitore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/06\\\/08\\\/cassino-festival-dei-sentieri-decretato-il-vincitore\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cassino, Festival dei sentieri: decretato il vincitore - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/","og_locale":"it_IT","og_type":"article","og_title":"Cassino, Festival dei sentieri: decretato il vincitore","og_description":"Si \u00e8 concluso nei giorni scorsi l\u2019ultimo evento riguardante la prima edizione del Festival dei Sentieri: il contest fotografico per","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-06-08T05:57:49+00:00","article_modified_time":"2021-06-08T06:37:09+00:00","og_image":[{"width":480,"height":360,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0008.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Cassino, Festival dei sentieri: decretato il vincitore","datePublished":"2021-06-08T05:57:49+00:00","dateModified":"2021-06-08T06:37:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/"},"wordCount":789,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0008.jpg","keywords":["Ciociaria","Festival dei sentieri","Frosinone","marino fardelli","mauro buschini","Sara Battisti"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0","Turismo"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/","name":"Cassino, Festival dei sentieri: decretato il vincitore - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0008.jpg","datePublished":"2021-06-08T05:57:49+00:00","dateModified":"2021-06-08T06:37:09+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0008.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/06\/0_IMG-20210607-WA0008.jpg","width":480,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Cassino, Festival dei sentieri: decretato il vincitore"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/06\/08\/cassino-festival-dei-sentieri-decretato-il-vincitore\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/59114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=59114"}],"version-history":[{"count":7,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/59114\/revisions"}],"predecessor-version":[{"id":59146,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/59114\/revisions\/59146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/59116"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=59114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=59114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=59114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}