{"id":588,"date":"2018-10-30T21:11:20","date_gmt":"2018-10-30T20:11:20","guid":{"rendered":"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=588"},"modified":"2018-11-01T16:54:07","modified_gmt":"2018-11-01T15:54:07","slug":"ferentino-maltrattamento-di-animali-quattro-denunce","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/","title":{"rendered":"Ferentino &#8211; Maltrattamento di animali, quattro denunce"},"content":{"rendered":"<p>Nel pomeriggio di ieri i carabinieri di Ferentino hanno denunciato quattro persone del frusinate, residenti nella cittadina ciociara, responsabili di <strong>maltrattamento di animali<\/strong> e gravi violazioni delle norme sulla protezione della fauna selvatica. I carabinieri hanno accertato l\u2019esistenza, nelle pertinenze dell\u2019abitazione del quartetto,\u00a0 di un<strong> allevamento abusivo<\/strong> nel quale erano presenti <strong>35 cani<\/strong> di varie razze pregiate (pechinese, chiwawa e bulldog francese), nonch\u00e9 circa 100 esemplari di <strong>fauna selvatica protetta<\/strong> (quaglie e simili).<\/p>\n<h2>Pessime le condizioni in cui erano tenuti<\/h2>\n<p>Gli animali erano tutti tenuti in condizioni igienico-sanitarie pessime, aggravate dalla presenza di carcasse di bestie morte. L\u2019intera area \u00e8 stata sottoposta a sequestro, mentre per gli animali sono state attivate le strutture competenti allo scopo di reperire un&#8217;idonea sistemazione.<\/p>\n<p>Gli accertamenti hanno consentito di raccogliere elementi di colpevolezza a carico delle quattro persone in merito alla vendita illegale di numerosi cuccioli al<strong> prezzo di euro 1.400<\/strong> per ogni esemplare e della fauna al prezzo di euro 10,00 per ogni animale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel pomeriggio di ieri i carabinieri di Ferentino hanno denunciato quattro persone del frusinate, residenti nella cittadina ciociara, responsabili di<\/p>\n","protected":false},"author":3,"featured_media":590,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[88,90,94,91,92,93,89],"class_list":["post-588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","tag-animali","tag-carabinieri","tag-ciociaria","tag-denunce","tag-ferentino","tag-frosinone","tag-matrattameto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ferentino - Maltrattamento di animali, quattro denunce - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"I carabinieri di Ferentino hanno scoperto un allevamento abusivo con 35 cani e denunciato 4 persone per violazioni delle norme sulla protezione della fauna.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferentino - Maltrattamento di animali, quattro denunce\" \/>\n<meta property=\"og:description\" content=\"I carabinieri di Ferentino hanno scoperto un allevamento abusivo con 35 cani e denunciato 4 persone per violazioni delle norme sulla protezione della fauna.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/TuNews24\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-30T20:11:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-01T15:54:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/10\/carabinieri-animali.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Trento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Trento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/\"},\"author\":{\"name\":\"Gianluca Trento\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\"},\"headline\":\"Ferentino &#8211; Maltrattamento di animali, quattro denunce\",\"datePublished\":\"2018-10-30T20:11:20+00:00\",\"dateModified\":\"2018-11-01T15:54:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/\"},\"wordCount\":167,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/carabinieri-animali.jpg\",\"keywords\":[\"Animali\",\"carabinieri\",\"Ciociaria\",\"denunce\",\"ferentino\",\"Frosinone\",\"matrattameto\"],\"articleSection\":[\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/\",\"name\":\"Ferentino - Maltrattamento di animali, quattro denunce - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/carabinieri-animali.jpg\",\"datePublished\":\"2018-10-30T20:11:20+00:00\",\"dateModified\":\"2018-11-01T15:54:07+00:00\",\"description\":\"I carabinieri di Ferentino hanno scoperto un allevamento abusivo con 35 cani e denunciato 4 persone per violazioni delle norme sulla protezione della fauna.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/carabinieri-animali.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/carabinieri-animali.jpg\",\"width\":620,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferentino &#8211; Maltrattamento di animali, quattro denunce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\",\"name\":\"Gianluca Trento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"caption\":\"Gianluca Trento\"},\"description\":\"Giornalista dei quotidiani online \\\"LaProvinciaQuotidiano.it\\\" e \\\"TuNews24.it\\\" e del settimanale cartaceo \\\"Tu News\\\". In passato \u00e8 stato anche Direttore Editoriale de \\\"La Provincia\\\", Direttore Responsabile del quotidiano \\\"Ciociaria Oggi\\\", Condirettore de \\\"Il quotidiano della Ciociaria\\\", giornalista di \\\"Paese Sera\\\", del settimanale \\\"L\u2019Inchiesta\\\" e del quotidiano online \\\"Il Corriere della Provincia\\\".\",\"sameAs\":[\"https:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/TuNews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/gianluca\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/ferentino-maltrattamento-di-animali-quattro-denunce\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ferentino - Maltrattamento di animali, quattro denunce - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"I carabinieri di Ferentino hanno scoperto un allevamento abusivo con 35 cani e denunciato 4 persone per violazioni delle norme sulla protezione della fauna.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/","og_locale":"it_IT","og_type":"article","og_title":"Ferentino - Maltrattamento di animali, quattro denunce","og_description":"I carabinieri di Ferentino hanno scoperto un allevamento abusivo con 35 cani e denunciato 4 persone per violazioni delle norme sulla protezione della fauna.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/TuNews24","article_published_time":"2018-10-30T20:11:20+00:00","article_modified_time":"2018-11-01T15:54:07+00:00","og_image":[{"width":620,"height":420,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/10\/carabinieri-animali.jpg","type":"image\/jpeg"}],"author":"Gianluca Trento","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Gianluca Trento","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/"},"author":{"name":"Gianluca Trento","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd"},"headline":"Ferentino &#8211; Maltrattamento di animali, quattro denunce","datePublished":"2018-10-30T20:11:20+00:00","dateModified":"2018-11-01T15:54:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/"},"wordCount":167,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/10\/carabinieri-animali.jpg","keywords":["Animali","carabinieri","Ciociaria","denunce","ferentino","Frosinone","matrattameto"],"articleSection":["Cronaca"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/","name":"Ferentino - Maltrattamento di animali, quattro denunce - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/10\/carabinieri-animali.jpg","datePublished":"2018-10-30T20:11:20+00:00","dateModified":"2018-11-01T15:54:07+00:00","description":"I carabinieri di Ferentino hanno scoperto un allevamento abusivo con 35 cani e denunciato 4 persone per violazioni delle norme sulla protezione della fauna.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/10\/carabinieri-animali.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/10\/carabinieri-animali.jpg","width":620,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ferentino &#8211; Maltrattamento di animali, quattro denunce"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd","name":"Gianluca Trento","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","caption":"Gianluca Trento"},"description":"Giornalista dei quotidiani online \"LaProvinciaQuotidiano.it\" e \"TuNews24.it\" e del settimanale cartaceo \"Tu News\". In passato \u00e8 stato anche Direttore Editoriale de \"La Provincia\", Direttore Responsabile del quotidiano \"Ciociaria Oggi\", Condirettore de \"Il quotidiano della Ciociaria\", giornalista di \"Paese Sera\", del settimanale \"L\u2019Inchiesta\" e del quotidiano online \"Il Corriere della Provincia\".","sameAs":["https:\/\/www.tunews24.it","http:\/\/www.facebook.com\/TuNews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/gianluca\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/ferentino-maltrattamento-di-animali-quattro-denunce\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=588"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/588\/revisions"}],"predecessor-version":[{"id":592,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/588\/revisions\/592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/590"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}