{"id":58424,"date":"2021-05-22T18:41:21","date_gmt":"2021-05-22T16:41:21","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=58424"},"modified":"2021-05-22T18:46:34","modified_gmt":"2021-05-22T16:46:34","slug":"fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/","title":{"rendered":"Fiuggi, Battisti con D&#8217;Amato e il Dg Asl al centro vaccinale: grande soddisfazione da parte dei  cittadini"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> \u201cOggi a Fiuggi, con l&#8217;Assessore D\u2019Amato e Direttore Generale ASL di Frosinone al centro Vaccinale, abbiamo registrato grande soddisfazione da parte dei cittadini\u201d. <strong>Cos\u00ec la Presidente della I Commissione del Consiglio Regionale del Lazio Sara Battisti. <\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cGrazie ai medici di medicina generale, agli operatori sanitari e all\u2019instancabile lavoro della ASL di Frosinone e in particolar modo della Dottoressa Pierpaola D\u2019Alessandro per avere dato vita al centro vaccinale di Fiuggi ormai pienamente operativo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"985\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/fiuggi2-1024x985.jpg\" alt=\"\" class=\"wp-image-58428\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/fiuggi2-1024x985.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/fiuggi2-300x288.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/fiuggi2-768x738.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/fiuggi2-1536x1477.jpg 1536w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/fiuggi2.jpg 1997w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Un ringraziamento ad ATF per aver messo a disposizione la Fonte Anticolana permettendo cos\u00ec ai cittadini di fare il vaccino all\u2019interno di un parco naturale di una bellezza straordinaria. Un messaggio fondamentale, la speranza della rinascita e il richiamo di un marchio come quello di Fiuggi che rappresenta il benessere psicofisico della persona.\u201d.<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>\u201cOggi a Fiuggi, con l&#8217;Assessore D\u2019Amato e Direttore Generale ASL di Frosinone al centro Vaccinale, abbiamo registrato grande soddisfazione da<\/p>\n","protected":false},"author":26,"featured_media":58425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[3968,108,217,9392,1721,6982],"class_list":["post-58424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-alessio-damato","tag-asl","tag-fiuggi","tag-pierpaola-dalessandro","tag-sara-battisti","tag-vaccini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fiuggi, Battisti con D&#039;Amato e il Dg Asl al centro vaccinale: grande soddisfazione da parte dei cittadini - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiuggi, Battisti con D&#039;Amato e il Dg Asl al centro vaccinale: grande soddisfazione da parte dei cittadini\" \/>\n<meta property=\"og:description\" content=\"\u201cOggi a Fiuggi, con l&#8217;Assessore D\u2019Amato e Direttore Generale ASL di Frosinone al centro Vaccinale, abbiamo registrato grande soddisfazione da\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-22T16:41:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-22T16:46:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/fiuggi1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Fiuggi, Battisti con D&#8217;Amato e il Dg Asl al centro vaccinale: grande soddisfazione da parte dei cittadini\",\"datePublished\":\"2021-05-22T16:41:21+00:00\",\"dateModified\":\"2021-05-22T16:46:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/\"},\"wordCount\":150,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/fiuggi1-scaled.jpg\",\"keywords\":[\"alessio d'amato\",\"Asl\",\"Fiuggi\",\"pierpaola d&#039;alessandro\",\"Sara Battisti\",\"vaccini\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/\",\"name\":\"Fiuggi, Battisti con D'Amato e il Dg Asl al centro vaccinale: grande soddisfazione da parte dei cittadini - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/fiuggi1-scaled.jpg\",\"datePublished\":\"2021-05-22T16:41:21+00:00\",\"dateModified\":\"2021-05-22T16:46:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/fiuggi1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/fiuggi1-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiuggi, Battisti con D&#8217;Amato e il Dg Asl al centro vaccinale: grande soddisfazione da parte dei cittadini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fiuggi, Battisti con D'Amato e il Dg Asl al centro vaccinale: grande soddisfazione da parte dei cittadini - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/","og_locale":"it_IT","og_type":"article","og_title":"Fiuggi, Battisti con D'Amato e il Dg Asl al centro vaccinale: grande soddisfazione da parte dei cittadini","og_description":"\u201cOggi a Fiuggi, con l&#8217;Assessore D\u2019Amato e Direttore Generale ASL di Frosinone al centro Vaccinale, abbiamo registrato grande soddisfazione da","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-05-22T16:41:21+00:00","article_modified_time":"2021-05-22T16:46:34+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/fiuggi1-scaled.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Fiuggi, Battisti con D&#8217;Amato e il Dg Asl al centro vaccinale: grande soddisfazione da parte dei cittadini","datePublished":"2021-05-22T16:41:21+00:00","dateModified":"2021-05-22T16:46:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/"},"wordCount":150,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/fiuggi1-scaled.jpg","keywords":["alessio d'amato","Asl","Fiuggi","pierpaola d&#039;alessandro","Sara Battisti","vaccini"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/","name":"Fiuggi, Battisti con D'Amato e il Dg Asl al centro vaccinale: grande soddisfazione da parte dei cittadini - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/fiuggi1-scaled.jpg","datePublished":"2021-05-22T16:41:21+00:00","dateModified":"2021-05-22T16:46:34+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/fiuggi1-scaled.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/fiuggi1-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Fiuggi, Battisti con D&#8217;Amato e il Dg Asl al centro vaccinale: grande soddisfazione da parte dei cittadini"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/fiuggi-battisti-con-damato-e-il-dg-asl-al-centro-vaccinale-grande-soddisfazione-da-parte-dei-cittadini\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/58424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=58424"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/58424\/revisions"}],"predecessor-version":[{"id":58431,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/58424\/revisions\/58431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/58425"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=58424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=58424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=58424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}