{"id":58406,"date":"2021-05-22T14:22:33","date_gmt":"2021-05-22T12:22:33","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=58406"},"modified":"2021-05-22T15:26:09","modified_gmt":"2021-05-22T13:26:09","slug":"ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/","title":{"rendered":"Ferentino in lutto per la morte di Sonni. Pompeo: perdiamo un pezzo della nostra storia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Si \u00e8 spento questa mattina, all&#8217;et\u00e0 di 89 anni, all&#8217;ospedale &#8216;Fabrizio Spaziani&#8217; di Frosinone, dove era ricoverato da alcuni giorni, il presidente della Pro Loco di Ferentino<\/strong>, Luigi Sonni, titolare della storica edicola in piazza Matteotti, figura centrale in tutte le iniziative e le manifestazioni della citt\u00e0, punto di riferimento per le associazioni e le attivit\u00e0 di promozione del turismo, della cultura e della storia di Ferentino. Da 45 anni alla guida della Pro Loco di Ferentino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una grave perdita per la comunit\u00e0 e, soprattutto, per il sindaco Antonio Pompeo, che ha condiviso con lui tutto il suo percorso amministrativo e ha voluto ricordarlo con non poca commozione.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<em>Una notizia tristissima per la citt\u00e0 di Ferentino \u2013\u00a0<\/em>ha detto Pompeo &#8211;\u00a0<em>e un momento difficile anche per me: la scomparsa di Luigino \u00e8 un lutto per tutti noi, che abbiamo potuto apprezzare per decenni il suo contributo, la sua energia, il suo impegno profuso per la crescita culturale e la promozione turistica di Ferentino, delle sue ricchezze, del suo patrimonio storico-artistico&#8221;.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Un legame personale forte: con lui ho condiviso tante esperienze e tanti momenti sin da quando ero assessore alla cultura e al turismo. Con lui ho lavorato fianco a fianco, con passione, dedizione ed entusiasmo. \u00c8 stato per me anche un maestro di vita, una guida che mi ha supportato e incoraggiato: consigli, suggerimenti e critiche costruttive hanno contribuito, negli anni, a rafforzare il nostro rapporto e a farmi crescere nell&#8217;esperienza amministrativa che ho acquisito oggi. Quello che sono lo devo anche al suo sostegno e alla sua vicinanza. Appassionato, legato, innamorato della citt\u00e0 e del suo ruolo di presidente, ha sempre lavorato nell&#8217;esclusivo interesse di Ferentino: un grande uomo, un grande presidente della Pro Loco e un grande amico. Oggi perdiamo tutti un pezzo importante della nostra storia. Ma non la dimenticheremo. Ciao Luigino!&#8221;.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I funerali di Luigi Sonni <strong>si terranno luned\u00ec 24 maggio 2021 nella chiesa di San Valentino a Ferentino<\/strong>. Il sindaco Antonio Pompeo e tutta l&#8217;Amministrazione comunale <strong>si stringono al dolore dei figli Fausto e Ambrogio.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ferentino in lutto per la morte del presidente della Pro Loco Luigi Sonni<\/p>\n","protected":false},"author":26,"featured_media":58414,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[842,92,1732,4297,945],"class_list":["post-58406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-antonio-pompeo","tag-ferentino","tag-funerali","tag-luigi-sonni-pro-loco","tag-morto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ferentino in lutto per la morte di Sonni. Pompeo: perdiamo un pezzo della nostra storia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferentino in lutto per la morte di Sonni. Pompeo: perdiamo un pezzo della nostra storia\" \/>\n<meta property=\"og:description\" content=\"Ferentino in lutto per la morte del presidente della Pro Loco Luigi Sonni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-22T12:22:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-22T13:26:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/Pompeo-Sonni-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"475\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Ferentino in lutto per la morte di Sonni. Pompeo: perdiamo un pezzo della nostra storia\",\"datePublished\":\"2021-05-22T12:22:33+00:00\",\"dateModified\":\"2021-05-22T13:26:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/\"},\"wordCount\":355,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/Pompeo-Sonni-1.jpg\",\"keywords\":[\"antonio pompeo\",\"ferentino\",\"funerali\",\"Luigi Sonni Pro LOco\",\"Morto\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/\",\"name\":\"Ferentino in lutto per la morte di Sonni. Pompeo: perdiamo un pezzo della nostra storia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/Pompeo-Sonni-1.jpg\",\"datePublished\":\"2021-05-22T12:22:33+00:00\",\"dateModified\":\"2021-05-22T13:26:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/Pompeo-Sonni-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/Pompeo-Sonni-1.jpg\",\"width\":475,\"height\":487,\"caption\":\"Il sindaco Pompeo e il presidente della Pro Loco Luigi Sonni\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferentino in lutto per la morte di Sonni. Pompeo: perdiamo un pezzo della nostra storia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/22\\\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ferentino in lutto per la morte di Sonni. Pompeo: perdiamo un pezzo della nostra storia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/","og_locale":"it_IT","og_type":"article","og_title":"Ferentino in lutto per la morte di Sonni. Pompeo: perdiamo un pezzo della nostra storia","og_description":"Ferentino in lutto per la morte del presidente della Pro Loco Luigi Sonni","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-05-22T12:22:33+00:00","article_modified_time":"2021-05-22T13:26:09+00:00","og_image":[{"width":475,"height":487,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/Pompeo-Sonni-1.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Ferentino in lutto per la morte di Sonni. Pompeo: perdiamo un pezzo della nostra storia","datePublished":"2021-05-22T12:22:33+00:00","dateModified":"2021-05-22T13:26:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/"},"wordCount":355,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/Pompeo-Sonni-1.jpg","keywords":["antonio pompeo","ferentino","funerali","Luigi Sonni Pro LOco","Morto"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/","name":"Ferentino in lutto per la morte di Sonni. Pompeo: perdiamo un pezzo della nostra storia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/Pompeo-Sonni-1.jpg","datePublished":"2021-05-22T12:22:33+00:00","dateModified":"2021-05-22T13:26:09+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/Pompeo-Sonni-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/Pompeo-Sonni-1.jpg","width":475,"height":487,"caption":"Il sindaco Pompeo e il presidente della Pro Loco Luigi Sonni"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ferentino in lutto per la morte di Sonni. Pompeo: perdiamo un pezzo della nostra storia"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/22\/ferentino-citta-in-lutto-per-la-morte-di-sonni-pompeo-perdiamo-un-pezzo-della-nostra-storia\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/58406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=58406"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/58406\/revisions"}],"predecessor-version":[{"id":58416,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/58406\/revisions\/58416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/58414"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=58406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=58406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=58406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}