{"id":58125,"date":"2021-05-18T10:08:50","date_gmt":"2021-05-18T08:08:50","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=58125"},"modified":"2021-05-18T18:53:26","modified_gmt":"2021-05-18T16:53:26","slug":"cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/","title":{"rendered":"Cartelle Bonifica Conca di Sora, dalla Regione massima disponibilit\u00e0 ad incontrare i sindaci per una soluzione"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br><strong>La Regione Lazio ha dato massima disponibilit\u00e0 ad incontrare gli amministratori locali al fine di mettere in campo una serie di azioni in accordo con i Comuni del territorio, <\/strong>in netta discontinuit\u00e0 con il commissariamento precedente, e <strong>soprattutto al fine di alleggerire le imposte importanti pagate dai cittadini,<\/strong> migliorando allo stesso tempo i servizi a loro offerti.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.quotidianolaprovincia.it\/wp-content\/uploads\/2021\/05\/buschini-battisti-800x445-1.jpg\" alt=\"\" class=\"wp-image-1506\" \/><figcaption>Mauro BUschini e Sara Battisti<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">L\u2019impegno<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il confronto \u00e8 stato avviato anche grazie alla disponibilit\u00e0 dei Consiglieri regionali Mauro Buschini, Sara Battisti e Loreto Marcelli, e del commissario del Consorzio di Bonifica Stefania Ruffo<\/strong>.L\u2019attuale commissariamento del Consorzio Conca di Sora ha trovato una situazione debitoria complessa di milioni di euro, per la quale comunque sono in corso attivit\u00e0 ed interventi di risoluzione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La Regione Lazio \u00e8 intervenuta con circa 500mila euro per la risoluzione del debito elettrico<\/strong>, oltre una serie di finanziamenti promossi&nbsp; nel corso degli ultimi anni. Tra questi 200mila euro per lavori di messa in sicurezza dello sbarramento mobile sul fiume Liri in localit\u00e0 Val Francesca.&nbsp;&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.quotidianolaprovincia.it\/wp-content\/uploads\/2021\/05\/loreto-marcelli-1.png\" alt=\"\" class=\"wp-image-1707\" \/><figcaption>Loreto Marecelli<\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Regione Lazio ha dato massima disponibilit\u00e0 ad incontrare gli amministratori locali al fine di mettere in campo una serie<\/p>\n","protected":false},"author":26,"featured_media":58126,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[537,6342,1692,1388,562,1721,13140],"class_list":["post-58125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-bonifica","tag-conca-di-sora","tag-loreto-marcelli","tag-mauro-buschini","tag-regione-lazio","tag-sara-battisti","tag-stefana-ruffo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cartelle Bonifica Conca di Sora, dalla Regione massima disponibilit\u00e0 ad incontrare i sindaci per una soluzione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartelle Bonifica Conca di Sora, dalla Regione massima disponibilit\u00e0 ad incontrare i sindaci per una soluzione\" \/>\n<meta property=\"og:description\" content=\"La Regione Lazio ha dato massima disponibilit\u00e0 ad incontrare gli amministratori locali al fine di mettere in campo una serie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-18T08:08:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-18T16:53:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/regione-lazio-365838.660x368.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"368\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Cartelle Bonifica Conca di Sora, dalla Regione massima disponibilit\u00e0 ad incontrare i sindaci per una soluzione\",\"datePublished\":\"2021-05-18T08:08:50+00:00\",\"dateModified\":\"2021-05-18T16:53:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/\"},\"wordCount\":187,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/regione-lazio-365838.660x368.jpg\",\"keywords\":[\"bonifica\",\"conca di sora\",\"loreto marcelli\",\"mauro buschini\",\"regione lazio\",\"Sara Battisti\",\"stefana ruffo\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/\",\"name\":\"Cartelle Bonifica Conca di Sora, dalla Regione massima disponibilit\u00e0 ad incontrare i sindaci per una soluzione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/regione-lazio-365838.660x368.jpg\",\"datePublished\":\"2021-05-18T08:08:50+00:00\",\"dateModified\":\"2021-05-18T16:53:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/regione-lazio-365838.660x368.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/regione-lazio-365838.660x368.jpg\",\"width\":660,\"height\":368},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartelle Bonifica Conca di Sora, dalla Regione massima disponibilit\u00e0 ad incontrare i sindaci per una soluzione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/18\\\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cartelle Bonifica Conca di Sora, dalla Regione massima disponibilit\u00e0 ad incontrare i sindaci per una soluzione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/","og_locale":"it_IT","og_type":"article","og_title":"Cartelle Bonifica Conca di Sora, dalla Regione massima disponibilit\u00e0 ad incontrare i sindaci per una soluzione","og_description":"La Regione Lazio ha dato massima disponibilit\u00e0 ad incontrare gli amministratori locali al fine di mettere in campo una serie","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-05-18T08:08:50+00:00","article_modified_time":"2021-05-18T16:53:26+00:00","og_image":[{"width":660,"height":368,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/regione-lazio-365838.660x368.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Cartelle Bonifica Conca di Sora, dalla Regione massima disponibilit\u00e0 ad incontrare i sindaci per una soluzione","datePublished":"2021-05-18T08:08:50+00:00","dateModified":"2021-05-18T16:53:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/"},"wordCount":187,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/regione-lazio-365838.660x368.jpg","keywords":["bonifica","conca di sora","loreto marcelli","mauro buschini","regione lazio","Sara Battisti","stefana ruffo"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/","name":"Cartelle Bonifica Conca di Sora, dalla Regione massima disponibilit\u00e0 ad incontrare i sindaci per una soluzione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/regione-lazio-365838.660x368.jpg","datePublished":"2021-05-18T08:08:50+00:00","dateModified":"2021-05-18T16:53:26+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/regione-lazio-365838.660x368.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/regione-lazio-365838.660x368.jpg","width":660,"height":368},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Cartelle Bonifica Conca di Sora, dalla Regione massima disponibilit\u00e0 ad incontrare i sindaci per una soluzione"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/18\/cartelle-bonifica-conca-di-sora-dalla-regione-massima-disponibilita-ad-incontrare-i-sindaci-per-una-soluzione\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/58125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=58125"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/58125\/revisions"}],"predecessor-version":[{"id":58127,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/58125\/revisions\/58127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/58126"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=58125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=58125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=58125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}