{"id":5807,"date":"2019-01-30T17:59:48","date_gmt":"2019-01-30T16:59:48","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=5807"},"modified":"2019-01-30T17:59:48","modified_gmt":"2019-01-30T16:59:48","slug":"droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/","title":{"rendered":"Droga, bullismo e pericoli del web: i carabinieri salgono in cattedra"},"content":{"rendered":"<p><strong>Bullismo e vandalismo<\/strong>,<strong> effetto degli stupefacenti<\/strong> e dell\u2019<strong>abuso di alcol<\/strong>, educazione stradale, <strong>violenza intra-familiare<\/strong> e di genere, <strong>pedopornografia sul web<\/strong> e pericolosit\u00e0 dei social network.<\/p>\n<p>Di questo e altro hanno parlato i carabinieri, coordinati dal <strong>comandante della Compagnia di Anagni<\/strong>, che ieri e oggi hanno incontrato i ragazzi degli <strong>Istituti \u2018Scienze Umane e Linguistico\u2019 di Anagni<\/strong>, <strong>\u2018Commerciale Lolli Ghetti\u2019 di Ferentino<\/strong> e della<strong> scuola media \u2018Ernesto Biondi\u2019 di Morolo<\/strong>, incontri ai quali hanno partecipato complessivamente oltre <strong>340 alunni<\/strong>.<\/p>\n<h2>L\u2019importanza della collaborazione<\/h2>\n<p>Il relatore, ricorrendo ad esempi concreti legati alla sua professione, attraverso un linguaggio semplice e diretto ha sottolineato l\u2019importanza della <strong>corretta collaborazione con l\u2019istituzione<\/strong> per favorire la prevenzione e la repressione dei crimini. Lo stesso ha sottolineato come &#8220;la stazione dei carabinieri deve essere considerata luogo di accoglienza di chi ha bisogno di aiuto e di tutela dei propri diritti&#8221;, vera e propria \u2018interfaccia\u2019 tra il cittadino e l\u2019Arma.<\/p>\n<p>L&#8217;obiettivo di questi incontri nelle scuole \u00e8 quello di<strong> fornire delle informazioni pi\u00f9 approfondite<\/strong> ai giovani e ai giovanissimi su temi che li toccano da vicino. Le curiosit\u00e0 degli studenti si sono concentrate non solo sull\u2019uso di droghe e dell\u2019alcol ma anche sulla violenza in genere e sulle problematiche del cyberbullismo.<\/p>\n<h2>Alcuni dei temi trattati<\/h2>\n<p>I carabinieri hanno spiegato che l&#8217;<strong>assunzione di droghe<\/strong> \u00e8 comunque un illecito, che pu\u00f2 essere amministrativo o penale, essere segnalato come consumatore di droghe pu\u00f2 precludere un giorno la partecipazione ad un concorso pubblico, ad esempio. Mentre se si passa dall&#8217;uso personale di droghe allo spaccio vero e proprio, le conseguenze legali diventano pi\u00f9 serie.<\/p>\n<p>Anche le tematiche che riguardano <strong>internet e il cyberbullismo<\/strong> hanno stimolato molte domande da parte degli studenti, i quali hanno tutti almeno un profilo su un social network, ma sono poco consapevoli delle conseguenze che pu\u00f2 creare la pubblicazione di una foto in rete.<\/p>\n<p>Le visite dei carabinieri nelle scuole saranno contraccambiate da alcune classi che insieme ai professori visiteranno il Comando Compagnia Carabinieri per conoscere da vicino le attivit\u00e0 svolte dai militari dell\u2019Arma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bullismo e vandalismo, effetto degli stupefacenti e dell\u2019abuso di alcol, educazione stradale, violenza intra-familiare e di genere, pedopornografia sul web<\/p>\n","protected":false},"author":18,"featured_media":5810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,38],"tags":[267,441,751,90,2145,189,92,59,2146,1751,367,598],"class_list":["post-5807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-scuola","tag-alcol","tag-anagni","tag-bullismo","tag-carabinieri","tag-cattedra","tag-droga","tag-ferentino","tag-internet","tag-lezioni","tag-morolo","tag-scuola","tag-violenza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Droga, bullismo e pericoli del web: i carabinieri salgono in cattedra - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"I carabinieri salgono in cattedra e affrontano insieme agli studenti i delicati temi della droga, dell&#039;abuso di alcol, del bullismo e della violenza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Droga, bullismo e pericoli del web: i carabinieri salgono in cattedra\" \/>\n<meta property=\"og:description\" content=\"I carabinieri salgono in cattedra e affrontano insieme agli studenti i delicati temi della droga, dell&#039;abuso di alcol, del bullismo e della violenza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-30T16:59:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/carabinieri-scuola-e1548867522886.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"474\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Droga, bullismo e pericoli del web: i carabinieri salgono in cattedra\",\"datePublished\":\"2019-01-30T16:59:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/carabinieri-scuola-e1548867522886.jpg\",\"keywords\":[\"alcol\",\"anagni\",\"Bullismo\",\"carabinieri\",\"cattedra\",\"droga\",\"ferentino\",\"internet\",\"lezioni\",\"morolo\",\"scuola\",\"violenza\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Scuola\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/\",\"name\":\"Droga, bullismo e pericoli del web: i carabinieri salgono in cattedra - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/carabinieri-scuola-e1548867522886.jpg\",\"datePublished\":\"2019-01-30T16:59:48+00:00\",\"description\":\"I carabinieri salgono in cattedra e affrontano insieme agli studenti i delicati temi della droga, dell'abuso di alcol, del bullismo e della violenza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/carabinieri-scuola-e1548867522886.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/carabinieri-scuola-e1548867522886.jpg\",\"width\":632,\"height\":474,\"caption\":\"Carabinieri a scuola\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Droga, bullismo e pericoli del web: i carabinieri salgono in cattedra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Droga, bullismo e pericoli del web: i carabinieri salgono in cattedra - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"I carabinieri salgono in cattedra e affrontano insieme agli studenti i delicati temi della droga, dell'abuso di alcol, del bullismo e della violenza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/","og_locale":"it_IT","og_type":"article","og_title":"Droga, bullismo e pericoli del web: i carabinieri salgono in cattedra","og_description":"I carabinieri salgono in cattedra e affrontano insieme agli studenti i delicati temi della droga, dell'abuso di alcol, del bullismo e della violenza","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-01-30T16:59:48+00:00","og_image":[{"width":632,"height":474,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/carabinieri-scuola-e1548867522886.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Droga, bullismo e pericoli del web: i carabinieri salgono in cattedra","datePublished":"2019-01-30T16:59:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/carabinieri-scuola-e1548867522886.jpg","keywords":["alcol","anagni","Bullismo","carabinieri","cattedra","droga","ferentino","internet","lezioni","morolo","scuola","violenza"],"articleSection":["*PRIMO PIANO*","Scuola"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/","name":"Droga, bullismo e pericoli del web: i carabinieri salgono in cattedra - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/carabinieri-scuola-e1548867522886.jpg","datePublished":"2019-01-30T16:59:48+00:00","description":"I carabinieri salgono in cattedra e affrontano insieme agli studenti i delicati temi della droga, dell'abuso di alcol, del bullismo e della violenza","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/carabinieri-scuola-e1548867522886.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/carabinieri-scuola-e1548867522886.jpg","width":632,"height":474,"caption":"Carabinieri a scuola"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Droga, bullismo e pericoli del web: i carabinieri salgono in cattedra"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/droga-bullismo-e-pericoli-del-web-i-carabinieri-salgono-in-cattedra\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/5807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=5807"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/5807\/revisions"}],"predecessor-version":[{"id":5811,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/5807\/revisions\/5811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/5810"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=5807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=5807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=5807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}