{"id":5798,"date":"2019-01-30T17:22:20","date_gmt":"2019-01-30T16:22:20","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=5798"},"modified":"2019-01-31T15:13:23","modified_gmt":"2019-01-31T14:13:23","slug":"infrastrutture-investimenti-regionali-per-un-milone-e-mezzo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/","title":{"rendered":"Infrastrutture, investimenti regionali per un milone e mezzo"},"content":{"rendered":"<p>Il via libera della<strong> Commissione Sviluppo Economico e Attivit\u00e0 Produttive<\/strong> del <strong>Consiglio Regionale<\/strong> alla proposta di delibera della Giunta sul programma operativo per gli &#8216;Interventi per il sostegno allo sviluppo e all\u2019occupazione nelle aree interessate dalla crisi dello stabilimento Fca (ex Fiat) di Piedimonte San Germano&#8217; <strong>permetter\u00e0 di far partire<\/strong> gi\u00e0 quest\u2019anno importanti<strong> interventi per circa un milione e mezzo<\/strong> di euro su viabilit\u00e0 e infrastrutture, funzionali all\u2019attivit\u00e0 economica e produttiva di tutto il frusinate.<\/p>\n<p>Si comincer\u00e0 da lavori di manutenzione straordinaria di un importante asse viario nel<strong> Comune di Anagni<\/strong> (progetto proposto dal Consorzio per lo Sviluppo Industriale di Frosinone) e da un intervento su un<strong> depuratore e degli scarichi fognari nell\u2019area industriale di Castrocielo<\/strong> (proposto dal Cosilam) per poi passare ad altri progetti gi\u00e0 individuati.<\/p>\n<h2>L&#8217;intervento di Manzella<\/h2>\n<p>&#8220;Molto bene &#8211; \u00e8 il commento dell&#8217;assessore regionale allo<strong> Sviluppo Economico<\/strong>, <strong>Gian Paolo Manzella<\/strong> &#8211;\u00a0 l\u2019approvazione ieri in Commissione Sviluppo Economico del piano operativo della Legge Regionale 46 del 2002. Ora partano subito i lavori. Si tratta di infrastrutture essenziali per la <strong>competitivit\u00e0 del distretto dell\u2019automotive<\/strong>: un pezzo importante della nostra economia \u2013 rappresentato da un indotto di pi\u00f9 di 10.000 lavoratori che fa perno intorno all\u2019impianto produttivo cassinate di Fca, che d\u00e0 lavoro a 4.300 persone \u2013 e un elemento essenziale di tutta la nostra identit\u00e0 industriale&#8221;.<\/p>\n<figure id=\"attachment_3502\" aria-describedby=\"caption-attachment-3502\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3502 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/stabilimento-fca-piedimonte-e1545222074353.jpg\" alt=\"stabilimento fca piedimonte san germano cassino frosinone ciociaria\" width=\"632\" height=\"317\" \/><figcaption id=\"caption-attachment-3502\" class=\"wp-caption-text\">Lo stabilimento Fca di Piedimonte San Germano<\/figcaption><\/figure>\n<p>&#8220;Questo \u00e8 un segno del nostro impegno su tutte le aree industriali del Lazio. In questi dieci mesi &#8211; continua Manzella &#8211; ho conosciuto molte realt\u00e0 del territorio ed \u00e8 qui un elemento fondamentale del nostro sistema e della nostra competitivit\u00e0. Il nostro lavoro, come amministrazione regionale, \u00e8 rendere queste aree sempre pi\u00f9 attrattive. <strong>Cominciamo con Anagni e con Castrocielo<\/strong>, ma siamo gi\u00e0 al lavoro per trovare risorse e finanziare per le altre infrastrutture del piano: a cominciare dal depuratore di Ceccano&#8221;.<\/p>\n<h2>La soddisfazione di De Angelis<\/h2>\n<p>&#8220;L\u2019investimento sulla manutenzione di strade e servizi nelle aree a vocazione industriale della provincia di Frosinone e a servizio dello stabilimento <strong>Fca di Piedimonte<\/strong>, \u00e8 un segnale forte che va nella direzione che auspichiamo per restituire slancio, fiducia e competitivit\u00e0 ai nostri territori&#8221; ha dichiarato il <strong>Commissario del Consorzio Unico, Francesco De Angelis.<\/strong><\/p>\n<p>&#8220;In questi giorni \u2013 ha continuato \u2013 insieme all\u2019assessore Manzella e ai nostri partner economici e sociali, stiamo gettando le basi del nascituro Consorzio Unico per lo sviluppo economico del Lazio, e in proposito una delle priorit\u00e0 \u00e8 stata individuata proprio nel rilancio delle infrastrutture materiali. Sono questi, infatti, gli assi su cui dobbiamo impostare la competitivit\u00e0 del sistema produttivo locale. Viceversa, si innescherebbero le spirali degradanti che disincentivano gli investimenti privati. E la provincia di Frosinone, proprio per la sua vocazione industriale, \u00e8 l\u2019ambito territoriale che pi\u00f9 di altri ha bisogno di essere incoraggiato&#8221;.<\/p>\n<figure id=\"attachment_5803\" aria-describedby=\"caption-attachment-5803\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5803 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/anagni-area-industriale-1-e1548865177501.jpg\" alt=\"area industriale anagni il corriere della provincia\" width=\"632\" height=\"375\" \/><figcaption id=\"caption-attachment-5803\" class=\"wp-caption-text\">L&#8217;area industriale di Anagni<\/figcaption><\/figure>\n<p>&#8220;Nostro obiettivo \u2013 ha proseguito De Angelis \u2013 \u00e8 <strong>rendere il territorio appetibile<\/strong> rispetto agli investimenti privati, per attirare nuove imprese da fuori e quindi nuovi posti di lavoro. Per questo le spese decise dalla Regione su proposta del tavolo di concertazione sulla 46 per le infrastrutture non sono costi ma investimenti, per mantenere, rafforzare e accompagnare l\u2019attivit\u00e0 di zone produttive strategiche per l\u2019economia regionale, tra cui <strong>Anagni, Frosinone, Ceccano, Castrocielo, Roccasecca e Cassino<\/strong>&#8220;.<\/p>\n<p>&#8220;Di grande importanza anche il <strong>progetto di finanziamento per il depuratore di Ceccano<\/strong> che conferma l\u2019attenzione e l\u2019impegno sui problemi della tutela dell\u2019ambiente e della valle del Sacco. Ora, dopo il via libera alla delibera, finalmente possiamo partire con la sistemazione e il rifacimento della rete viaria nell\u2019area industriale di Anagni. Un intervento di straordinaria importanza per restituire competitivit\u00e0 e forza al tessuto imprenditoriale della provincia. In questo senso ritengo che lo <strong>svincolo di Roccasecca sulla A1<\/strong>, tra gli investimenti del prossimo triennio, costituisca un altro importante tassello infrastrutturale per agevolare lo sviluppo economico locale. Nei prossimi tre anni, inoltre, &#8211; ha concluso De Angelis &#8211; andranno finanziate ulteriori opere decisive per lo sviluppo di tutte le imprese dell\u2019intero indotto Fca di Cassino&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il via libera della Commissione Sviluppo Economico e Attivit\u00e0 Produttive del Consiglio Regionale alla proposta di delibera della Giunta sul<\/p>\n","protected":false},"author":18,"featured_media":5799,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[2142,554,1004,2141,2144,2143,2140],"class_list":["post-5798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-economia","tag-distretto-automotive","tag-fca","tag-infrastrutture","tag-legge-regionale","tag-risorse-finanziarie","tag-sistema-produttivo","tag-sviluppo-economico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Infrastrutture, investimenti regionali per un milone e mezzo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Ok della Commissione Sviluppo Economico e Attivit\u00e0 Produttive del Consiglio Regionale alla proposta di delibera della Giunta sul programma operativo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infrastrutture, investimenti regionali per un milone e mezzo\" \/>\n<meta property=\"og:description\" content=\"Ok della Commissione Sviluppo Economico e Attivit\u00e0 Produttive del Consiglio Regionale alla proposta di delibera della Giunta sul programma operativo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-30T16:22:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-31T14:13:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/De-Angelis-Manzella.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"532\" \/>\n\t<meta property=\"og:image:height\" content=\"355\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Infrastrutture, investimenti regionali per un milone e mezzo\",\"datePublished\":\"2019-01-30T16:22:20+00:00\",\"dateModified\":\"2019-01-31T14:13:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/\"},\"wordCount\":685,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/De-Angelis-Manzella.jpg\",\"keywords\":[\"distretto automotive\",\"Fca\",\"Infrastrutture\",\"legge regionale\",\"risorse finanziarie\",\"sistema produttivo\",\"sviluppo economico\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/\",\"name\":\"Infrastrutture, investimenti regionali per un milone e mezzo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/De-Angelis-Manzella.jpg\",\"datePublished\":\"2019-01-30T16:22:20+00:00\",\"dateModified\":\"2019-01-31T14:13:23+00:00\",\"description\":\"Ok della Commissione Sviluppo Economico e Attivit\u00e0 Produttive del Consiglio Regionale alla proposta di delibera della Giunta sul programma operativo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/De-Angelis-Manzella.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/De-Angelis-Manzella.jpg\",\"width\":532,\"height\":355,\"caption\":\"De Angelis Manzella il corriere della provincia frosinone ciociaria regione lazio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Infrastrutture, investimenti regionali per un milone e mezzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/01\\\/30\\\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Infrastrutture, investimenti regionali per un milone e mezzo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Ok della Commissione Sviluppo Economico e Attivit\u00e0 Produttive del Consiglio Regionale alla proposta di delibera della Giunta sul programma operativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/","og_locale":"it_IT","og_type":"article","og_title":"Infrastrutture, investimenti regionali per un milone e mezzo","og_description":"Ok della Commissione Sviluppo Economico e Attivit\u00e0 Produttive del Consiglio Regionale alla proposta di delibera della Giunta sul programma operativo","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-01-30T16:22:20+00:00","article_modified_time":"2019-01-31T14:13:23+00:00","og_image":[{"width":532,"height":355,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/De-Angelis-Manzella.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Infrastrutture, investimenti regionali per un milone e mezzo","datePublished":"2019-01-30T16:22:20+00:00","dateModified":"2019-01-31T14:13:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/"},"wordCount":685,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/De-Angelis-Manzella.jpg","keywords":["distretto automotive","Fca","Infrastrutture","legge regionale","risorse finanziarie","sistema produttivo","sviluppo economico"],"articleSection":["*PRIMO PIANO*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/","name":"Infrastrutture, investimenti regionali per un milone e mezzo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/De-Angelis-Manzella.jpg","datePublished":"2019-01-30T16:22:20+00:00","dateModified":"2019-01-31T14:13:23+00:00","description":"Ok della Commissione Sviluppo Economico e Attivit\u00e0 Produttive del Consiglio Regionale alla proposta di delibera della Giunta sul programma operativo","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/De-Angelis-Manzella.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/De-Angelis-Manzella.jpg","width":532,"height":355,"caption":"De Angelis Manzella il corriere della provincia frosinone ciociaria regione lazio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Infrastrutture, investimenti regionali per un milone e mezzo"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/01\/30\/infrastrutture-investimenti-regionali-per-un-milone-e-mezzo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/5798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=5798"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/5798\/revisions"}],"predecessor-version":[{"id":5805,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/5798\/revisions\/5805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/5799"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=5798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=5798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=5798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}