{"id":57372,"date":"2021-05-03T16:58:29","date_gmt":"2021-05-03T14:58:29","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=57372"},"modified":"2021-05-03T16:59:22","modified_gmt":"2021-05-03T14:59:22","slug":"frosinone-asili-nido-iscrizioni-e-tariffe-invariate","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/","title":{"rendered":"Frosinone, asili nido: iscrizioni e tariffe invariate"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>L&#8217;assessorato all&#8217;istruzione, coordinato da Valentina Sementilli, rende noto che sono aperte le iscrizioni e le reiscrizioni presso gli asili nido comunali (&#8220;Pollicino&#8221; e &#8220;Fantasia&#8221;)<\/strong> per l&#8217;anno educativo 2021\/2022, come da avviso pubblico pubblicato su <a href=\"http:\/\/www.comune.frosinone.it\" target=\"_blank\" rel=\"noreferrer noopener\">www.comune.frosinone.it<\/a>. Le domande di iscrizione e reiscrizione devono essere redatte sull\u2019allegato modello (Allegato A), predisposto dal Servizio Pubblica Istruzione e debbono essere presentate tassativamente presso l\u2019ufficio di Protocollo Generale o in forma telematica a mezzo posta certificata (<a href=\"mailto:pec@pec.comune.frosinone.it\" target=\"_blank\" rel=\"noreferrer noopener\">pec@pec.comune.frosinone.it<\/a>), fino al 31 maggio 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le graduatorie di ammissione verranno pubblicate entro il 15.07.2021. Le tariffe, anche per l\u2019anno educativo in oggetto, resteranno invariate, senza alcun aumento.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"649\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/valentina-sementilli.jpg\" alt=\"\" class=\"wp-image-38307\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/valentina-sementilli.jpg 620w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/valentina-sementilli-287x300.jpg 287w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Ecco i costi<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">In particolare, per quanto riguarda l\u2019asilo \u201cFantasia\u201d, le tariffe per gli utenti residenti nel comune di Frosinone risultano suddivise per fasce di reddito: da Isee 0 a \u20ac 1.865,01, le quote mensili dal luned\u00ec al venerd\u00ec (7,30-14,30) sono pari a \u20ac 84,26; dalle ore 7.30 alle ore 16.00, sono invece pari a \u20ac 94,38. Da 1.865,02 a 6.925,76 euro, la quota con orario 7,30-14,30 \u00e8 di \u20ac 134,80, mentre con orario 7.30- 16.00 \u00e8 di \u20ac 151,767. Da \u20ac 6.925,77 a \u20ac 8.867,33, dalle ore 7,30 alle ore 14,30, \u00e8 pari a \u20ac 189,58; dalle ore 7.30 alle ore 16.00 \u00e8 di \u20ac 210,628. Da \u20ac 8.867,34 a \u20ac 12.750,46, la quota con orario 7,30-14,30 \u00e8 di \u20ac 210,64; con orario 7.30- 16.00 \u00e8 di 235,906. Da \u20ac 12.750,47 a \u20ac 16.633,60, la quota con orario 7,30-14,30 \u00e8 di \u20ac 252,77; con orario 7.30- 16.00 \u00e8 di \u20ac 278,058. Da \u20ac 16.633,61 a \u20ac 20.516,75, la quota con orario 7,30-14,30 \u00e8 di \u20ac 294,88; con orario 7.30- 16.00 \u00e8 di \u20ac 337,029. Da \u20ac 20.516,76 in su, la quota con orario 7,30-14,30 \u00e8 di \u20ac 337,79; con orario 7.30- 16.00 \u00e8 di \u20ac 385,759. Ai fini dell\u2019iscrizione presso l\u2019Asilo Nido Fantasia, per gli utenti non residenti nel Comune di Frosinone, viene fissata una tariffa unica pari all\u2019ultima fascia, mentre la retta per il secondo o pi\u00f9 figli viene ridotta del 50% rispetto alla retta per il primo figlio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questi, invece, gli importi per l\u2019iscrizione al nido \u201cPollicino\u201d, dal luned\u00ec al venerd\u00ec, con le relative fasce orarie: dalle ore 7,30 alle ore 11:30, la quota \u00e8 di 210 \u20ac; dalle ore 7,30 alle ore 13:00, \u00e8 di 290 \u20ac; dalle ore 7,30 alle ore 16:00, di 380 \u20ac.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Riguardo ai posti disponibili si rende noto che, ai fini della continuit\u00e0 educativa<\/strong>, ai fini della formazione della graduatoria, saranno prioritariamente prese in considerazione le iscrizioni dei bambini gi\u00e0 frequentanti, nell\u2019Anno Educativo 2020\/2021, l\u2019Asilo Nido Fantasia e l\u2019Asilo Nido Pollicino.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Il temine per le domande<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A seguito della pubblicazione della graduatoria delle iscrizioni dovr\u00e0 essere presentato, il modulo di accettazione dell\u2019iscrizione (Allegato B), entro il termine tassativo del 31 Luglio 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il Modulo di Accettazione dovr\u00e0 pervenire presso l\u2019ufficio di Protocollo Generale o in forma telematica a mezzo posta certificata, corredato, nel caso di nuova iscrizione, dell\u2019attestazione di versamento della cauzione. La mancata presentazione del sopraindicato modulo di accettazione comporter\u00e0 l\u2019automatica decadenza dell\u2019inserimento in graduatoria.&nbsp; Il Servizio Pubblica Istruzione si riserva di valutare le richieste di frequenza dell\u2019orario a tempo pieno (ore 7.30 \u2013 16.00) in relazione agli assetti organizzativi del Servizio Asili Nido ed anche in relazione alle necessit\u00e0 lavorative documentate del nucleo familiare di riferimento, mediante apposita disposizione dirigenziale. Si precisa che le domande di iscrizione devono essere obbligatoriamente presentate anche per i bambini gi\u00e0 frequentanti gli Asili Nido comunali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ogni informazione potr\u00e0 essere assunta presso il Servizio Pubblica Istruzione del Comune di Frosinone contattando Ida Belli, tel. 0775\/2656679; <a href=\"mailto:ida.belli@comune.frosinone.it\" target=\"_blank\" rel=\"noreferrer noopener\">ida.belli@comune.frosinone.it<\/a>, oppure Alessadro Petricca, tel. 0775\/2656261; <a href=\"mailto:alessandro.petricca@comune.frosinone.it\" target=\"_blank\" rel=\"noreferrer noopener\">alessandro.petricca@comune.frosinone.it<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;assessorato all&#8217;istruzione, coordinato da Valentina Sementilli, rende noto che sono aperte le iscrizioni e le reiscrizioni presso gli asili nido<\/p>\n","protected":false},"author":26,"featured_media":57374,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236,38],"tags":[1658,94,93,10426,639,861,1217],"class_list":["post-57372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-scuola","tag-asili-nido","tag-ciociaria","tag-frosinone","tag-la-provincia","tag-nicola-ottaviani","tag-tariffe","tag-valentina-sementilli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, asili nido: iscrizioni e tariffe invariate - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, asili nido: iscrizioni e tariffe invariate\" \/>\n<meta property=\"og:description\" content=\"L&#8217;assessorato all&#8217;istruzione, coordinato da Valentina Sementilli, rende noto che sono aperte le iscrizioni e le reiscrizioni presso gli asili nido\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-03T14:58:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-03T14:59:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/asilo-bambini-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Frosinone, asili nido: iscrizioni e tariffe invariate\",\"datePublished\":\"2021-05-03T14:58:29+00:00\",\"dateModified\":\"2021-05-03T14:59:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/\"},\"wordCount\":540,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/asilo-bambini-2.jpg\",\"keywords\":[\"asili nido\",\"Ciociaria\",\"Frosinone\",\"la provincia\",\"nicola ottaviani\",\"tariffe\",\"valentina sementilli\"],\"articleSection\":[\"Attualit\u00e0\",\"Scuola\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/\",\"name\":\"Frosinone, asili nido: iscrizioni e tariffe invariate - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/asilo-bambini-2.jpg\",\"datePublished\":\"2021-05-03T14:58:29+00:00\",\"dateModified\":\"2021-05-03T14:59:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/asilo-bambini-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/asilo-bambini-2.jpg\",\"width\":1000,\"height\":592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, asili nido: iscrizioni e tariffe invariate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/05\\\/03\\\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, asili nido: iscrizioni e tariffe invariate - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, asili nido: iscrizioni e tariffe invariate","og_description":"L&#8217;assessorato all&#8217;istruzione, coordinato da Valentina Sementilli, rende noto che sono aperte le iscrizioni e le reiscrizioni presso gli asili nido","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-05-03T14:58:29+00:00","article_modified_time":"2021-05-03T14:59:22+00:00","og_image":[{"width":1000,"height":592,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/asilo-bambini-2.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Frosinone, asili nido: iscrizioni e tariffe invariate","datePublished":"2021-05-03T14:58:29+00:00","dateModified":"2021-05-03T14:59:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/"},"wordCount":540,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/asilo-bambini-2.jpg","keywords":["asili nido","Ciociaria","Frosinone","la provincia","nicola ottaviani","tariffe","valentina sementilli"],"articleSection":["Attualit\u00e0","Scuola"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/","name":"Frosinone, asili nido: iscrizioni e tariffe invariate - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/asilo-bambini-2.jpg","datePublished":"2021-05-03T14:58:29+00:00","dateModified":"2021-05-03T14:59:22+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/asilo-bambini-2.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/05\/asilo-bambini-2.jpg","width":1000,"height":592},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, asili nido: iscrizioni e tariffe invariate"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/05\/03\/frosinone-asili-nido-iscrizioni-e-tariffe-invariate\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/57372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=57372"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/57372\/revisions"}],"predecessor-version":[{"id":57373,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/57372\/revisions\/57373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/57374"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=57372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=57372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=57372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}