{"id":57147,"date":"2021-04-29T16:37:52","date_gmt":"2021-04-29T14:37:52","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=57147"},"modified":"2021-04-29T16:37:53","modified_gmt":"2021-04-29T14:37:53","slug":"fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/","title":{"rendered":"Fiuggi: compra tre ma riceve due. Sessantenne truffato su internet da moglie e marito"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si era lasciato allettare dal prezzo particolarmente vantaggioso e cos\u00ec ha deciso di acquistare su internet <strong>un orologio, un lampadario e vecchie insegne pubblicitarie<\/strong>. Peccato, per\u00f2, che aprendo il pacco ha trovato soltanto i primi due: <strong>delle 20 insegne al costo di 350 euro non c\u2019era traccia.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 cos\u00ec che <strong>un sessantenne di Fiuggi<\/strong> ha scoperto di essere stato vittima di una truffa dopo aver versato la somma su una postepay senza aver ricevuto, per\u00f2, tutto quello che aveva acquistato. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ha chiesto spiegazioni riguardo al ritardo, rivolgendosi al venditore ma le risposte ricevute erano sempre evasive.<strong> Sospettando di essere stato raggirato, il 60enne ha deciso allora di rivolgersi alla Polizia<\/strong> che, dopo i dovuti accertamenti, ha denunciato due partenopei, moglie e marito, per truffa in concorso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un sessantenne di Fiuggi \u00e8 stato truffato da una coppia di napoletani da cui ha acquistato oggetti su internet<\/p>\n","protected":false},"author":26,"featured_media":52228,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[94,217,93,59,291,5067,3830,243],"class_list":["post-57147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-ciociaria","tag-fiuggi","tag-frosinone","tag-internet","tag-polizia","tag-postepay","tag-sessantenne","tag-truffa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fiuggi: compra tre ma riceve due. Sessantenne truffato su internet da moglie e marito - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiuggi: compra tre ma riceve due. Sessantenne truffato su internet da moglie e marito\" \/>\n<meta property=\"og:description\" content=\"Un sessantenne di Fiuggi \u00e8 stato truffato da una coppia di napoletani da cui ha acquistato oggetti su internet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-29T14:37:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-29T14:37:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/foto-social.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"451\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Fiuggi: compra tre ma riceve due. Sessantenne truffato su internet da moglie e marito\",\"datePublished\":\"2021-04-29T14:37:52+00:00\",\"dateModified\":\"2021-04-29T14:37:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/\"},\"wordCount\":138,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/foto-social.jpg\",\"keywords\":[\"Ciociaria\",\"Fiuggi\",\"Frosinone\",\"internet\",\"polizia\",\"postepay\",\"sessantenne\",\"truffa\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/\",\"name\":\"Fiuggi: compra tre ma riceve due. Sessantenne truffato su internet da moglie e marito - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/foto-social.jpg\",\"datePublished\":\"2021-04-29T14:37:52+00:00\",\"dateModified\":\"2021-04-29T14:37:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/foto-social.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/foto-social.jpg\",\"width\":800,\"height\":451,\"caption\":\"polizia postale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiuggi: compra tre ma riceve due. Sessantenne truffato su internet da moglie e marito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/29\\\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fiuggi: compra tre ma riceve due. Sessantenne truffato su internet da moglie e marito - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/","og_locale":"it_IT","og_type":"article","og_title":"Fiuggi: compra tre ma riceve due. Sessantenne truffato su internet da moglie e marito","og_description":"Un sessantenne di Fiuggi \u00e8 stato truffato da una coppia di napoletani da cui ha acquistato oggetti su internet","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-04-29T14:37:52+00:00","article_modified_time":"2021-04-29T14:37:53+00:00","og_image":[{"width":800,"height":451,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/foto-social.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Fiuggi: compra tre ma riceve due. Sessantenne truffato su internet da moglie e marito","datePublished":"2021-04-29T14:37:52+00:00","dateModified":"2021-04-29T14:37:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/"},"wordCount":138,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/foto-social.jpg","keywords":["Ciociaria","Fiuggi","Frosinone","internet","polizia","postepay","sessantenne","truffa"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/","name":"Fiuggi: compra tre ma riceve due. Sessantenne truffato su internet da moglie e marito - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/foto-social.jpg","datePublished":"2021-04-29T14:37:52+00:00","dateModified":"2021-04-29T14:37:53+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/foto-social.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/foto-social.jpg","width":800,"height":451,"caption":"polizia postale"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Fiuggi: compra tre ma riceve due. Sessantenne truffato su internet da moglie e marito"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/29\/fiuggi-compra-tre-ma-riceve-due-sessantenne-truffato-su-internet-da-moglie-e-marito\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/57147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=57147"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/57147\/revisions"}],"predecessor-version":[{"id":57148,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/57147\/revisions\/57148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/52228"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=57147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=57147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=57147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}