{"id":57099,"date":"2021-04-28T16:49:19","date_gmt":"2021-04-28T14:49:19","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=57099"},"modified":"2021-04-28T21:12:14","modified_gmt":"2021-04-28T19:12:14","slug":"consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/","title":{"rendered":"Consorzio di Bonifica: Salera chiede a Zingaretti di sospendere le bollette 2021"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Cos\u00ec come stabilito nella precedente riunione, il sindaco <strong>Enzo Salera<\/strong>, nella sua qualit\u00e0 di presidente della Consulta dei Sindaci del Lazio Meridionale, ha trasmesso al Presidente della Regione, <strong>Nicola Zingaretti<\/strong>, il verbale e i relativi atti. Tale documentazione \u00e8 stata inviata per conoscenza anche al commissario del Consorzio di Bonifica \u201cValle del Liri\u201d, dott.ssa <strong>Stefania Ruffo<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ci\u00f2 perch\u00e9 uno dei tre argomenti all\u2019ordine del giorno trattati dalla Consulta in quella riunione ha riguardato la problematica dei pesanti aumenti tariffari del Consorzio. Dove in questi anni si \u00e8 registrato il susseguirsi di vari commissari dell\u2019Ente. Come anche il raddoppio delle quote di irrigazione. Insomma una politica \u201clacrime e sangue\u201d. Come ha avuto modo di definirla, <strong>Albino Ruberti<\/strong>, capo di gabinetto della Regione, da lui ritenuta doverosa e necessaria per ripartire con un discorso nuovo. Egli giustificava cos\u00ec il ricorso al Commissariamento del Consorzio: \u00ab<em>La decisione \u00e8 stata dettata dalle gravi criticit\u00e0 riscontrate nella precedente amministrazione del Consorzio di Bonifica, che hanno dato vita a quella preoccupante situazione debitoria. E a una serie di inefficienze che gravavano sui consorziati\u00bb.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Esasperati per il canone di irrigazione<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">I consorziati, in gran numero, esasperati per l\u2019entit\u00e0 del canone di irrigazione e delle tariffe si sono rivolti ai sindaci, da qui la presa di posizione dei primi cittadini.<br><strong>Enzo Salera<\/strong>, a nome dei suoi colleghi, richiede ed auspica l\u2019intervento della Regione &#8220;<em>affinch\u00e9 il Consorzio di Bonifica<\/em> \u2013 si legge in un passo della sua lettera \u2013 <em>previa sospensione immediata del pagamento delle bollette per l\u2019anno 2021, relative sia al servizio di irrigazione che al pagamento del contributo a difesa del suolo, voglia spiegare e chiarire in merito agli immotivati aumenti dei tributi, sia per il servizio di irrigazione che per la difesa del suolo, nonch\u00e9 rendere pubblici gli atti amministrativi in base ai quali sono stati stabiliti gli ulteriori aumenti dei canoni nel 2021<\/em>&#8220;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viene chiesto inoltre la verifica delle opere di concreto beneficio realizzate in tutte le aree interessate dal \u201c<strong>Valle del Liri<\/strong>\u201d, atteso che &#8220;\u00e8 pacificamente incostituzionale \u2013 si legge \u2013 imporre il contributo ai consorziati indipendentemente dal beneficio predetto&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cos\u00ec come stabilito nella precedente riunione, il sindaco Enzo Salera, nella sua qualit\u00e0 di presidente della Consulta dei Sindaci del<\/p>\n","protected":false},"author":26,"featured_media":51284,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,1],"tags":[216,6555,3273,918],"class_list":["post-57099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-news","tag-cassino","tag-consorzio-di-bonifica","tag-enzo-salera","tag-nicola-zingaretti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Consorzio di Bonifica: Salera chiede a Zingaretti di sospendere le bollette 2021 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consorzio di Bonifica: Salera chiede a Zingaretti di sospendere le bollette 2021\" \/>\n<meta property=\"og:description\" content=\"Cos\u00ec come stabilito nella precedente riunione, il sindaco Enzo Salera, nella sua qualit\u00e0 di presidente della Consulta dei Sindaci del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-28T14:49:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-28T19:12:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/salera-enzo-cassino-sindaco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"761\" \/>\n\t<meta property=\"og:image:height\" content=\"492\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Consorzio di Bonifica: Salera chiede a Zingaretti di sospendere le bollette 2021\",\"datePublished\":\"2021-04-28T14:49:19+00:00\",\"dateModified\":\"2021-04-28T19:12:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/\"},\"wordCount\":355,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/salera-enzo-cassino-sindaco.jpg\",\"keywords\":[\"Cassino\",\"consorzio di bonifica\",\"enzo salera\",\"nicola zingaretti\"],\"articleSection\":[\"*PRIMO PIANO*\",\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/\",\"name\":\"Consorzio di Bonifica: Salera chiede a Zingaretti di sospendere le bollette 2021 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/salera-enzo-cassino-sindaco.jpg\",\"datePublished\":\"2021-04-28T14:49:19+00:00\",\"dateModified\":\"2021-04-28T19:12:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/salera-enzo-cassino-sindaco.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/salera-enzo-cassino-sindaco.jpg\",\"width\":761,\"height\":492},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consorzio di Bonifica: Salera chiede a Zingaretti di sospendere le bollette 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/28\\\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Consorzio di Bonifica: Salera chiede a Zingaretti di sospendere le bollette 2021 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/","og_locale":"it_IT","og_type":"article","og_title":"Consorzio di Bonifica: Salera chiede a Zingaretti di sospendere le bollette 2021","og_description":"Cos\u00ec come stabilito nella precedente riunione, il sindaco Enzo Salera, nella sua qualit\u00e0 di presidente della Consulta dei Sindaci del","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-04-28T14:49:19+00:00","article_modified_time":"2021-04-28T19:12:14+00:00","og_image":[{"width":761,"height":492,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/salera-enzo-cassino-sindaco.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Consorzio di Bonifica: Salera chiede a Zingaretti di sospendere le bollette 2021","datePublished":"2021-04-28T14:49:19+00:00","dateModified":"2021-04-28T19:12:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/"},"wordCount":355,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/salera-enzo-cassino-sindaco.jpg","keywords":["Cassino","consorzio di bonifica","enzo salera","nicola zingaretti"],"articleSection":["*PRIMO PIANO*","News"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/","name":"Consorzio di Bonifica: Salera chiede a Zingaretti di sospendere le bollette 2021 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/salera-enzo-cassino-sindaco.jpg","datePublished":"2021-04-28T14:49:19+00:00","dateModified":"2021-04-28T19:12:14+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/salera-enzo-cassino-sindaco.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/salera-enzo-cassino-sindaco.jpg","width":761,"height":492},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Consorzio di Bonifica: Salera chiede a Zingaretti di sospendere le bollette 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/28\/consorzio-di-bonifica-salera-chiede-a-zingaretti-di-sospendere-le-bollette-2021\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/57099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=57099"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/57099\/revisions"}],"predecessor-version":[{"id":57108,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/57099\/revisions\/57108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/51284"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=57099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=57099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=57099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}