{"id":56782,"date":"2021-04-22T16:59:19","date_gmt":"2021-04-22T14:59:19","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=56782"},"modified":"2021-04-23T14:40:44","modified_gmt":"2021-04-23T12:40:44","slug":"frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/","title":{"rendered":"Frosinone: convenzione con l\u2019Universit\u00e0 di Perugia per stage al Comune"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La giunta Ottaviani ha approvato la convenzione quadro per la promozione di tirocini teorico pratici <strong>tra il Comune di Frosinone e l&#8217;Universit\u00e0 degli studi di Perugia<\/strong> &#8211;\u00a0 Dipartimento di Ingegneria Civile ed Ambientale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019ateneo umbro, infatti, ha scelto il Comune di Frosinone per promuovere iniziative di tirocinio pratico, al fine di agevolare le scelte professionali degli studenti frequentanti i corsi, stipulando apposita convenzione; <strong>l\u2019attivit\u00e0 di stage, pur se limitata nel tempo, permette infatti allo studente di conseguire importanti risultati<\/strong> che vanno dall&#8217;acquisizione di un\u2019immagine pi\u00f9 reale del mondo lavorativo all\u2019opportunit\u00e0 di apprendere concrete metodologie operative e di organizzazione del lavoro, oltre a costituire <strong>un\u2019utile occasione di approfondimento ed arricchimento delle tematiche trattate nei corsi di studio.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Spetta all\u2019Universit\u00e0 degli Studi di Perugia \u2013 Dipartimento di Ingegneria Civile ed Ambientale (soggetto promotore) assicurare i tirocinanti contro gli infortuni sul lavoro presso l&#8217;INAIL, con la speciale forma della copertura assicurativa per conto dello Stato (D.P.R. n. 156 del 9\/4\/1999), e per la responsabilit\u00e0 civile presso compagnie assicurative operanti nel settore. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"749\" height=\"562\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/comune-frosinone.jpg\" alt=\"comune frosinone\" class=\"wp-image-55785\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/comune-frosinone.jpg 749w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/comune-frosinone-300x225.jpg 300w\" sizes=\"auto, (max-width: 749px) 100vw, 749px\" \/><figcaption>Il Comune di Frosinone<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il tirocinio non costituisce rapporto di lavoro e, quindi, il Comune di Frosinone (soggetto ospitante) non ha alcun obbligo di assunzione al termine del periodo del tirocinio stesso. <\/strong>L\u2019Universit\u00e0 si impegner\u00e0 a comunicare il nominativo degli allievi inviati presso il Comune di Frosinone specificando la tipologia dell\u2019attivit\u00e0 formativa da svolgere. Per ciascun tirocinio avviato sulla base della convenzione, inoltre, verr\u00e0 predisposto un progetto formativo e di orientamento, ove verr\u00e0 individuato all\u2019interno dell\u2019ente un tutor in veste di responsabile didattico \u2013organizzativo, designato di volta in volta dal soggetto ospitante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La giunta ha quindi approvato lo schema di convenzione fra Comune e Universit\u00e0 degli Studi di Perugia \u2013 Dipartimento di Ingegneria Civile ed Ambientale, per l&#8217;avvio di tirocini di formazione e di orientamento da effettuarsi presso la sede comunale, con validit\u00e0 quinquennale. \u00c8 stato dato mandato al dirigente del settore servizi alla persona \u2013 servizio personale di firmare l\u2019originale di convenzione da porre a base del rapporto giuridico tra le parti e di individuare di volta in volta il tutor didattico \u2013 organizzativo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Frosinone ha firmato una convenzione con l&#8217;Universit\u00e0 di Perugia per avviare stage formativi<\/p>\n","protected":false},"author":26,"featured_media":56783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,38],"tags":[94,149,93,639,12908,12907,12909,685],"class_list":["post-56782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-scuola","tag-ciociaria","tag-comune","tag-frosinone","tag-nicola-ottaviani","tag-perugia","tag-stage","tag-tirocinio","tag-universita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone: convenzione con l\u2019Universit\u00e0 di Perugia per stage al Comune - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone: convenzione con l\u2019Universit\u00e0 di Perugia per stage al Comune\" \/>\n<meta property=\"og:description\" content=\"Il Comune di Frosinone ha firmato una convenzione con l&#039;Universit\u00e0 di Perugia per avviare stage formativi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-22T14:59:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-23T12:40:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/uni-perugia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"946\" \/>\n\t<meta property=\"og:image:height\" content=\"634\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Frosinone: convenzione con l\u2019Universit\u00e0 di Perugia per stage al Comune\",\"datePublished\":\"2021-04-22T14:59:19+00:00\",\"dateModified\":\"2021-04-23T12:40:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/\"},\"wordCount\":364,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/uni-perugia.jpg\",\"keywords\":[\"Ciociaria\",\"comune\",\"Frosinone\",\"nicola ottaviani\",\"perugia\",\"stage\",\"tirocinio\",\"Universit\u00e0\"],\"articleSection\":[\"Evidenza\",\"Scuola\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/\",\"name\":\"Frosinone: convenzione con l\u2019Universit\u00e0 di Perugia per stage al Comune - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/uni-perugia.jpg\",\"datePublished\":\"2021-04-22T14:59:19+00:00\",\"dateModified\":\"2021-04-23T12:40:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/uni-perugia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/uni-perugia.jpg\",\"width\":946,\"height\":634,\"caption\":\"L'Universit\u00e0 di Perugia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone: convenzione con l\u2019Universit\u00e0 di Perugia per stage al Comune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/22\\\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone: convenzione con l\u2019Universit\u00e0 di Perugia per stage al Comune - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone: convenzione con l\u2019Universit\u00e0 di Perugia per stage al Comune","og_description":"Il Comune di Frosinone ha firmato una convenzione con l'Universit\u00e0 di Perugia per avviare stage formativi","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-04-22T14:59:19+00:00","article_modified_time":"2021-04-23T12:40:44+00:00","og_image":[{"width":946,"height":634,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/uni-perugia.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Frosinone: convenzione con l\u2019Universit\u00e0 di Perugia per stage al Comune","datePublished":"2021-04-22T14:59:19+00:00","dateModified":"2021-04-23T12:40:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/"},"wordCount":364,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/uni-perugia.jpg","keywords":["Ciociaria","comune","Frosinone","nicola ottaviani","perugia","stage","tirocinio","Universit\u00e0"],"articleSection":["Evidenza","Scuola"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/","name":"Frosinone: convenzione con l\u2019Universit\u00e0 di Perugia per stage al Comune - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/uni-perugia.jpg","datePublished":"2021-04-22T14:59:19+00:00","dateModified":"2021-04-23T12:40:44+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/uni-perugia.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/uni-perugia.jpg","width":946,"height":634,"caption":"L'Universit\u00e0 di Perugia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone: convenzione con l\u2019Universit\u00e0 di Perugia per stage al Comune"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/22\/frosinone-convenzione-con-luniversita-di-perugia-per-stage-al-comune\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=56782"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56782\/revisions"}],"predecessor-version":[{"id":56784,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56782\/revisions\/56784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/56783"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=56782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=56782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=56782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}