{"id":56673,"date":"2021-04-19T15:25:00","date_gmt":"2021-04-19T13:25:00","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=56673"},"modified":"2021-04-20T16:46:16","modified_gmt":"2021-04-20T14:46:16","slug":"anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/","title":{"rendered":"Anagni, fatturazione tariffe idriche: tavolo tra Comune, Acea e associazioni"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nel corso del tavolo tecnico tra <strong>Comune di Anagni, Acea&nbsp; ATO 5 S.p.A. <\/strong>ed <strong>Associazioni dei Consumatori <\/strong>tenutosi nel pomeriggio del 16 aprile&nbsp; in merito alle utenze idriche di Localit\u00e0 San Bartolomeo, i partecipanti hanno deciso di&nbsp; avviare una collaborazione volta a condividere i principi per la corretta interpretazione&nbsp; dei criteri di fatturazione applicati all\u2019utenza a partire dal 2019.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La questione<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Diverse le tematiche affrontate, dal corretto computo dei componenti dei nuclei familiari&nbsp;<\/strong> e di concessione per le utenze commerciali, alle modalit\u00e0 previste per rateizzazioni e&nbsp; bonus idrico. Nell\u2019ambito della giornata dei lavori, il sindaco <strong>Daniele Natalia <\/strong>e&nbsp; l&#8217;assessore ai Rapporti con il Gestore Idrico Integrato, <strong>Valentina Cicconi<\/strong>, hanno&nbsp; rilevato che la cifra riportata nelle bollette di Acea Ato 5 relative alle utenze di San&nbsp; Bartolomeo rappresenta un prezzo forfettario applicato dalla societ\u00e0 a partire da&nbsp; novembre 2019. Non si tratta quindi del pregresso calcolato tra il 2014 ed il 2019.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acea Ato 5 <\/strong>&#8211; nel corso dello svolgimento dell\u2019incontro &#8211; ha comunque garantito la&nbsp; possibilit\u00e0 di accogliere le richieste dell\u2019utenza relative al recepimento del corretto&nbsp; numero di componenti del nucleo familiare, nel caso delle utenze uso domestico, o del&nbsp; numero di concessioni nel caso di forniture relative ad attivit\u00e0 commerciali ed ha inoltre&nbsp; ricordato che, In ogni caso, tutti gli utenti hanno la possibilit\u00e0 sia di rateizzare il&nbsp; pagamento, sia di vedersi applicato il bonus idrico qualora ve ne fossero le condizioni,&nbsp;nonch\u00e9 di rappresentare eventuali anomalie relative a casi particolari, utilizzando i consueti canali di contatto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u2019Amministrazione comunale ed Acea Ato5 rimarranno tra loro in costante contatto, per&nbsp; favorire un rapporto proficuo<\/strong> al fine di individuare tutte le situazioni particolari che&nbsp; necessitino di particolare attenzione. Nel corso dell\u2019incontro, Acea Ato5 ha inoltre&nbsp; rappresentato il progressivo avviamento, per tutta la base d\u2019utenza dell\u2019ATO 5, e quindi&nbsp; anche per i cittadini di Anagni e della Localit\u00e0 di San Bartolomeo, delle attivit\u00e0&nbsp; propedeutiche all\u2019applicazione delle nuove tariffe deliberate della Conferenza dei Sindaci&nbsp; del 10\/03\/2021, relative anche alle annualit\u00e0 2020 e 2021. La Societ\u00e0 precisa pertanto&nbsp; che le comunicazioni trasmesse sono relative esclusivamente a questo processo e&nbsp; riportano indicazioni precise con conseguenti riferimenti normativi: si avvisano pertanto&nbsp; i cittadini di diffidare di altre tipologie di comunicazioni eventualmente pervenute facenti&nbsp; riferimento a presunti storni\/sgravi\/decurtazioni o altre similari tipologie di rettifica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel corso del tavolo tecnico tra Comune di Anagni, Acea&nbsp; ATO 5 S.p.A. ed Associazioni dei Consumatori tenutosi nel pomeriggio<\/p>\n","protected":false},"author":26,"featured_media":37795,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236,28],"tags":[1329,441,94,5333,9575],"class_list":["post-56673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-politica","tag-acea-ato-5","tag-anagni","tag-ciociaria","tag-san-bartolomeo","tag-tariffe-idriche"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Anagni, fatturazione tariffe idriche: tavolo tra Comune, Acea e associazioni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anagni, fatturazione tariffe idriche: tavolo tra Comune, Acea e associazioni\" \/>\n<meta property=\"og:description\" content=\"Nel corso del tavolo tecnico tra Comune di Anagni, Acea&nbsp; ATO 5 S.p.A. ed Associazioni dei Consumatori tenutosi nel pomeriggio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-19T13:25:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-20T14:46:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/comune-anagni-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"685\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Anagni, fatturazione tariffe idriche: tavolo tra Comune, Acea e associazioni\",\"datePublished\":\"2021-04-19T13:25:00+00:00\",\"dateModified\":\"2021-04-20T14:46:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/\"},\"wordCount\":418,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/comune-anagni-1.jpg\",\"keywords\":[\"acea ato 5\",\"anagni\",\"Ciociaria\",\"san bartolomeo\",\"tariffe idriche\"],\"articleSection\":[\"Attualit\u00e0\",\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/\",\"name\":\"Anagni, fatturazione tariffe idriche: tavolo tra Comune, Acea e associazioni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/comune-anagni-1.jpg\",\"datePublished\":\"2021-04-19T13:25:00+00:00\",\"dateModified\":\"2021-04-20T14:46:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/comune-anagni-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/comune-anagni-1.jpg\",\"width\":685,\"height\":445,\"caption\":\"La sede del Comune di Anagni\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anagni, fatturazione tariffe idriche: tavolo tra Comune, Acea e associazioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/19\\\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Anagni, fatturazione tariffe idriche: tavolo tra Comune, Acea e associazioni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/","og_locale":"it_IT","og_type":"article","og_title":"Anagni, fatturazione tariffe idriche: tavolo tra Comune, Acea e associazioni","og_description":"Nel corso del tavolo tecnico tra Comune di Anagni, Acea&nbsp; ATO 5 S.p.A. ed Associazioni dei Consumatori tenutosi nel pomeriggio","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-04-19T13:25:00+00:00","article_modified_time":"2021-04-20T14:46:16+00:00","og_image":[{"width":685,"height":445,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/comune-anagni-1.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Anagni, fatturazione tariffe idriche: tavolo tra Comune, Acea e associazioni","datePublished":"2021-04-19T13:25:00+00:00","dateModified":"2021-04-20T14:46:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/"},"wordCount":418,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/comune-anagni-1.jpg","keywords":["acea ato 5","anagni","Ciociaria","san bartolomeo","tariffe idriche"],"articleSection":["Attualit\u00e0","Evidenza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/","name":"Anagni, fatturazione tariffe idriche: tavolo tra Comune, Acea e associazioni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/comune-anagni-1.jpg","datePublished":"2021-04-19T13:25:00+00:00","dateModified":"2021-04-20T14:46:16+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/comune-anagni-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/comune-anagni-1.jpg","width":685,"height":445,"caption":"La sede del Comune di Anagni"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Anagni, fatturazione tariffe idriche: tavolo tra Comune, Acea e associazioni"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/19\/anagni-fatturazione-tariffe-idriche-tavolo-di-lavoro-tra-comune-acea-e-associazioni\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=56673"}],"version-history":[{"count":6,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56673\/revisions"}],"predecessor-version":[{"id":56734,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56673\/revisions\/56734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/37795"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=56673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=56673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=56673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}