{"id":56327,"date":"2021-04-13T14:07:20","date_gmt":"2021-04-13T12:07:20","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=56327"},"modified":"2021-04-13T14:08:17","modified_gmt":"2021-04-13T12:08:17","slug":"isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/","title":{"rendered":"Isola del Liri: la palestra del \u2018Nicolucci-Reggio\u2019 diventa centro vaccinale anti-Covid"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La palestra dell\u2019<strong>Istituto d\u2019Istruzione Superiore &#8216;Nicolucci-Reggio&#8217; di Isola del Liri <\/strong>sar\u00e0 utilizzata come centro per la <strong>vaccinazione anti-Covid<\/strong>: saranno i medici di base, molti dei quali hanno gi\u00e0 dato la loro disponibilit\u00e0, ad occuparsi delle inoculazioni.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un&#8217;iniziativa dell&#8217;amministrazione comunale della citt\u00e0 delle cascate, guidata dal <strong>sindaco e consigliere provinciale delegato all&#8217;Edilizia Scolastica, Massimiliano Quadrini<\/strong>, con il pieno supporto della Provincia di Frosinone e del <strong>presidente Antonio Pompeo<\/strong>, anche a seguito dell&#8217;impegno, assunto dalle Province attraverso l&#8217;Upi, di individuare sedi e spazi idonei da utilizzare come centri di somministrazione dei vaccini.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Spazi della Provincia per le somministrazioni<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;Ente di piazza Gramsci, peraltro, non \u00e8 nuovo ad azioni e interventi concreti per i territori:<strong> con il progetto &#8216;Provincia Solidale&#8217; ha messo in campo, sin dall&#8217;inizio dell&#8217;emergenza, numerose misure di sostegno, <\/strong>soprattutto per aiutare le fasce deboli della popolazione e le famiglie in maggiore difficolt\u00e0, anche attraverso il coinvolgimento delle Caritas diocesane.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"643\" height=\"633\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Pompeo-Quadrini.jpg\" alt=\"scuole controlli provincia terremoto pompeo quadrini il corriere\" class=\"wp-image-21896\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Pompeo-Quadrini.jpg 643w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Pompeo-Quadrini-300x295.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Pompeo-Quadrini-500x492.jpg 500w\" sizes=\"auto, (max-width: 643px) 100vw, 643px\" \/><figcaption>Il presidente Antonio Pompeo e il consigliere provinciale e sindaco Massimiliano Quadrini<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I locali della palestra di Isola del Liri saranno allestiti con tutte le strumentazioni necessarie, sanificati secondo i protocolli previsti per legge e gi\u00e0 nei prossimi giorni la struttura entrer\u00e0 in funzione, con le prime vaccinazioni. Da parte sua il sindaco ha voluto ringraziare i medici di base che hanno gi\u00e0 confermato la loro disponibilit\u00e0, sottolineando come la comunit\u00e0 isolana, sin dalle prime fasi dell&#8217;emergenza, abbia dimostrato grande senso di solidariet\u00e0 e vicinanza nei confronti di quanti sono stati colpiti dal virus e delle situazioni di particolare disagio aggravate dalla pandemia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un modello replicabile sul territorio<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Siamo tutti consapevoli \u2013 \u00e8 il commento di <strong>Pompeo e Quadrini <\/strong>\u2013 che questo \u00e8 il momento pi\u00f9 importante nella durissima battaglia contro il Covid. \u00c8 necessario ogni sforzo possibile affinch\u00e9 la campagna di vaccinazione possa proseguire spedita con l&#8217;obiettivo di immunizzare tutti i cittadini che lo vorranno nei tempi pi\u00f9 rapidi possibili. Quello di Isola del Liri, dove la palestra di una scuola viene riconvertita ad hub vaccinale, pu\u00f2 e deve diventare un modello replicabile anche in altri Comuni del territorio, per aumentare il numero di centri in cui sar\u00e0 possibile effettuare la somministrazione dei vaccini. Questa \u00e8 l&#8217;unica arma per sconfiggere la diffusione del virus che ancora sta facendo vittime in tutto il Paese&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La palestra dell&#8217;IIS &#8216;Nicolucci Reggio&#8217; di Isola del Liri diventer\u00e0 centro vaccinale anti-Covid<\/p>\n","protected":false},"author":26,"featured_media":1217,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[842,94,8916,3346,93,260,1775,8841,3141,12209],"class_list":["post-56327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-antonio-pompeo","tag-ciociaria","tag-covid","tag-edilizia-scolastica","tag-frosinone","tag-isola-del-liri","tag-massimiliano-quadrini","tag-nicolucci-reggio","tag-palestra","tag-vaccinazione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Isola del Liri: la palestra del \u2018Nicolucci-Reggio\u2019 diventa centro vaccinale anti-Covid - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isola del Liri: la palestra del \u2018Nicolucci-Reggio\u2019 diventa centro vaccinale anti-Covid\" \/>\n<meta property=\"og:description\" content=\"La palestra dell&#039;IIS &#039;Nicolucci Reggio&#039; di Isola del Liri diventer\u00e0 centro vaccinale anti-Covid\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-13T12:07:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-13T12:08:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/itis-nicolucci-reggio-isola-del-liri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Isola del Liri: la palestra del \u2018Nicolucci-Reggio\u2019 diventa centro vaccinale anti-Covid\",\"datePublished\":\"2021-04-13T12:07:20+00:00\",\"dateModified\":\"2021-04-13T12:08:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/\"},\"wordCount\":390,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/itis-nicolucci-reggio-isola-del-liri.jpg\",\"keywords\":[\"antonio pompeo\",\"Ciociaria\",\"covid\",\"edilizia scolastica\",\"Frosinone\",\"isola del liri\",\"massimiliano quadrini\",\"nicolucci reggio\",\"palestra\",\"vaccinazione\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/\",\"name\":\"Isola del Liri: la palestra del \u2018Nicolucci-Reggio\u2019 diventa centro vaccinale anti-Covid - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/itis-nicolucci-reggio-isola-del-liri.jpg\",\"datePublished\":\"2021-04-13T12:07:20+00:00\",\"dateModified\":\"2021-04-13T12:08:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/itis-nicolucci-reggio-isola-del-liri.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/itis-nicolucci-reggio-isola-del-liri.jpg\",\"width\":660,\"height\":375,\"caption\":\"L'ingresso dell'Itis Nicolucci Reggio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Isola del Liri: la palestra del \u2018Nicolucci-Reggio\u2019 diventa centro vaccinale anti-Covid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/13\\\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Isola del Liri: la palestra del \u2018Nicolucci-Reggio\u2019 diventa centro vaccinale anti-Covid - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/","og_locale":"it_IT","og_type":"article","og_title":"Isola del Liri: la palestra del \u2018Nicolucci-Reggio\u2019 diventa centro vaccinale anti-Covid","og_description":"La palestra dell'IIS 'Nicolucci Reggio' di Isola del Liri diventer\u00e0 centro vaccinale anti-Covid","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-04-13T12:07:20+00:00","article_modified_time":"2021-04-13T12:08:17+00:00","og_image":[{"width":660,"height":375,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/itis-nicolucci-reggio-isola-del-liri.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Isola del Liri: la palestra del \u2018Nicolucci-Reggio\u2019 diventa centro vaccinale anti-Covid","datePublished":"2021-04-13T12:07:20+00:00","dateModified":"2021-04-13T12:08:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/"},"wordCount":390,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/itis-nicolucci-reggio-isola-del-liri.jpg","keywords":["antonio pompeo","Ciociaria","covid","edilizia scolastica","Frosinone","isola del liri","massimiliano quadrini","nicolucci reggio","palestra","vaccinazione"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/","name":"Isola del Liri: la palestra del \u2018Nicolucci-Reggio\u2019 diventa centro vaccinale anti-Covid - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/itis-nicolucci-reggio-isola-del-liri.jpg","datePublished":"2021-04-13T12:07:20+00:00","dateModified":"2021-04-13T12:08:17+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/itis-nicolucci-reggio-isola-del-liri.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/itis-nicolucci-reggio-isola-del-liri.jpg","width":660,"height":375,"caption":"L'ingresso dell'Itis Nicolucci Reggio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Isola del Liri: la palestra del \u2018Nicolucci-Reggio\u2019 diventa centro vaccinale anti-Covid"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/13\/isola-del-liri-la-palestra-del-nicolucci-reggio-diventa-centro-per-la-somministrazione-dei-vaccini\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=56327"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56327\/revisions"}],"predecessor-version":[{"id":56329,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56327\/revisions\/56329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/1217"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=56327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=56327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=56327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}