{"id":56226,"date":"2021-04-11T08:46:42","date_gmt":"2021-04-11T06:46:42","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=56226"},"modified":"2021-04-11T08:46:44","modified_gmt":"2021-04-11T06:46:44","slug":"frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/","title":{"rendered":"Frosinone: bilancio tecnico in attesa dei fondi del Governo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Giunta Ottaviani ha approvato la proposta del<strong> bilancio di previsione 2021-2023 e il Documento Unico di Programmazione<\/strong>, tenuto conto della scadenza imposta dalla legge rinviata da ultimo con il decreto cosiddetto Sostegni al 30 aprile 2021. <strong>La proposta di bilancio<\/strong>, che sar\u00e0 di natura sostanzialmente tecnica, in attesa delle decisioni del Governo sui fondi per fronteggiare la crisi socio-sanitaria, <strong>ha come obiettivo principale il mantenimento dei livelli qualitativi e quantitativi dei servizi fondamentali gestiti dall\u2019ente<\/strong>, con particolare riferimento ai servizi sociali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il bilancio, inoltre, permette di adempiere agli obblighi di rientro del disavanzo concordati con i magistrati contabili, <strong>tenuto conto del recupero gi\u00e0 attuato per l\u2019anno 2020 <\/strong>che dovr\u00e0 completarsi nei primi due esercizi dell\u2019attuale bilancio di previsione secondo la tempistica definita dal Consiglio comunale ed approvata dalla Corte dei conti del Lazio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;analisi di Mastrangeli<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Il Documento Unico di Programmazione \u00e8 lo strumento che permette l\u2019attivit\u00e0 di guida strategica ed operativa degli enti locali e costituisce il presupposto fondamentale e imprescindibile per l\u2019approvazione del bilancio di previsione 2021-2023 \u2013 ha dichiarato <strong>l\u2019assessore al bilancio e alle finanze, Riccardo Mastrangeli<\/strong> \u2013 Quest\u2019ultimo \u00e8 interessato dalle recenti restrizioni imposte dall\u2019emergenza sanitaria le quali, in considerazione dell\u2019impatto imposto dal Governo centrale, hanno avuto una importante influenza nei conti degli enti locali e quindi anche del Comune di Frosinone. Con il D.L. 34\/2020, in un primo intervento, infatti, il legislatore ha previsto un ristoro iniziale delle future mancate entrate per circa 3 Miliardi per i soli Comuni, la cui suddivisione, per\u00f2, segue un complicato iter di difficile interpretazione in tema di impatto sulle singole entrate<strong>. La legge di bilancio 2021 e il dl 41\/2021 ha incrementato, per l\u2019anno in corso, ulteriori risorse pari a complessivi 1.35 miliardi<\/strong>, con l\u2019impossibilit\u00e0, per\u00f2, al momento, di tradurre il ristoro previsto dallo Stato con le minori entrate effettive del Comune o delle minori spese sostenute, la cui certificazione si avr\u00e0 solo con la prima certificazione al Mef, nel mese di maggio 2021, come da normativa. Il tutto, in un ente, come il nostro, gi\u00e0 in procedura di riequilibrio finanziario pluriennale, che ha gi\u00e0 imposto una forte contrazione della spesa corrente (-10% sulle prestazioni di beni e servizi e -25% sulla parte di trasferimenti a carico dell\u2019ente)&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"749\" height=\"562\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/comune-frosinone.jpg\" alt=\"comune frosinone\" class=\"wp-image-55785\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/comune-frosinone.jpg 749w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/comune-frosinone-300x225.jpg 300w\" sizes=\"auto, (max-width: 749px) 100vw, 749px\" \/><figcaption>Il Comune di Frosinone<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Lo stesso piano di risanamento del debito (derivante da importi pregressi non onorati ammontanti a circa 50 milioni di euro), inoltre, non permette di accendere mutui: una limitazione che l\u2019amministrazione ha trasformato in forza, dal momento che ha permesso a Frosinone di diventare la prima in Italia ad adottare il rent to buy per una sede istituzionale e, in particolare, per il palazzo comunale, che sar\u00e0 a breve allocato nella prestigiosa sede di Palazzo Munari, ex Banca d&#8217;Italia. <strong>Per quanto riguarda le opere pubbliche <\/strong>\u2013 ha proseguito Mastrangeli &#8211; in considerazione delle risorse trasferite per il programma delle periferie e delle altre risorse dedicate agli interventi di pianificazione e riqualificazione promossi dall\u2019amministrazione Ottaviani,<strong> i cronoprogrammi procedono secondo le direttive stabilite dagli organi vigilanti,<\/strong> nonostante la crisi epidemiologica ancora in atto. Particolare riguardo sar\u00e0 posto sull\u2019utilizzazione del cosiddetto \u201cfondone\u201d, ossia delle risorse trasferite dallo Stato per il Covid-19, attualmente accantonate nell\u2019avanzo vincolato. Dai recenti dati dell\u2019anno 2020 \u00e8 emerso una sostanziale tenuta per le entrate da autoliquidazione (IMU e addizionale Irpef). In materia di personale, nella fase finale della procedura di ripianamento del debito, dopo otto anni di azioni efficaci e puntuali,<strong> si stanno liberando nuove risorse che consentono la ripresa delle assunzioni di nuovo personale, <\/strong>soprattutto all&#8217;interno degli uffici tecnici e amministrativi: si prevedono, infatti, le assunzioni di quattro istruttori direttivi tecnici e di due assistenti sociali&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si attendono effetti positivi sia sulle risorse economiche che dovranno ancora essere trasferite dallo Stato anche per l\u2019anno corrente, sia sugli emendamenti al decreto sostegni suggeriti dall\u2019ANCI, bench\u00e9 l\u2019inserimento sia prematuro nella fase attuale del bilancio di previsione.Lo schema del bilancio di previsione e il Dup saranno poi sottoposti al consiglio comunale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il bilancio tecnico del Comune di Frosinone in attesa dei fondi governativi<\/p>\n","protected":false},"author":26,"featured_media":37589,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[1335,94,149,565,93,330,2033],"class_list":["post-56226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-economia","tag-bilancio","tag-ciociaria","tag-comune","tag-fondi","tag-frosinone","tag-governo","tag-riccardo-mastrangeli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone: bilancio tecnico in attesa dei fondi del Governo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone: bilancio tecnico in attesa dei fondi del Governo\" \/>\n<meta property=\"og:description\" content=\"Il bilancio tecnico del Comune di Frosinone in attesa dei fondi governativi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-11T06:46:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-11T06:46:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/Riccardo-Mastrangeli-01-2-800x445-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Frosinone: bilancio tecnico in attesa dei fondi del Governo\",\"datePublished\":\"2021-04-11T06:46:42+00:00\",\"dateModified\":\"2021-04-11T06:46:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/\"},\"wordCount\":670,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/Riccardo-Mastrangeli-01-2-800x445-1.jpg\",\"keywords\":[\"bilancio\",\"Ciociaria\",\"comune\",\"fondi\",\"Frosinone\",\"Governo\",\"riccardo mastrangeli\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/\",\"name\":\"Frosinone: bilancio tecnico in attesa dei fondi del Governo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/Riccardo-Mastrangeli-01-2-800x445-1.jpg\",\"datePublished\":\"2021-04-11T06:46:42+00:00\",\"dateModified\":\"2021-04-11T06:46:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/Riccardo-Mastrangeli-01-2-800x445-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/Riccardo-Mastrangeli-01-2-800x445-1.jpg\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone: bilancio tecnico in attesa dei fondi del Governo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone: bilancio tecnico in attesa dei fondi del Governo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone: bilancio tecnico in attesa dei fondi del Governo","og_description":"Il bilancio tecnico del Comune di Frosinone in attesa dei fondi governativi","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-04-11T06:46:42+00:00","article_modified_time":"2021-04-11T06:46:44+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/Riccardo-Mastrangeli-01-2-800x445-1.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Frosinone: bilancio tecnico in attesa dei fondi del Governo","datePublished":"2021-04-11T06:46:42+00:00","dateModified":"2021-04-11T06:46:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/"},"wordCount":670,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/Riccardo-Mastrangeli-01-2-800x445-1.jpg","keywords":["bilancio","Ciociaria","comune","fondi","Frosinone","Governo","riccardo mastrangeli"],"articleSection":["*PRIMO PIANO*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/","name":"Frosinone: bilancio tecnico in attesa dei fondi del Governo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/Riccardo-Mastrangeli-01-2-800x445-1.jpg","datePublished":"2021-04-11T06:46:42+00:00","dateModified":"2021-04-11T06:46:44+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/Riccardo-Mastrangeli-01-2-800x445-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/Riccardo-Mastrangeli-01-2-800x445-1.jpg","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone: bilancio tecnico in attesa dei fondi del Governo"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-bilancio-tecnico-in-attesa-dei-fondi-del-governo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=56226"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56226\/revisions"}],"predecessor-version":[{"id":56227,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56226\/revisions\/56227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/37589"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=56226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=56226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=56226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}