{"id":56204,"date":"2021-04-11T07:20:21","date_gmt":"2021-04-11T05:20:21","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=56204"},"modified":"2021-04-11T07:27:47","modified_gmt":"2021-04-11T05:27:47","slug":"bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/","title":{"rendered":"Bando Ossigeno, Battisti: nel Frusinate finanziati tutti i progetti"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;Il bando &#8220;Ossigeno&#8221; \u00e8 l&#8217;emblema della grande rivoluzione green della Regione Lazio. Attraverso questo bando, infatti, si finanzia la piantumazione di nuovi alberi e arbusti nelle aree pubbliche, restituendo aria nuova e pulita ai nostri territori. Sono molto soddisfatta per il risultato conseguito nella Provincia di Frosinone, dove sono stati finanziati tutti i progetti presentati, sintomo di una grande attenzione e sensibilit\u00e0 da parte delle nostre amministrazioni verso il verde&#8221;.  <strong>Cos\u00ec Sara Battisti, consigliere regionale del PD. <\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ecco quali sono<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><b>In particolare<\/b>, i Comuni finanziati sono: Coreno Ausonio, Falvaterra, Piedimonte San Germano, Alatri, San Giovanni Incarico, San Giorgio a Liri, Posta Fibreno, Cassino, Veroli, Vicalvi, Pescosolido, Alvito, Anagni, Fontana Liri, Fumone, Acuto, Serrone, Sant&#8217;Elia Fiumerapido, Ceccano, Vallerotonda, Castro dei Volsci, Pontecorvo, Ceprano, Villa Santo Stefano, Patrica, Roccasecca, Giuliano di Roma, oltre a Villa Casa Lawrence.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>&#8220;<strong>Ossigeno si inserisce in una prospettiva ampia di progettualit\u00e0 votate al green da integrare anche con il mio impegno in &#8220;RiparTiAmo &#8211; tourism&#8221;<\/strong>, in particolare nel &#8220;Progetto sentieri&#8221; che prevede la realizzazione di percorsi naturalistici per attrarre visitatori e turismo di prossimit\u00e0.<br>Credere nella difesa ambientale e nel ripristino di ampie aree verdi, lavorare per accrescere l\u2019offerta turistica legata segmento dell\u2019outdoor permette di dare un volto nuovo e una nuova vocazione alla nostra Provincia. Un grazie alla Giunta regionale per questa opportunit\u00e0 per i territori del Lazio&#8217;. &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Il bando &#8220;Ossigeno&#8221; \u00e8 l&#8217;emblema della grande rivoluzione green della Regione Lazio. Attraverso questo bando, infatti, si finanzia la piantumazione<\/p>\n","protected":false},"author":26,"featured_media":29990,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[94,613,93,12828,98,562,1721],"class_list":["post-56204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-ciociaria","tag-finanziamenti","tag-frosinone","tag-ossigeno","tag-pd","tag-regione-lazio","tag-sara-battisti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bando Ossigeno, Battisti: nel Frusinate finanziati tutti i progetti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bando Ossigeno, Battisti: nel Frusinate finanziati tutti i progetti\" \/>\n<meta property=\"og:description\" content=\"&#8220;Il bando &#8220;Ossigeno&#8221; \u00e8 l&#8217;emblema della grande rivoluzione green della Regione Lazio. Attraverso questo bando, infatti, si finanzia la piantumazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-11T05:20:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-11T05:27:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/sara-battisti.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"328\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Bando Ossigeno, Battisti: nel Frusinate finanziati tutti i progetti\",\"datePublished\":\"2021-04-11T05:20:21+00:00\",\"dateModified\":\"2021-04-11T05:27:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/\"},\"wordCount\":234,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/sara-battisti.png\",\"keywords\":[\"Ciociaria\",\"finanziamenti\",\"Frosinone\",\"Ossigeno\",\"Pd\",\"regione lazio\",\"Sara Battisti\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/\",\"name\":\"Bando Ossigeno, Battisti: nel Frusinate finanziati tutti i progetti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/sara-battisti.png\",\"datePublished\":\"2021-04-11T05:20:21+00:00\",\"dateModified\":\"2021-04-11T05:27:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/sara-battisti.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/sara-battisti.png\",\"width\":512,\"height\":328,\"caption\":\"Sara Battisti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bando Ossigeno, Battisti: nel Frusinate finanziati tutti i progetti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bando Ossigeno, Battisti: nel Frusinate finanziati tutti i progetti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/","og_locale":"it_IT","og_type":"article","og_title":"Bando Ossigeno, Battisti: nel Frusinate finanziati tutti i progetti","og_description":"&#8220;Il bando &#8220;Ossigeno&#8221; \u00e8 l&#8217;emblema della grande rivoluzione green della Regione Lazio. Attraverso questo bando, infatti, si finanzia la piantumazione","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-04-11T05:20:21+00:00","article_modified_time":"2021-04-11T05:27:47+00:00","og_image":[{"width":512,"height":328,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/sara-battisti.png","type":"image\/png"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Bando Ossigeno, Battisti: nel Frusinate finanziati tutti i progetti","datePublished":"2021-04-11T05:20:21+00:00","dateModified":"2021-04-11T05:27:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/"},"wordCount":234,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/sara-battisti.png","keywords":["Ciociaria","finanziamenti","Frosinone","Ossigeno","Pd","regione lazio","Sara Battisti"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/","name":"Bando Ossigeno, Battisti: nel Frusinate finanziati tutti i progetti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/sara-battisti.png","datePublished":"2021-04-11T05:20:21+00:00","dateModified":"2021-04-11T05:27:47+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/sara-battisti.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/sara-battisti.png","width":512,"height":328,"caption":"Sara Battisti"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Bando Ossigeno, Battisti: nel Frusinate finanziati tutti i progetti"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/bando-ossigeno-battisti-nel-frusinate-finanziati-tutti-i-progetti\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=56204"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56204\/revisions"}],"predecessor-version":[{"id":56205,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56204\/revisions\/56205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/29990"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=56204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=56204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=56204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}