{"id":56111,"date":"2021-04-11T07:00:46","date_gmt":"2021-04-11T05:00:46","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=56111"},"modified":"2021-04-11T07:48:27","modified_gmt":"2021-04-11T05:48:27","slug":"frosinone-ultima-domenica-ecologica","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/","title":{"rendered":"Frosinone,  ultima domenica ecologica. Ottaviani: presto 16 km di piste ciclabili"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Oggi a Frosinone<\/strong> si terr\u00e0 la quinta e ultima giornata ecologica in adempimento delle disposizioni statuite dalla Regione Lazio in materia di Piano sulla qualit\u00e0 dell&#8217;aria, per il contenimento dei valori delle polveri sottili.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dalle ore 8 alle 18 <\/strong>, dunque, divieto di circolazione nell\u2019area urbana circoscritta dalle seguenti strade: da via Tiburtina, piazza Madonna della Neve, via Madonna della Neve, via Marco Tullio Cicerone (da incrocio con via Madonna della Neve), viale Volsci, via Simoncelli, via Vado del Tufo, viale Europa, via Marittima (da incrocio viale Europa), via Puccini, via Pasta, via Pier Luigi da Palestrina, via san Giuliano, via Vivaldi, via Verdi (da incrocio via Vivaldi), viale America Latina, via Marconi, via Fosse Ardeatine, via san Gerardo (senso unico in discesa), via don Buttarazzi, via Ferrarelli (da incrocio via don Buttarazzi), via Caio Mario, via Maria (da incrocio via Caio Mario) fino all&#8217;incrocio con via Tiburtina; limitatamente al tratto stradale di via Sacra Famiglia, uscita obbligata su via Pasta (sottopasso ferroviario); limitatamente a via Mascagni, \u00e8 vietato il transito sul tratto di piazza Pertini e di via Monteverdi in direzione piazza Kambo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 comunque consentito l&#8217;accesso di tutti i tipi di veicoli per raggiungere la pi\u00f9 vicina area destinata a parcheggio (da cui sar\u00e0 quindi possibile recarsi presso le varie zone del centro urbano mediante i servizi di trasporto pubblico), come piazza Salvo D&#8217;Acquisto, piazza Falcone e Borsellino (antistante la villa comunale), piazza Martiri delle Foibe (parcheggio Questura, in via Vado del Tufo). Sono esentati dal divieto i veicoli ibridi o elettrici, quelli adibiti a pubblici servizi, a servizio di persone invalide e quelli comunque autorizzati per esigenze speciali.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ottaviani: attenzione sempre altissima sull&#8217;ambiente<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La misura della limitazione alla circolazione veicolare, mediante le domeniche ecologiche &#8211; ha dichiarato <strong>il sindaco di Frosinone, Nicola Ottaviani<\/strong> &#8211; certamente non \u00e8 risolutiva rispetto al problema della concentrazione delle polveri sottili, specie in quelle citt\u00e0 in cui, per conformazione stessa del territorio, \u00e8 impossibile usufruire di correnti in grado di permettere un ricambio ottimale dell\u2019aria. Tuttavia, le disposizioni statuite dal Piano della Regione costituiscono uno strumento in grado di attenuare le emissioni e di modificare i comportamenti che hanno un impatto sull\u2019ambiente in cui viviamo&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"341\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/nicola-ottaviani-aggressivo.jpg\" alt=\"ottaviani de laurentis frosinone napoli stirpe\" class=\"wp-image-5340\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/nicola-ottaviani-aggressivo.jpg 512w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/nicola-ottaviani-aggressivo-300x200.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/nicola-ottaviani-aggressivo-500x333.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/nicola-ottaviani-aggressivo-272x182.jpg 272w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><figcaption>Il sindaco di Frosinone Nicola Ottaviani<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;L\u2019attenzione da parte dell\u2019amministrazione comunale sulla materia ambientale \u00e8 sempre altissima, nella convinzione, anche, che attraverso una effettiva cultura della pedonalizzazione o della mobilit\u00e0 alternativa sia possibile procedere, nel medio e lungo periodo, al raggiungimento degli ambiziosi obiettivi di ottimizzazione della qualit\u00e0 dell&#8217;aria&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">A Frosinone presto 16 km di piste ciclabili<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Per questo motivo, <strong>stiamo continuando a lavorare per varare circa 16 km di piste ciclabili in citt\u00e0<\/strong>, dopo aver introdotto il rinnovo della flotta del trasporto pubblico locale, con tutti i bus euro 6, in linea con i migliori parametri europei, in materia di mezzi pubblici. Abbiamo proseguito, inoltre, <strong>nell&#8217;attivit\u00e0 di controllo sugli impianti di riscaldamento civili e industriali, promuovendo, poi, progetti, come &#8216;Urban Forestry&#8217;<\/strong>, che prevedono la messa a dimora e la cura di nuovi alberi sul territorio comunale, al fine di creare un sistema integrato unico di verde urbano territoriale tale da avere un effetto sinergico nel rimuovere notevoli quantit\u00e0 di inquinanti e contribuire a ridurre l\u2019anidride carbonica&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 11 aprile si terr\u00e0 l&#8217;ultima domenica ecologica nel capoluogo <\/p>\n","protected":false},"author":26,"featured_media":53974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[520,94,528,1929,93,639,461],"class_list":["post-56111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-ambiente","tag-ciociaria","tag-circolazione","tag-domenica-ecologica","tag-frosinone","tag-nicola-ottaviani","tag-traffico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, ultima domenica ecologica. Ottaviani: presto 16 km di piste ciclabili - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, ultima domenica ecologica. Ottaviani: presto 16 km di piste ciclabili\" \/>\n<meta property=\"og:description\" content=\"Domenica 11 aprile si terr\u00e0 l&#039;ultima domenica ecologica nel capoluogo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-11T05:00:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-11T05:48:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/domenica2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1023\" \/>\n\t<meta property=\"og:image:height\" content=\"663\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Frosinone, ultima domenica ecologica. Ottaviani: presto 16 km di piste ciclabili\",\"datePublished\":\"2021-04-11T05:00:46+00:00\",\"dateModified\":\"2021-04-11T05:48:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/\"},\"wordCount\":542,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/domenica2.jpg\",\"keywords\":[\"ambiente\",\"Ciociaria\",\"circolazione\",\"domenica ecologica\",\"Frosinone\",\"nicola ottaviani\",\"traffico\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/\",\"name\":\"Frosinone, ultima domenica ecologica. Ottaviani: presto 16 km di piste ciclabili - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/domenica2.jpg\",\"datePublished\":\"2021-04-11T05:00:46+00:00\",\"dateModified\":\"2021-04-11T05:48:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/domenica2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/domenica2.jpg\",\"width\":1023,\"height\":663,\"caption\":\"domenica ecologica frosinone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, ultima domenica ecologica. Ottaviani: presto 16 km di piste ciclabili\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/11\\\/frosinone-ultima-domenica-ecologica\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, ultima domenica ecologica. Ottaviani: presto 16 km di piste ciclabili - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, ultima domenica ecologica. Ottaviani: presto 16 km di piste ciclabili","og_description":"Domenica 11 aprile si terr\u00e0 l'ultima domenica ecologica nel capoluogo","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-04-11T05:00:46+00:00","article_modified_time":"2021-04-11T05:48:27+00:00","og_image":[{"width":1023,"height":663,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/domenica2.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Frosinone, ultima domenica ecologica. Ottaviani: presto 16 km di piste ciclabili","datePublished":"2021-04-11T05:00:46+00:00","dateModified":"2021-04-11T05:48:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/"},"wordCount":542,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/domenica2.jpg","keywords":["ambiente","Ciociaria","circolazione","domenica ecologica","Frosinone","nicola ottaviani","traffico"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/","name":"Frosinone, ultima domenica ecologica. Ottaviani: presto 16 km di piste ciclabili - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/domenica2.jpg","datePublished":"2021-04-11T05:00:46+00:00","dateModified":"2021-04-11T05:48:27+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/domenica2.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/domenica2.jpg","width":1023,"height":663,"caption":"domenica ecologica frosinone"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, ultima domenica ecologica. Ottaviani: presto 16 km di piste ciclabili"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/11\/frosinone-ultima-domenica-ecologica\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=56111"}],"version-history":[{"count":5,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56111\/revisions"}],"predecessor-version":[{"id":56218,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56111\/revisions\/56218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/53974"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=56111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=56111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=56111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}