{"id":56085,"date":"2021-04-08T14:29:20","date_gmt":"2021-04-08T12:29:20","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=56085"},"modified":"2021-04-08T15:15:05","modified_gmt":"2021-04-08T13:15:05","slug":"astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/","title":{"rendered":"AstraZeneca, uso raccomandato per over 60. La Asl: nessuno stop per la seconda dose"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dalla Asl di Frosinone arriva la comunicazione che il Ministero della Salute raccomanda l\u2019uso preferenziale del vaccino AstraZeneca &#8220;nelle persone di et\u00e0 superiore ai 60 anni&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La circolare diramata oggi a tutti gli organi competenti ed \u00e8 stata firmata dal<strong> direttore generale Gianni Rezza<\/strong>. La disposizione ministeriale fa sua la linea del <strong>Comitato tecnico scientifico (Cts)<\/strong> e del <strong>Consiglio superiore di Sanit\u00e0.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pur ribadendo che il vaccino \u00e8 approvato per <strong>tutte le persone con pi\u00f9 di 18 anni di et\u00e0<\/strong>, se ne raccomanda un suo uso &#8220;preferenziale nelle persone di et\u00e0 superiore ai 60 anni&#8221;, tenuto conto del \u201cbasso rischio di reazioni avverse di tipo trombo embolico a fronte della elevata mortalit\u00e0 da Covid-19\u201c.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pertanto tutti i prenotati per la seconda dose&nbsp; del vaccino AstraZeneca possono completare il ciclo assumendo la seconda dose regolarmente.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Astrazeneca \u00e8 raccomandato per gli over 60 ma chi ha gi\u00e0 effettuato la prima dose pu\u00f2 tranquillamente assumere la seconda <\/p>\n","protected":false},"author":26,"featured_media":53002,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[108,12460,94,8822,93,9328],"class_list":["post-56085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-asl","tag-astrazeneca","tag-ciociaria","tag-comitato-tecnico-scientifico","tag-frosinone","tag-vaccino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>AstraZeneca, uso raccomandato per over 60. La Asl: nessuno stop per la seconda dose - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AstraZeneca, uso raccomandato per over 60. La Asl: nessuno stop per la seconda dose\" \/>\n<meta property=\"og:description\" content=\"Astrazeneca \u00e8 raccomandato per gli over 60 ma chi ha gi\u00e0 effettuato la prima dose pu\u00f2 tranquillamente assumere la seconda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-08T12:29:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-08T13:15:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/02\/vaccino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"735\" \/>\n\t<meta property=\"og:image:height\" content=\"416\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"AstraZeneca, uso raccomandato per over 60. La Asl: nessuno stop per la seconda dose\",\"datePublished\":\"2021-04-08T12:29:20+00:00\",\"dateModified\":\"2021-04-08T13:15:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/\"},\"wordCount\":144,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/vaccino.jpg\",\"keywords\":[\"Asl\",\"astrazeneca\",\"Ciociaria\",\"comitato tecnico scientifico\",\"Frosinone\",\"vaccino\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/\",\"name\":\"AstraZeneca, uso raccomandato per over 60. La Asl: nessuno stop per la seconda dose - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/vaccino.jpg\",\"datePublished\":\"2021-04-08T12:29:20+00:00\",\"dateModified\":\"2021-04-08T13:15:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/vaccino.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/vaccino.jpg\",\"width\":735,\"height\":416,\"caption\":\"vaccino anti-covid\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AstraZeneca, uso raccomandato per over 60. La Asl: nessuno stop per la seconda dose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/08\\\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AstraZeneca, uso raccomandato per over 60. La Asl: nessuno stop per la seconda dose - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/","og_locale":"it_IT","og_type":"article","og_title":"AstraZeneca, uso raccomandato per over 60. La Asl: nessuno stop per la seconda dose","og_description":"Astrazeneca \u00e8 raccomandato per gli over 60 ma chi ha gi\u00e0 effettuato la prima dose pu\u00f2 tranquillamente assumere la seconda","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-04-08T12:29:20+00:00","article_modified_time":"2021-04-08T13:15:05+00:00","og_image":[{"width":735,"height":416,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/02\/vaccino.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"AstraZeneca, uso raccomandato per over 60. La Asl: nessuno stop per la seconda dose","datePublished":"2021-04-08T12:29:20+00:00","dateModified":"2021-04-08T13:15:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/"},"wordCount":144,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/02\/vaccino.jpg","keywords":["Asl","astrazeneca","Ciociaria","comitato tecnico scientifico","Frosinone","vaccino"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/","name":"AstraZeneca, uso raccomandato per over 60. La Asl: nessuno stop per la seconda dose - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/02\/vaccino.jpg","datePublished":"2021-04-08T12:29:20+00:00","dateModified":"2021-04-08T13:15:05+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/02\/vaccino.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/02\/vaccino.jpg","width":735,"height":416,"caption":"vaccino anti-covid"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"AstraZeneca, uso raccomandato per over 60. La Asl: nessuno stop per la seconda dose"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/08\/astrazeneca-uso-raccomandato-per-over-60-la-asl-nessuno-stop-per-la-seconda-dose\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=56085"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56085\/revisions"}],"predecessor-version":[{"id":56089,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/56085\/revisions\/56089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/53002"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=56085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=56085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=56085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}