{"id":55801,"date":"2021-04-02T13:23:11","date_gmt":"2021-04-02T11:23:11","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=55801"},"modified":"2021-04-02T15:00:52","modified_gmt":"2021-04-02T13:00:52","slug":"coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/","title":{"rendered":"Coldiretti, al via l\u2019operazione solidariet\u00e0 di Pasqua con il sostegno della Camera di Commercio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Coldiretti insieme alla Camera di Commercio portano in tavola la solidariet\u00e0 a Pasqua<\/strong>. Consegnati i pacchi di circa 50 kg l&#8217;uno, che attraverso l&#8217;opera della Croce Rossa Italiana e della Protezione saranno consegnati alle famiglie che si trovano in difficolt\u00e0 a causa della crisi determinata dall\u2019emergenza sanitaria. Prodotti Made in Lazio che consentiranno a chi versa in stato di difficolt\u00e0 di trascorrere delle festivit\u00e0 pi\u00f9 serene attraverso l\u2019iniziativa \u201cA sostegno di chi ha pi\u00f9 bisogno\u201d. Una iniziativa promossa da Coldiretti, Filiera Italia e Campagna Amica con la partecipazione delle pi\u00f9 rilevanti realt\u00e0 economiche e sociali del Paese e che oggi trova l&#8217;adesione convinta della Camera di Commercio Frosinone-Latina.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"560\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/solidarieta.jpg\" alt=\"\" class=\"wp-image-55808\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/solidarieta.jpg 684w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/solidarieta-300x246.jpg 300w\" sizes=\"auto, (max-width: 684px) 100vw, 684px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento di Acampora<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Una iniziativa\u00a0 importante che fa onore ad una grande organizzazione come Coldiretti&#8221; &#8211;<strong> ha commentato il Presidente della Camera di Commercio Giovanni Acampora che aggiunge<\/strong> &#8211; &#8221; \u00e8 in questi momenti che occorre superare tecnicismi e burocrazia e andare direttamente al cuore dei problemi, non appena il Direttore di Coldiretti Carlo Picchi , al quale va il mio ringraziamento, me lo ha proposto, abbiamo immediatamente attivato la rete di solidariet\u00e0, attraverso la Croce Rossa e la Protezione civile. Sono davvero felice&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLe nostre imprese, nonostante le difficolt\u00e0 in questi mesi non hanno mai smesso di produrre cibo, hanno garantito l\u2019approvvigionamento alimentare ai cittadini e dimostrato un forte senso di comunit\u00e0 facendo sentire il proprio sostegno ai meno fortunati. L\u2019iniziativa, inoltre, \u00e8 stata resa possibile grazie alla collaborazione della Croce Rossa e alla Protezione civile per la provincia di Latina e dalla Caritas e diversi Comuni per quella di Frosinone\u201d<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le parole di Picchi<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa nostra vuole essere un\u2019iniziativa dalla doppia solidariet\u00e0 \u2013<strong> ha voluto sottolineare il Direttore di Coldiretti Carlo Picchi <\/strong>\u2013 andando a sostenere le aziende italiane con l\u2019acquisto dei loro prodotti e aiutando quelle famiglie, che a seguito della pandemia, si sono trovate in difficolt\u00e0.\u00a0 Abbiamo voluto cos\u00ec dimostrare la vicinanza della filiera\u00a0 agroalimentare verso le fasce pi\u00f9 deboli della popolazione\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coldiretti insieme alla Camera di Commercio portano in tavola la solidariet\u00e0 a Pasqua. Consegnati i pacchi di circa 50 kg<\/p>\n","protected":false},"author":26,"featured_media":55807,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1013,2027,1375,8826,513],"class_list":["post-55801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-camera-di-commercio","tag-carlo-picchi","tag-coldiretti","tag-giovanni-acampora","tag-latina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coldiretti, al via l\u2019operazione solidariet\u00e0 di Pasqua con il sostegno della Camera di Commercio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coldiretti, al via l\u2019operazione solidariet\u00e0 di Pasqua con il sostegno della Camera di Commercio\" \/>\n<meta property=\"og:description\" content=\"Coldiretti insieme alla Camera di Commercio portano in tavola la solidariet\u00e0 a Pasqua. Consegnati i pacchi di circa 50 kg\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-02T11:23:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-02T13:00:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/picchi-acampora.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"654\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Coldiretti, al via l\u2019operazione solidariet\u00e0 di Pasqua con il sostegno della Camera di Commercio\",\"datePublished\":\"2021-04-02T11:23:11+00:00\",\"dateModified\":\"2021-04-02T13:00:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/\"},\"wordCount\":342,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/picchi-acampora.jpg\",\"keywords\":[\"Camera di Commercio\",\"carlo picchi\",\"coldiretti\",\"giovanni acampora\",\"latina\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/\",\"name\":\"Coldiretti, al via l\u2019operazione solidariet\u00e0 di Pasqua con il sostegno della Camera di Commercio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/picchi-acampora.jpg\",\"datePublished\":\"2021-04-02T11:23:11+00:00\",\"dateModified\":\"2021-04-02T13:00:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/picchi-acampora.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/picchi-acampora.jpg\",\"width\":654,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coldiretti, al via l\u2019operazione solidariet\u00e0 di Pasqua con il sostegno della Camera di Commercio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/02\\\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coldiretti, al via l\u2019operazione solidariet\u00e0 di Pasqua con il sostegno della Camera di Commercio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/","og_locale":"it_IT","og_type":"article","og_title":"Coldiretti, al via l\u2019operazione solidariet\u00e0 di Pasqua con il sostegno della Camera di Commercio","og_description":"Coldiretti insieme alla Camera di Commercio portano in tavola la solidariet\u00e0 a Pasqua. Consegnati i pacchi di circa 50 kg","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-04-02T11:23:11+00:00","article_modified_time":"2021-04-02T13:00:52+00:00","og_image":[{"width":654,"height":512,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/picchi-acampora.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Coldiretti, al via l\u2019operazione solidariet\u00e0 di Pasqua con il sostegno della Camera di Commercio","datePublished":"2021-04-02T11:23:11+00:00","dateModified":"2021-04-02T13:00:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/"},"wordCount":342,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/picchi-acampora.jpg","keywords":["Camera di Commercio","carlo picchi","coldiretti","giovanni acampora","latina"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/","name":"Coldiretti, al via l\u2019operazione solidariet\u00e0 di Pasqua con il sostegno della Camera di Commercio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/picchi-acampora.jpg","datePublished":"2021-04-02T11:23:11+00:00","dateModified":"2021-04-02T13:00:52+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/picchi-acampora.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/picchi-acampora.jpg","width":654,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Coldiretti, al via l\u2019operazione solidariet\u00e0 di Pasqua con il sostegno della Camera di Commercio"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/02\/coldiretti-al-via-loperazione-solidarieta-di-pasqua-con-il-sostegno-della-camera-di-commercio\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/55801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=55801"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/55801\/revisions"}],"predecessor-version":[{"id":55809,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/55801\/revisions\/55809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/55807"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=55801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=55801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=55801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}