{"id":55708,"date":"2021-04-01T11:10:30","date_gmt":"2021-04-01T09:10:30","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=55708"},"modified":"2021-04-01T16:56:12","modified_gmt":"2021-04-01T14:56:12","slug":"frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/","title":{"rendered":"Frosinone punta sulla rigenerazione urbana: l&#8217;assise civica approva le delibere"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Il consiglio comunale di Frosinone ha approvato le due delibere sulla rigenerazione urbana,<\/strong> relative ai cambi di destinazione d\u2019uso e agli ampliamenti degli immobili attraverso il miglioramento sismico e l\u2019efficientamento energetico. Sar\u00e0 possibile presentare le domande per gli interventi gi\u00e0 dal prossimo mese di aprile (<a href=\"mailto:sue@comune.frosinone.it\" target=\"_blank\" rel=\"noreferrer noopener\">sue@comune.frosinone.it<\/a>).\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/consiglio-comunale-frosinone-mascherine-bis.jpg\" alt=\"\" class=\"wp-image-35540\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/consiglio-comunale-frosinone-mascherine-bis.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/consiglio-comunale-frosinone-mascherine-bis-300x225.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/consiglio-comunale-frosinone-mascherine-bis-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">La decisione<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le delibere in oggetto, illustrate in consiglio dal sindaco, Nicola Ottaviani, riguardano le &#8220;Disposizioni per la rigenerazione urbana&nbsp; e&nbsp; per il&nbsp; recupero edilizio. Disposizioni per il cambio di destinazione d&#8217;uso degli edifici ai sensi dell&#8217;art. 4\u201c e \u201cDisposizioni per il&nbsp; miglioramento sismico e l&#8217;efficientamento energetico degli edifici ai sensi dell&#8217;art. 5\u201d,&nbsp;per recepimento delle osservazioni da parte della Regione Lazio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I documenti fanno riferimento\u00a0alla rigenerazione urbana, che p<strong>ermetter\u00e0 i cambi di\u00a0destinazione\u00a0d&#8217;uso su quasi tutta la fascia urbana ed extraurbana del territorio comunale, consentendo alle famiglie e agli operatori privati di adeguare l&#8217;assetto urbanistico ed edilizio alle mutate esigenze economiche e sociali,<\/strong> che hanno caratterizzato l&#8217;evoluzione del contesto locale negli ultimi 40 anni. Grazie al medesimo strumento, si attiveranno le procedure per permettere l&#8217;aumento delle cubature e l&#8217;ampliamento delle superfici nell&#8217;ordine del 20%, in media, utilizzando criteri e canoni simili a quelli del Piano Casa, la cui possibilit\u00e0 \u00e8 venuta meno.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"692\" height=\"426\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/rigenerazione-urbana-frosinone.jpg\" alt=\"frosinone rigenerazione urbana il corriere della provincia\" class=\"wp-image-25617\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/rigenerazione-urbana-frosinone.jpg 692w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/rigenerazione-urbana-frosinone-300x185.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/rigenerazione-urbana-frosinone-500x308.jpg 500w\" sizes=\"auto, (max-width: 692px) 100vw, 692px\" \/><figcaption>Panorama Frosinone<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Le modalit\u00e0<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sono quindi consentiti interventi di ristrutturazione edilizia, compresa la demolizione e ricostruzione, di singoli edifici <\/strong>aventi una superficie lorda complessiva fino ad un massimo di 10.000 mq, con mutamento della destinazione d&#8217;uso tra le categorie funzionali individuate all&#8217;articolo 23 ter del d.p.r. 380\/2001 con esclusione di quella rurale. Tali edifici devono essere legittimamente realizzati o per i quali sia stato rilasciato il titolo abilitativo edilizio in sanatoria, ovvero intervenga l&#8217;attestazione di avvenuta formazione del silenzio assenso sulla richiesta di concessione edilizia in sanatoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gli interventi, sia relativamente all\u2019articolo 4, sia all\u2019articolo 5, sono consentiti nelle porzioni di territorio urbanizzate, classificate dalla Carta dell&#8217;uso del suolo come:<\/strong> insediamento residenziale e produttivo, zone estrattive, cantieri e discariche e aree verdi urbanizzate, nonch\u00e9 nella parte di territorio gi\u00e0 trasformata in attuazione delle previsioni degli strumenti urbanistici e nelle porzioni di territorio individuate come trasformabili dalle previsioni degli strumenti urbanistici vigenti, ivi incluse le aree per gli standard urbanistici ancorch\u00e9 non realizzati.\u00a0Gli interventi non possono prevedere l&#8217;apertura di medie e grandi strutture di vendita. La destinazione d&#8217;uso originaria \u00e8 quella risultante nel titolo abilitativo autorizzatorio dell&#8217;intervento edilizio. ln alternativa, si presume destinazione d&#8217;uso attuale ai fini del presente articolo quella risultante da atti pubblici ovvero da atti in possesso della pubblica amministrazione formati in data anteriore 1987. Gli interventi di modifica di destinazione d&#8217;uso in applicazione di queste norme determinano automaticamente la variazione della destinazione di zona dell&#8217;area di sedime e delle aree pertinenziali dell&#8217;edificio, nonch\u00e9 delle aree cedute per gli standard urbanistici, comprese quelle per la viabilit\u00e0 pubblica prevista dal progetto. Al riguardo, la nuova destinazione da attribuire al terreno interessato dal progetto, sar\u00e0 quella impressa dall&#8217;intervento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Al fine di incentivare gli interventi di miglioramento sismico e di efficientamento energetico degli edifici esistenti, inoltre, \u00e8 possibile realizzare interventi di ampliamento del 20% della volumetria<\/strong> o della superficie utile esistente degli edifici a destinazione residenziale, per un incremento massimo di 70 mq di superficie. Gli ampliamenti devono essere realizzati nel rispetto di quanto previsto dalla normativa statale e regionale in materia di sostenibilit\u00e0 energetico-ambientale e di bioedilizia e sono consentiti previa acquisizione di idoneo titolo abilitativo, anche con aumento delle unit\u00e0 immobiliari. Tali interventi si applicano agli edifici legittimi o legittimati per i quali sia stato rilasciato il titolo edilizio in sanatoria, anche se ricadenti nelle zone omogenee E. Gli interventi del presente articolo, nel caso prevedano un aumento del carico urbanistico derivante dall&#8217;incremento volumetrico degli immobili, devono prevedere la cessione all&#8217;amministrazione di aree per gli standard urbanistici.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il complesso programma di&nbsp;rigenerazione&nbsp;urbana e di recupero edilizio, predisposto dall&#8217;amministrazione Ottaviani interesser\u00e0, secondo le stime, circa 2\/3.000 immobili presenti all&#8217;interno del territorio comunale, con un introito potenziale di circa 10 milioni di euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il consiglio comunale di Frosinone ha approvato le due delibere sulla rigenerazione urbana, relative ai cambi di destinazione d\u2019uso e<\/p>\n","protected":false},"author":26,"featured_media":52081,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[4488,94,721,93,3067,639,3091],"class_list":["post-55708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-cambio-destinazione-duso","tag-ciociaria","tag-consiglio-comunale","tag-frosinone","tag-la-provincia-quotidiano","tag-nicola-ottaviani","tag-rigenerazione-urbana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone punta sulla rigenerazione urbana: l&#039;assise civica approva le delibere - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone punta sulla rigenerazione urbana: l&#039;assise civica approva le delibere\" \/>\n<meta property=\"og:description\" content=\"Il consiglio comunale di Frosinone ha approvato le due delibere sulla rigenerazione urbana, relative ai cambi di destinazione d\u2019uso e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-01T09:10:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-01T14:56:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/via-maria-edilizia-convenzionata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"890\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Frosinone punta sulla rigenerazione urbana: l&#8217;assise civica approva le delibere\",\"datePublished\":\"2021-04-01T09:10:30+00:00\",\"dateModified\":\"2021-04-01T14:56:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/\"},\"wordCount\":691,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/via-maria-edilizia-convenzionata.jpg\",\"keywords\":[\"cambio destinazione d'uso\",\"Ciociaria\",\"consiglio comunale\",\"Frosinone\",\"La provincia quotidiano\",\"nicola ottaviani\",\"rigenerazione urbana\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/\",\"name\":\"Frosinone punta sulla rigenerazione urbana: l'assise civica approva le delibere - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/via-maria-edilizia-convenzionata.jpg\",\"datePublished\":\"2021-04-01T09:10:30+00:00\",\"dateModified\":\"2021-04-01T14:56:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/via-maria-edilizia-convenzionata.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/via-maria-edilizia-convenzionata.jpg\",\"width\":890,\"height\":536,\"caption\":\"Cantiere via Maria a Frosinone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone punta sulla rigenerazione urbana: l&#8217;assise civica approva le delibere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/04\\\/01\\\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone punta sulla rigenerazione urbana: l'assise civica approva le delibere - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone punta sulla rigenerazione urbana: l'assise civica approva le delibere","og_description":"Il consiglio comunale di Frosinone ha approvato le due delibere sulla rigenerazione urbana, relative ai cambi di destinazione d\u2019uso e","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-04-01T09:10:30+00:00","article_modified_time":"2021-04-01T14:56:12+00:00","og_image":[{"width":890,"height":536,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/via-maria-edilizia-convenzionata.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Frosinone punta sulla rigenerazione urbana: l&#8217;assise civica approva le delibere","datePublished":"2021-04-01T09:10:30+00:00","dateModified":"2021-04-01T14:56:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/"},"wordCount":691,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/via-maria-edilizia-convenzionata.jpg","keywords":["cambio destinazione d'uso","Ciociaria","consiglio comunale","Frosinone","La provincia quotidiano","nicola ottaviani","rigenerazione urbana"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/","name":"Frosinone punta sulla rigenerazione urbana: l'assise civica approva le delibere - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/via-maria-edilizia-convenzionata.jpg","datePublished":"2021-04-01T09:10:30+00:00","dateModified":"2021-04-01T14:56:12+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/via-maria-edilizia-convenzionata.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/via-maria-edilizia-convenzionata.jpg","width":890,"height":536,"caption":"Cantiere via Maria a Frosinone"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone punta sulla rigenerazione urbana: l&#8217;assise civica approva le delibere"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/04\/01\/frosinone-punta-sulla-rigenerazione-urbana-lassise-civica-approva-le-delibere\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/55708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=55708"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/55708\/revisions"}],"predecessor-version":[{"id":55709,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/55708\/revisions\/55709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/52081"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=55708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=55708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=55708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}