{"id":55684,"date":"2021-03-31T19:41:42","date_gmt":"2021-03-31T17:41:42","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=55684"},"modified":"2021-03-31T20:00:24","modified_gmt":"2021-03-31T18:00:24","slug":"assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/","title":{"rendered":"Assunzioni in Regione, Buschini propone di affidare l&#8217;indagine a FdI: Righini chiede una commissione d&#8217;inchiesta"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Fare luce sulle oltre 20 assunzioni in Consiglio regionale del Lazio, <\/strong>pescando&#8217; dalle graduatorie di un concorso bandito dal Comune di Allumiere. La Pisana \u00e8 pronta a un&#8217;indagine interna sulla vicenda di cui hanno beneficiato persone vicine a consiglieri e ad alcuni partiti, in particolare Pd, M5S e Lega.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"729\" height=\"516\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/mauro-buschini-2.jpg\" alt=\"\" class=\"wp-image-50156\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/mauro-buschini-2.jpg 729w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/mauro-buschini-2-300x212.jpg 300w\" sizes=\"auto, (max-width: 729px) 100vw, 729px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il presidente dell&#8217;Assemblea del Lazio, Mauro Buschini, ha proposto di affidare il dossier alla Commissione regionale di Controllo contabile,<\/strong> guidata dall&#8217;esponente di Fratelli d&#8217;Italia, Giancarlo Righini. Il partito di Giorgia Meloni ha, per\u00f2, replicato chiedendo l&#8217;istituzione di una commissione di inchiesta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento del presidente<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;\u00c8 esigenza immediata mia e del mio ufficio di presidenza &#8211; ha affermato Buschini <\/strong> &#8211; che tutti abbiano piena consapevolezza di quello che correttamente l&#8217;Udp ha deliberato, le scelte che ha portato avanti e la procedura che \u00e8 stata seguita. Gia da oggi pomeriggio il Coreco pu\u00f2 avere la documentazione e mettersi al lavoro&#8221;. Tuttavia Fdi, unico partito a non aver dato il via libera a questa possibilit\u00e0, ancora deve sciogliere la riserva. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;I<strong>l consigliere Ghera &#8211; ha aggiunto Buschini &#8211;  ci ha chiesto tempo e il consigliere Righini ne fa una questione di competenze<\/strong> che possono essere chiarite. Ci\u00f2 che guida questa discussione \u00e8 l&#8217;esigenza di tutti, affinch\u00e8 su questa vicenda non vi siano ombre e dubbi sul lavoro che ha portato avanti l&#8217;Udp. Nella capigruppo di venerdi sceglieremo la strada e per me non c&#8217;\u00e8 problema&#8221;. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/giancarlo-righini-regione-lazio-1024x768.jpg\" alt=\"\" class=\"wp-image-857\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/giancarlo-righini-regione-lazio-1024x768.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/giancarlo-righini-regione-lazio-300x225.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/giancarlo-righini-regione-lazio-768x576.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/giancarlo-righini-regione-lazio-500x375.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/giancarlo-righini-regione-lazio.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Il consigliere regionale di Fratelli d&#8217;Italia Giancarlo Righini <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Il gruppo di Fratelli d\u2019Italia ha, invece, ribadito \u201cla sua ferma volont\u00e0 di richiedere le immediate dimissioni dell\u2019Ufficio di presidenza e<strong> l\u2019avvio di una commissione speciale di indagine <\/strong>che faccia luce sulla vicenda del concorso che ha portato all\u2019assunzione di personale nella Regione Lazio, attingendo dalla graduatoria del comune di Allumiere. Riteniamo doveroso  e necessario \u2013 ha evidenziato il gruppo del partito di Giorgia Meloni \u2013 capire, soprattutto per rispetto dei cittadini della nostra Regione, perch\u00e9 la maggior parte dei vincitori sono riconducibili proprio ai partiti rappresentati nell\u2019ufficio di presidenza\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le parole di Righini<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Sono sicuro  &#8211; ha aggiunto Giancarlo Righini<\/strong> &#8211; <strong>che il passaggio in aula a Palazzo Madama, grazie all\u2019interrogazione presentata dal senatore William De Vecchis (Lega), che va nella stessa direzione di quella di FdI alla Pisana, <\/strong>dar\u00e0 un&#8217;accelerazione significativa all\u2019iter per l\u2019approfondimento e la chiarificazione della vicenda del concorso &#8216;natalizio&#8217; e delle conseguenti assunzioni politiche in Regione Lazio\u201d. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fare luce sulle oltre 20 assunzioni in Consiglio regionale del Lazio, pescando&#8217; dalle graduatorie di un concorso bandito dal Comune<\/p>\n","protected":false},"author":26,"featured_media":25299,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[374,8417,1388,562],"class_list":["post-55684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-assunzioni","tag-giancarlo-righini","tag-mauro-buschini","tag-regione-lazio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Assunzioni in Regione, Buschini propone di affidare l&#039;indagine a FdI: Righini chiede una commissione d&#039;inchiesta - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assunzioni in Regione, Buschini propone di affidare l&#039;indagine a FdI: Righini chiede una commissione d&#039;inchiesta\" \/>\n<meta property=\"og:description\" content=\"Fare luce sulle oltre 20 assunzioni in Consiglio regionale del Lazio, pescando&#8217; dalle graduatorie di un concorso bandito dal Comune\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-31T17:41:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T18:00:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/consiglio-regione-lazio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"521\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Assunzioni in Regione, Buschini propone di affidare l&#8217;indagine a FdI: Righini chiede una commissione d&#8217;inchiesta\",\"datePublished\":\"2021-03-31T17:41:42+00:00\",\"dateModified\":\"2021-03-31T18:00:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/\"},\"wordCount\":421,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/consiglio-regione-lazio.jpg\",\"keywords\":[\"assunzioni\",\"Giancarlo Righini\",\"mauro buschini\",\"regione lazio\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/\",\"name\":\"Assunzioni in Regione, Buschini propone di affidare l'indagine a FdI: Righini chiede una commissione d'inchiesta - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/consiglio-regione-lazio.jpg\",\"datePublished\":\"2021-03-31T17:41:42+00:00\",\"dateModified\":\"2021-03-31T18:00:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/consiglio-regione-lazio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/consiglio-regione-lazio.jpg\",\"width\":980,\"height\":521},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assunzioni in Regione, Buschini propone di affidare l&#8217;indagine a FdI: Righini chiede una commissione d&#8217;inchiesta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/31\\\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Assunzioni in Regione, Buschini propone di affidare l'indagine a FdI: Righini chiede una commissione d'inchiesta - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/","og_locale":"it_IT","og_type":"article","og_title":"Assunzioni in Regione, Buschini propone di affidare l'indagine a FdI: Righini chiede una commissione d'inchiesta","og_description":"Fare luce sulle oltre 20 assunzioni in Consiglio regionale del Lazio, pescando&#8217; dalle graduatorie di un concorso bandito dal Comune","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-03-31T17:41:42+00:00","article_modified_time":"2021-03-31T18:00:24+00:00","og_image":[{"width":980,"height":521,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/consiglio-regione-lazio.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Assunzioni in Regione, Buschini propone di affidare l&#8217;indagine a FdI: Righini chiede una commissione d&#8217;inchiesta","datePublished":"2021-03-31T17:41:42+00:00","dateModified":"2021-03-31T18:00:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/"},"wordCount":421,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/consiglio-regione-lazio.jpg","keywords":["assunzioni","Giancarlo Righini","mauro buschini","regione lazio"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/","name":"Assunzioni in Regione, Buschini propone di affidare l'indagine a FdI: Righini chiede una commissione d'inchiesta - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/consiglio-regione-lazio.jpg","datePublished":"2021-03-31T17:41:42+00:00","dateModified":"2021-03-31T18:00:24+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/consiglio-regione-lazio.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/consiglio-regione-lazio.jpg","width":980,"height":521},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Assunzioni in Regione, Buschini propone di affidare l&#8217;indagine a FdI: Righini chiede una commissione d&#8217;inchiesta"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/31\/assunzioni-in-regione-buschini-propone-di-affidare-lindagine-a-fdi-righini-chiede-una-commissione-dinchiesta\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/55684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=55684"}],"version-history":[{"count":20,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/55684\/revisions"}],"predecessor-version":[{"id":55706,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/55684\/revisions\/55706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/25299"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=55684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=55684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=55684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}