{"id":54949,"date":"2021-03-16T16:27:08","date_gmt":"2021-03-16T15:27:08","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=54949"},"modified":"2021-03-16T16:30:50","modified_gmt":"2021-03-16T15:30:50","slug":"certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/","title":{"rendered":"Certosa di Trisulti, il circolo Pd esprime soddisfazione per la decisione del consiglio di Stato"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Il<\/strong> C<strong>ircolo di Frosinone del PD esprime soddisfazione per la decisione del Consiglio di Stato di restituire l&#8217;Abbazia di Trisulti alla comunit\u00e0 cittadina<\/strong>. Il PD \u00e8 stato uno dei primi promotori di iniziative per impedire di ridurre l&#8217;Abbazia in un centro di scuola internazionale di sovranisti sostenuta dal fascista statunitense Steve Bannon. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"626\" height=\"382\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/andrea-palladino-nuova.jpg\" alt=\"\" class=\"wp-image-50125\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/andrea-palladino-nuova.jpg 626w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/andrea-palladino-nuova-300x183.jpg 300w\" sizes=\"auto, (max-width: 626px) 100vw, 626px\" \/><figcaption>Il segretario del circolo Pd Andrea Palladino<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La grande mobilitazione di associazioni, di sindacati, di cittadini aveva suscitato sdegno per la speculazione messa in atto il presidente dell&#8217;associazione affidataria&nbsp;Dhi&nbsp;Benjamin Harwell<\/strong>, indagato dalla&nbsp;Procura di Roma&nbsp;per falso e turbativa d&#8217;asta e perch\u00e9 la sua societ\u00e0 fosse sprovvista dei requisiti richiesti dalla concessione. Lo stesso Bannon erastato arrestato per frodenegli Stati Uniti d&#8217;America.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Il ricorso presentato dal Ministero dei beni culturali e da molte associazioni del territorio della provincia di Frosinone, ha ottenuto successo e consentito di vincere una battaglia per la difesa dei beni culturali. Trisulti, come i tanti tesori artistici e architettonici del patrimonio pubblico della nostra provincia, come di tutta l&#8217;Italia, deve essere salvaguardato da speculazioni private e valorizzato come patrimonio di tutti e bene comune.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il PD porr\u00e0 grande attenzione per realizzare obiettivi volti a preservare e rendere fruibile il nostro patrimonio artistico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Circolo di Frosinone del PD esprime soddisfazione per la decisione del Consiglio di Stato di restituire l&#8217;Abbazia di Trisulti<\/p>\n","protected":false},"author":18,"featured_media":12326,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3434,94,8405,93],"class_list":["post-54949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-certosa-trisulti","tag-ciociaria","tag-circolo-pd","tag-frosinone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Certosa di Trisulti, il circolo Pd esprime soddisfazione per la decisione del consiglio di Stato - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Certosa di Trisulti, il circolo Pd esprime soddisfazione per la decisione del consiglio di Stato\" \/>\n<meta property=\"og:description\" content=\"Il Circolo di Frosinone del PD esprime soddisfazione per la decisione del Consiglio di Stato di restituire l&#8217;Abbazia di Trisulti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-16T15:27:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-16T15:30:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/certosa-trisulti-e1559317037160.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"369\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Certosa di Trisulti, il circolo Pd esprime soddisfazione per la decisione del consiglio di Stato\",\"datePublished\":\"2021-03-16T15:27:08+00:00\",\"dateModified\":\"2021-03-16T15:30:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/\"},\"wordCount\":224,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/certosa-trisulti-e1559317037160.jpg\",\"keywords\":[\"Certosa Trisulti\",\"Ciociaria\",\"circolo pd\",\"Frosinone\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/\",\"name\":\"Certosa di Trisulti, il circolo Pd esprime soddisfazione per la decisione del consiglio di Stato - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/certosa-trisulti-e1559317037160.jpg\",\"datePublished\":\"2021-03-16T15:27:08+00:00\",\"dateModified\":\"2021-03-16T15:30:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/certosa-trisulti-e1559317037160.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/certosa-trisulti-e1559317037160.jpg\",\"width\":632,\"height\":369,\"caption\":\"La Certosa di Trisulti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Certosa di Trisulti, il circolo Pd esprime soddisfazione per la decisione del consiglio di Stato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Certosa di Trisulti, il circolo Pd esprime soddisfazione per la decisione del consiglio di Stato - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/","og_locale":"it_IT","og_type":"article","og_title":"Certosa di Trisulti, il circolo Pd esprime soddisfazione per la decisione del consiglio di Stato","og_description":"Il Circolo di Frosinone del PD esprime soddisfazione per la decisione del Consiglio di Stato di restituire l&#8217;Abbazia di Trisulti","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2021-03-16T15:27:08+00:00","article_modified_time":"2021-03-16T15:30:50+00:00","og_image":[{"width":632,"height":369,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/certosa-trisulti-e1559317037160.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Certosa di Trisulti, il circolo Pd esprime soddisfazione per la decisione del consiglio di Stato","datePublished":"2021-03-16T15:27:08+00:00","dateModified":"2021-03-16T15:30:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/"},"wordCount":224,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/certosa-trisulti-e1559317037160.jpg","keywords":["Certosa Trisulti","Ciociaria","circolo pd","Frosinone"],"articleSection":["News"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/","name":"Certosa di Trisulti, il circolo Pd esprime soddisfazione per la decisione del consiglio di Stato - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/certosa-trisulti-e1559317037160.jpg","datePublished":"2021-03-16T15:27:08+00:00","dateModified":"2021-03-16T15:30:50+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/certosa-trisulti-e1559317037160.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/certosa-trisulti-e1559317037160.jpg","width":632,"height":369,"caption":"La Certosa di Trisulti"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Certosa di Trisulti, il circolo Pd esprime soddisfazione per la decisione del consiglio di Stato"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/certosa-di-trisulti-il-circolo-pd-esprime-soddisfazione-per-la-decisione-del-consiglio-di-stato\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=54949"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54949\/revisions"}],"predecessor-version":[{"id":54954,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54949\/revisions\/54954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/12326"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=54949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=54949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=54949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}