{"id":54944,"date":"2021-03-16T15:39:44","date_gmt":"2021-03-16T14:39:44","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=54944"},"modified":"2021-03-16T15:41:42","modified_gmt":"2021-03-16T14:41:42","slug":"rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/","title":{"rendered":"Rifiuti Lazio, arresti Tosini e Lozza: ecco cosa emerge dall&#8217;ordinanza"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;La direttrice dei rifiuti del Lazio, Flaminia Tosini, era totalmente asservita agli interessi dell\u2019imprenditore Valter Lozza, e ha governato \u201cillecitamente\u201d la gestione del ciclo regionale del pattume&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>E\u2019 quanto emerge dalle 104 pagine di ordinanza di custodia cautelare per i due firmata dalla gip Annalisa Marzano, su richiesta dei procuratori aggiunti di Roma, Paolo Aiello e Nunzia D\u2019Elia,<\/strong> che hanno aperto un\u2019indagine per corruzione, concussione, falso ideologico e turbata libert\u00e0 di procedimento di scelta del contraente fino ad arrivare agli arresti domiciliari effettuati stamattina dai Carabinieri del Noe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un&#8217;inchiesta che non riguarda solo la scelta della nuova discarica di Roma, nella ex cava di Monte Carnevale, ma anche l\u2019ampliamento delle discariche di Roccasecca e Civitavecchia,<\/strong> di propriet\u00e0 della Mad di Valter Lozza, e il capping della discarica di Bracciano.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;accusa<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cSi tratta di un meccanismo criminoso, ben collaudato, estremamente pericoloso e pregiudizievole<\/strong> sia per la corretta e trasparente individuazione di un sito idoneo alla destinazione dei rifiuti solidi urbani della Capitale, che nella complessiva gestione degli interessi inerenti la gestione delle attivit\u00e0 dedite allo smaltimento dei rifiuti e alla gestione delle discariche\u201d, si legge nel provvedimento della Gip, secondo la quale \u201cil quadro probatorio raccolto nel corso delle indagini svolte ha svelato con sconcerto che il ciclo integrato dei rifiuti urbani della Regione Lazio e illecitamente monitorato \u00e8 governato da Flaminia Tosini.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Regali in cambi di favori<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Costei nella qualit\u00e0 di direttore regionale della direzione Politiche Ambientali e ciclo dei rifiuti anzich\u00e9 destinare le proprie conoscenze tecniche e le proprie funzioni all\u2019interesse pubblico, e in particolare al bene pubblico per eccellenza quale quello della salubrit\u00e0 dell\u2019ambiente, destinava il proprio ufficio e l\u2019intero reparto dedicato al ciclo integrato dei rifiuti, nel quale si muoveva con straordinaria disinvoltura, agli interessi privati di Valter Lozza,  condividendone, per\u00f2, anche gli affari<br>Tosini aveva ricevuto da Lozza \u201c<strong>oggetti preziosi di consistente valore: borsa Prada, orologio, bracciale marca Cartier, orecchini\u201d.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tante le intecettazioni<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cLa mole di conversazioni captate nel corso delle indagini, dopo un faticoso ed estenuante tentativo di sorprendere la Tosini in dialoghi non criptati, ha permesso di svelare come costei si dedichi, anima e corpo, a tessere relazioni e a muovere pedine<\/strong> per favorire l\u2019attivit\u00e0 imprenditoriale del Lozza, agevolata dalla posizione apicale ricoperta all\u2019interno della Regione Lazio\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La complessiva indagine accusatoria ha \u201csvelato come il totale asservimento delle funzioni pubbliche dell\u2019indagata agli interessi privati del Lozza avesse come contraltare la promessa di una buona fetta dei vantaggi economici e finanziari conseguiti dall\u2019imprenditore grazie alla costante e progressiva espansione imprenditoriale; tale intendimento aveva riscontro immediato nelle periodiche e generose regalie di cui la dirigente ha ampiamente beneficiato\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cL\u2019intero dipartimento della Regione Lazio, cruciale per la salvaguardia dell\u2019interesse ambientale del territorio laziale, a causa delle condotte illecite poste in essere dalla sua dirigente, Flaminia Tosini, e\u2019 stato totalmente ripiegato sugli interessi privati di Valter Lozza\u201d, continua la gip Marzano nella ordinanza di custodia cautelare.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Secondo Il Gip, la Tosini \u201cpur ricoprendo un incarico piuttosto delicato, con una straordinaria astuzia e inconsueta disinvoltura, ha manipolato la procedura amministrativa<\/strong> volta alla individuazione della prossima discarica di rifiuti solidi urbani della Capitale e lo faceva ricorrendo ad indebite scorciatoie\u201d. Non solo. \u201cNon contenta, orientava le determinazioni regionali \u2013 in tema di rifiuti \u2013 agli interessi dell\u2019amico imprenditore che gestiva anche le discariche di Civitavecchia e Roccasecca: nel primo caso assicurando a Lozza l\u2019ampliamento della discarica per rifiuti non pericolosi di Civitavecchia e nel secondo caso riuscendo a manipolare le determinazioni di altri organi dello Stato (la Presidenza del Consiglio dei ministri) assicurando a Lozza la conferma dell\u2019innalzamento della quota della discarica di Roccasecca (a mt 16,70 come stabiliti originariamente dalla Regione Lazio)\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Per la gip \u201cgli innumerevoli servigi resi a Lozza, in dispregio di ogni minima regola di trasparenza e imparzialit\u00e0 della Pubblica amministrazione<\/strong>, hanno descritto una donna totalmente indifferente ai risvolti pericolosi delle sue illecite determinazioni, ma hanno anche delineato lo spregevole tratto affaristico che ha governato e orientato gli indebiti comportamenti del funzionario pubblico\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tutto ci\u00f2 \u201canche grazie all\u2019astuzia e alla scaltrezza di Lozza, il quale, consapevole della carica apicale e strategica della Tosini, ne approfittava per un verso consolidandone la relazione affettiva mediante l\u2019astuto ricorso a regali dall\u2019ingente valore economico e su altro versante rassicurandola sulla condivisione dei profitti conseguiti\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E ancora: \u201cI contatti e le aderenze che Flaminia Tosini e Valter Lozza possiedono, ciascuno nel settore di competenza, connotano di concretezza e attualit\u00e0 il pericolo che il protrarsi di illecite condotte possa sfociare in determinazioni amministrative ancor pi\u00f9 pericolose per la collettivit\u00e0 (ad esempio destinando il sito di Monte Carnevale a discarica di Rsu della Capitale), cos\u00ec come il permanere della Tosini nell\u2019ufficio pubblico da costei diretto sarebbe certamente foriero di indebite pressioni, di pregiudizievoli manipolazioni, di illecite determinazioni\u201d.&nbsp;<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>&#8220;La direttrice dei rifiuti del Lazio, Flaminia Tosini, era totalmente asservita agli interessi dell\u2019imprenditore Valter Lozza, e ha governato \u201cillecitamente\u201d<\/p>\n","protected":false},"author":18,"featured_media":54945,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[3285,12672,12671,12673],"class_list":["post-54944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-arresti-domiciliari","tag-lozza","tag-rifiuti-lazio","tag-tosini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rifiuti Lazio, arresti Tosini e Lozza: ecco cosa emerge dall&#039;ordinanza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rifiuti Lazio, arresti Tosini e Lozza: ecco cosa emerge dall&#039;ordinanza\" \/>\n<meta property=\"og:description\" content=\"&#8220;La direttrice dei rifiuti del Lazio, Flaminia Tosini, era totalmente asservita agli interessi dell\u2019imprenditore Valter Lozza, e ha governato \u201cillecitamente\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-16T14:39:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-16T14:41:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/carabinieri-noe-860x450-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"860\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Rifiuti Lazio, arresti Tosini e Lozza: ecco cosa emerge dall&#8217;ordinanza\",\"datePublished\":\"2021-03-16T14:39:44+00:00\",\"dateModified\":\"2021-03-16T14:41:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/\"},\"wordCount\":812,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/carabinieri-noe-860x450-1.jpg\",\"keywords\":[\"arresti domiciliari\",\"lozza\",\"rifiuti lazio\",\"tosini\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/\",\"name\":\"Rifiuti Lazio, arresti Tosini e Lozza: ecco cosa emerge dall'ordinanza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/carabinieri-noe-860x450-1.jpg\",\"datePublished\":\"2021-03-16T14:39:44+00:00\",\"dateModified\":\"2021-03-16T14:41:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/carabinieri-noe-860x450-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/carabinieri-noe-860x450-1.jpg\",\"width\":860,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rifiuti Lazio, arresti Tosini e Lozza: ecco cosa emerge dall&#8217;ordinanza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/16\\\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rifiuti Lazio, arresti Tosini e Lozza: ecco cosa emerge dall'ordinanza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/","og_locale":"it_IT","og_type":"article","og_title":"Rifiuti Lazio, arresti Tosini e Lozza: ecco cosa emerge dall'ordinanza","og_description":"&#8220;La direttrice dei rifiuti del Lazio, Flaminia Tosini, era totalmente asservita agli interessi dell\u2019imprenditore Valter Lozza, e ha governato \u201cillecitamente\u201d","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2021-03-16T14:39:44+00:00","article_modified_time":"2021-03-16T14:41:42+00:00","og_image":[{"width":860,"height":450,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/carabinieri-noe-860x450-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Rifiuti Lazio, arresti Tosini e Lozza: ecco cosa emerge dall&#8217;ordinanza","datePublished":"2021-03-16T14:39:44+00:00","dateModified":"2021-03-16T14:41:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/"},"wordCount":812,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/carabinieri-noe-860x450-1.jpg","keywords":["arresti domiciliari","lozza","rifiuti lazio","tosini"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/","name":"Rifiuti Lazio, arresti Tosini e Lozza: ecco cosa emerge dall'ordinanza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/carabinieri-noe-860x450-1.jpg","datePublished":"2021-03-16T14:39:44+00:00","dateModified":"2021-03-16T14:41:42+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/carabinieri-noe-860x450-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/carabinieri-noe-860x450-1.jpg","width":860,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Rifiuti Lazio, arresti Tosini e Lozza: ecco cosa emerge dall&#8217;ordinanza"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/16\/rifiuti-lazio-arresti-tosini-e-lozza-ecco-cosa-emerge-dallordinanza\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=54944"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54944\/revisions"}],"predecessor-version":[{"id":54947,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54944\/revisions\/54947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/54945"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=54944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=54944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=54944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}