{"id":54637,"date":"2021-03-11T15:57:47","date_gmt":"2021-03-11T14:57:47","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=54637"},"modified":"2021-03-11T16:07:43","modified_gmt":"2021-03-11T15:07:43","slug":"gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/","title":{"rendered":"Gioia segretario della Cgil Frosinone-Latina: gli auguri della politica"},"content":{"rendered":"\n<p><strong>Giovanni Gioia \u00e8 il nuovo segretario della Cgil Frosinone-Latina<\/strong> dopo Anselmo Briganti. A lui giungono gli auguri del mondo politico, a cominciare dal <strong>presidente del Consiglio regionale del Lazio, Mauro Buschini.<\/strong><\/p>\n<h3>L&#8217;intervento di Buschini<\/h3>\n<p>&#8220;Rivolgo le mie congratulazioni e i migliori auguri di buon lavoro a Giovanni Gioia, nuovo segretario generale Cgil delle province di Frosinone e Latina. Sono fermamente convinto \u2013 <strong>spiega Buschini<\/strong> &#8211; che l\u2019esperienza e la capacit\u00e0 del nuovo segretario risulteranno molto importanti per il lavoro comune che faremo&#8221;.<\/p>\n<p>&#8220;\u00c8 necessario unire le forze, e rinnovo l\u2019assoluta disponibilit\u00e0 del Consiglio regionale, per superare la pandemia e costruire le basi per la ripartenza dei territori. Grazie al segretario uscente Anselmo Briganti, sono stati anni di grande collaborazione e di lavoro proficuo&#8221;.<\/p>\n<h3>Pompeo: funzione sindacati fondamentale in emergenza<\/h3>\n<p>A Gioia arrivano anche gli auguri del presidente della Provincia, Antonio Pompeo: &#8220;Le mie congratulazioni per la nomina e gli auguri di buon lavoro al nuovo segretario della Cgil Frosinone-Latina, Giovanni Gioia. I<strong>n un momento drammatico per tutto il Paese e di profonda difficolt\u00e0 soprattutto per il mondo del lavoro<\/strong>, dice Pompeo &#8211; il ruolo delle organizzazioni sindacali riveste un&#8217;importanza ancora pi\u00f9 delicata per la tutela dei livelli occupazionali. La Provincia, come sempre fatto negli anni passati, conferma la piena collaborazione e disponibilit\u00e0 nell\u2019esclusivo interesse dei lavoratori del territorio&#8221;.<\/p>\n<p>&#8220;<strong>Voglio anche ringraziare il segretario uscente, Anselmo Briganti,<\/strong> &#8211; conclude Pompeo &#8211; per l&#8217;ottimo lavoro svolto nel suo ruolo e per il rapporto di continua interazione con l&#8217;Ente che mi onoro di presiedere. \u00c8 dovere inderogabile di tutte le istituzioni proseguire nell&#8217;impegno per la difesa dei posti di lavoro e rafforzare una concreta e tangibile azione di rilancio e sviluppo dell&#8217;intera provincia di Frosinone&#8221;.<\/p>\n<h3>Il messaggio di Luca Fantini<\/h3>\n<p>Congratulazioni a Giovanni Gioia anche dal<strong> segretario del Partito Democratico di Frosinone, Luca Fantini.<\/strong> &#8220;\u00c8 un momento di straordinaria difficolt\u00e0- spiega -, soprattutto per tanti cittadini che vedono sempre meno certezze per il loro futuro. Il Partito democratico di Frosinone \u00e8 a disposizione per un percorso comune al fianco dei lavoratori e dei cittadini provati dalla pandemia&#8221;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Giovanni Gioia \u00e8 il nuovo segretario della Cgil Frosinone-Latina: a lui arrivano gli auguri della politica <\/p>\n","protected":false},"author":18,"featured_media":54638,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,17],"tags":[842,869,94,12649,3880,1388,1191,866],"class_list":["post-54637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-lavoro","tag-antonio-pompeo","tag-cgil","tag-ciociaria","tag-giovanni-gioia","tag-luca-fantini","tag-mauro-buschini","tag-partito-democratico","tag-segretario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gioia segretario della Cgil Frosinone-Latina: gli auguri della politica - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gioia segretario della Cgil Frosinone-Latina: gli auguri della politica\" \/>\n<meta property=\"og:description\" content=\"Giovanni Gioia \u00e8 il nuovo segretario della Cgil Frosinone-Latina: a lui arrivano gli auguri della politica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-11T14:57:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-11T15:07:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/giovanni-gioia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Gioia segretario della Cgil Frosinone-Latina: gli auguri della politica\",\"datePublished\":\"2021-03-11T14:57:47+00:00\",\"dateModified\":\"2021-03-11T15:07:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/\"},\"wordCount\":357,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/giovanni-gioia.jpg\",\"keywords\":[\"antonio pompeo\",\"Cgil\",\"Ciociaria\",\"giovanni gioia\",\"Luca Fantini\",\"mauro buschini\",\"partito democratico\",\"Segretario\"],\"articleSection\":[\"Evidenza\",\"Lavoro\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/\",\"name\":\"Gioia segretario della Cgil Frosinone-Latina: gli auguri della politica - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/giovanni-gioia.jpg\",\"datePublished\":\"2021-03-11T14:57:47+00:00\",\"dateModified\":\"2021-03-11T15:07:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/giovanni-gioia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/giovanni-gioia.jpg\",\"width\":600,\"height\":450,\"caption\":\"Il nuovo segretario della Cgil Latina Frosinone Giovanni Gioia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gioia segretario della Cgil Frosinone-Latina: gli auguri della politica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/11\\\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gioia segretario della Cgil Frosinone-Latina: gli auguri della politica - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/","og_locale":"it_IT","og_type":"article","og_title":"Gioia segretario della Cgil Frosinone-Latina: gli auguri della politica","og_description":"Giovanni Gioia \u00e8 il nuovo segretario della Cgil Frosinone-Latina: a lui arrivano gli auguri della politica","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2021-03-11T14:57:47+00:00","article_modified_time":"2021-03-11T15:07:43+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/giovanni-gioia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Gioia segretario della Cgil Frosinone-Latina: gli auguri della politica","datePublished":"2021-03-11T14:57:47+00:00","dateModified":"2021-03-11T15:07:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/"},"wordCount":357,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/giovanni-gioia.jpg","keywords":["antonio pompeo","Cgil","Ciociaria","giovanni gioia","Luca Fantini","mauro buschini","partito democratico","Segretario"],"articleSection":["Evidenza","Lavoro"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/","name":"Gioia segretario della Cgil Frosinone-Latina: gli auguri della politica - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/giovanni-gioia.jpg","datePublished":"2021-03-11T14:57:47+00:00","dateModified":"2021-03-11T15:07:43+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/giovanni-gioia.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/giovanni-gioia.jpg","width":600,"height":450,"caption":"Il nuovo segretario della Cgil Latina Frosinone Giovanni Gioia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Gioia segretario della Cgil Frosinone-Latina: gli auguri della politica"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/11\/gioia-segretario-della-cgil-frosinone-latina-gli-auguri-della-politica\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=54637"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54637\/revisions"}],"predecessor-version":[{"id":54640,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54637\/revisions\/54640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/54638"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=54637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=54637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=54637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}