{"id":54413,"date":"2021-03-07T13:05:52","date_gmt":"2021-03-07T12:05:52","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=54413"},"modified":"2021-03-07T15:12:58","modified_gmt":"2021-03-07T14:12:58","slug":"vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/","title":{"rendered":"Vaccino, l&#8217;appello della Asl per evitare assembramenti. Sospese le prenotazioni per 64enni e 65enni"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Per permettere agli operatori sanitari di svolgere al meglio le attivit\u00e0 di somministrazione<\/strong> del vaccino, la Asl&nbsp; invita&nbsp; cittadini a seguire tutte le le regole e le indicazioni comunicate in fase di prenotazione.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le modalit\u00e0 <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prima tra tutte, il rispetto dell&#8217;orario di prenotazione<\/strong>:&nbsp; \u00e8 molto importante presentarsi presso il centro vaccinale all&#8217;ora puntuale prevista e non in anticipo. Questo per evitare lunghe file e assembramenti nei corridoi, con conseguenti problemi di gestione di accompagnatori e pazienti, come accaduto ad esempio oggi presso il Centro vaccinale di Ceccano.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>&#8220;<strong>Abbiamo avuto qualche problema &#8211; evidenzia la Asl &#8211; e ce ne scusiamo,<\/strong> ma invitiamo al tempo stesso tutti a rispettare i protocolli e le regole previste&#8221;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La comunicazione<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">&#8221; Sono temporaneamente sospese le prenotazioni online  &#8211; si legge nel sito di Salute Lazio- per gli anni 65 e 64 ovvero i nati nel 1956 e 1957, poich\u00e9 \u00e8 imminente la nuova circolare del Ministero della Salute che dovrebbe ampliare la fascia di et\u00e0 per la somministrazione del vaccino Astrazeneca&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Da fonti ufficiali abbiamo appreso che nelle prossime ore sar\u00e0 emanata la nuova circolare e per questo motivo si \u00e8 deciso di sospendere provvisoriamente le prenotazioni affinch\u00e9 vi sia un pieno allineamento con le indicazioni nazionali. I nati negli anni 1956 e 1957 possono comunque continuare a richiedere la vaccinazione presso i propri medici di medicina generale in attesa delle nuove disposizioni&#8221;. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per permettere agli operatori sanitari di svolgere al meglio le attivit\u00e0 di somministrazione del vaccino, la Asl&nbsp; invita&nbsp; cittadini a<\/p>\n","protected":false},"author":18,"featured_media":50698,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,11],"tags":[958,9030,94,8337,8916,9328,8936],"class_list":["post-54413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-salute","tag-asl-frosinone","tag-assembramenti","tag-ciociaria","tag-coronavirus","tag-covid","tag-vaccino","tag-zona-rossa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vaccino, l&#039;appello della Asl per evitare assembramenti. Sospese le prenotazioni per 64enni e 65enni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vaccino, l&#039;appello della Asl per evitare assembramenti. Sospese le prenotazioni per 64enni e 65enni\" \/>\n<meta property=\"og:description\" content=\"Per permettere agli operatori sanitari di svolgere al meglio le attivit\u00e0 di somministrazione del vaccino, la Asl&nbsp; invita&nbsp; cittadini a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-07T12:05:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-07T14:12:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/vaccino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1022\" \/>\n\t<meta property=\"og:image:height\" content=\"537\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Vaccino, l&#8217;appello della Asl per evitare assembramenti. Sospese le prenotazioni per 64enni e 65enni\",\"datePublished\":\"2021-03-07T12:05:52+00:00\",\"dateModified\":\"2021-03-07T14:12:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/\"},\"wordCount\":241,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/vaccino.jpg\",\"keywords\":[\"Asl Frosinone\",\"assembramenti\",\"Ciociaria\",\"coronavirus\",\"covid\",\"vaccino\",\"zona rossa\"],\"articleSection\":[\"*SLIDE*\",\"Salute e Benessere\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/\",\"name\":\"Vaccino, l'appello della Asl per evitare assembramenti. Sospese le prenotazioni per 64enni e 65enni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/vaccino.jpg\",\"datePublished\":\"2021-03-07T12:05:52+00:00\",\"dateModified\":\"2021-03-07T14:12:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/vaccino.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/vaccino.jpg\",\"width\":1022,\"height\":537,\"caption\":\"vaccino anti covid\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vaccino, l&#8217;appello della Asl per evitare assembramenti. Sospese le prenotazioni per 64enni e 65enni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/07\\\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vaccino, l'appello della Asl per evitare assembramenti. Sospese le prenotazioni per 64enni e 65enni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/","og_locale":"it_IT","og_type":"article","og_title":"Vaccino, l'appello della Asl per evitare assembramenti. Sospese le prenotazioni per 64enni e 65enni","og_description":"Per permettere agli operatori sanitari di svolgere al meglio le attivit\u00e0 di somministrazione del vaccino, la Asl&nbsp; invita&nbsp; cittadini a","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2021-03-07T12:05:52+00:00","article_modified_time":"2021-03-07T14:12:58+00:00","og_image":[{"width":1022,"height":537,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/vaccino.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Vaccino, l&#8217;appello della Asl per evitare assembramenti. Sospese le prenotazioni per 64enni e 65enni","datePublished":"2021-03-07T12:05:52+00:00","dateModified":"2021-03-07T14:12:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/"},"wordCount":241,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/vaccino.jpg","keywords":["Asl Frosinone","assembramenti","Ciociaria","coronavirus","covid","vaccino","zona rossa"],"articleSection":["*SLIDE*","Salute e Benessere"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/","name":"Vaccino, l'appello della Asl per evitare assembramenti. Sospese le prenotazioni per 64enni e 65enni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/vaccino.jpg","datePublished":"2021-03-07T12:05:52+00:00","dateModified":"2021-03-07T14:12:58+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/vaccino.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/vaccino.jpg","width":1022,"height":537,"caption":"vaccino anti covid"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Vaccino, l&#8217;appello della Asl per evitare assembramenti. Sospese le prenotazioni per 64enni e 65enni"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/07\/vaccino-lappello-della-asl-per-evitare-assembramenti-sospese-le-prenotazioni-per-64enni-e-65enni\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=54413"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54413\/revisions"}],"predecessor-version":[{"id":54423,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54413\/revisions\/54423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/50698"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=54413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=54413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=54413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}