{"id":54030,"date":"2021-03-01T18:13:48","date_gmt":"2021-03-01T17:13:48","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=54030"},"modified":"2021-03-02T16:34:12","modified_gmt":"2021-03-02T15:34:12","slug":"varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/","title":{"rendered":"Varianti inglese e brasiliana del Covid: la Asl propone la chiusura delle scuole in 31 comuni"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Una nota a firma del <strong>responsabile della U.O.C. di Igiene e Sanit\u00e0 pubblica, dottor Giuseppe Di Luzio<\/strong>, in cui si propone a <strong>30 sindaci del territorio provinciale<\/strong> di chiudere le scuole di ogni ordine e grado <strong>fino al prossimo 14 marzo.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">I sindaci destinatari della nota<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La nota fa seguito all\u2019ordinanza Z00006 del 28 febbraio 2021 della Regione Lazio che fa riferimento all\u2019incidenza dei casi: in molti comuni della provincia di Frosinone oltre i 250 casi per centomila abitanti. Per questo, \u201cai fini della tutela della salute pubblica\u201d la Asl propone la chiusura di tutte le scuole nei comuni di<strong> Alatri, Arce, Amaseno, Boville Ernica, Broccostella, Campoli Appennino, Castelliri, Castelnuovo Parano, Ceccano,\u00a0 Collepardo, Coreno Ausonio, Esperia, Ferentino, Fontechiari, Frosinone, Guarcino, Giuliano Di Roma, Isola del Liri, Monte San Giovanni Campano, Pescosolido, Piedimonte San Germano, Ripi, San Giovanni Incarico, Sant\u2019Andrea del Garigliano, Sora, Strangolagalli, Torrice, Vallecorsa, Veroli, Vicalvi, Villa Santa Lucia.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nella stessa nota, infine, si legge &#8220;fatta salva la possibilit\u00e0 di ricorrere alla didattica a distanza&#8221;, lasciando ai singoli sindaci, di concerto con i dirigenti scolastici, la scelta della modalit\u00e0 da adottare ed eventuali ulteriori azioni necessarie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asl di Frosinone ha proposto a 30 sindaci del territorio di chiudere tutte le scuole per le varianti del Covid<\/p>\n","protected":false},"author":18,"featured_media":4170,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,11,38],"tags":[108,1542,94,8803,93,5928,287,129,12578],"class_list":["post-54030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-salute","category-scuola","tag-asl","tag-chiusura","tag-ciociaria","tag-covid-19-2","tag-frosinone","tag-igiene","tag-ordinanza","tag-scuole","tag-varianti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Varianti inglese e brasiliana del Covid: la Asl propone la chiusura delle scuole in 31 comuni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Varianti inglese e brasiliana del Covid: la Asl propone la chiusura delle scuole in 31 comuni\" \/>\n<meta property=\"og:description\" content=\"La Asl di Frosinone ha proposto a 30 sindaci del territorio di chiudere tutte le scuole per le varianti del Covid\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-01T17:13:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-02T15:34:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/asl-frosinone-e1546529690981.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Varianti inglese e brasiliana del Covid: la Asl propone la chiusura delle scuole in 31 comuni\",\"datePublished\":\"2021-03-01T17:13:48+00:00\",\"dateModified\":\"2021-03-02T15:34:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/\"},\"wordCount\":202,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/asl-frosinone-e1546529690981.jpg\",\"keywords\":[\"Asl\",\"chiusura\",\"Ciociaria\",\"covid-19\",\"Frosinone\",\"igiene\",\"ordinanza\",\"scuole\",\"varianti\"],\"articleSection\":[\"*SLIDE*\",\"Salute e Benessere\",\"Scuola\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/\",\"name\":\"Varianti inglese e brasiliana del Covid: la Asl propone la chiusura delle scuole in 31 comuni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/asl-frosinone-e1546529690981.jpg\",\"datePublished\":\"2021-03-01T17:13:48+00:00\",\"dateModified\":\"2021-03-02T15:34:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/asl-frosinone-e1546529690981.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/asl-frosinone-e1546529690981.jpg\",\"width\":632,\"height\":421,\"caption\":\"Asl di Frosinone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Varianti inglese e brasiliana del Covid: la Asl propone la chiusura delle scuole in 31 comuni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/03\\\/01\\\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Varianti inglese e brasiliana del Covid: la Asl propone la chiusura delle scuole in 31 comuni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/","og_locale":"it_IT","og_type":"article","og_title":"Varianti inglese e brasiliana del Covid: la Asl propone la chiusura delle scuole in 31 comuni","og_description":"La Asl di Frosinone ha proposto a 30 sindaci del territorio di chiudere tutte le scuole per le varianti del Covid","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2021-03-01T17:13:48+00:00","article_modified_time":"2021-03-02T15:34:12+00:00","og_image":[{"width":632,"height":421,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/asl-frosinone-e1546529690981.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Varianti inglese e brasiliana del Covid: la Asl propone la chiusura delle scuole in 31 comuni","datePublished":"2021-03-01T17:13:48+00:00","dateModified":"2021-03-02T15:34:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/"},"wordCount":202,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/asl-frosinone-e1546529690981.jpg","keywords":["Asl","chiusura","Ciociaria","covid-19","Frosinone","igiene","ordinanza","scuole","varianti"],"articleSection":["*SLIDE*","Salute e Benessere","Scuola"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/","name":"Varianti inglese e brasiliana del Covid: la Asl propone la chiusura delle scuole in 31 comuni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/asl-frosinone-e1546529690981.jpg","datePublished":"2021-03-01T17:13:48+00:00","dateModified":"2021-03-02T15:34:12+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/asl-frosinone-e1546529690981.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/asl-frosinone-e1546529690981.jpg","width":632,"height":421,"caption":"Asl di Frosinone"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Varianti inglese e brasiliana del Covid: la Asl propone la chiusura delle scuole in 31 comuni"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/03\/01\/varianti-inglese-e-brasiliana-del-covid-la-asl-propone-la-chiusura-delle-scuole-in-31-comuni\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=54030"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54030\/revisions"}],"predecessor-version":[{"id":54034,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/54030\/revisions\/54034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/4170"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=54030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=54030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=54030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}