{"id":53845,"date":"2021-02-27T14:19:27","date_gmt":"2021-02-27T13:19:27","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=53845"},"modified":"2021-02-28T12:18:47","modified_gmt":"2021-02-28T11:18:47","slug":"progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/","title":{"rendered":"Progetti Por, Anbi Lazio: sfida vinta grazie alla Regione"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br><strong>\u201cCome sistema Anbi Lazio abbiamo dimostrato sinergia, coesione e pragmatismo\u201d. Questo il commento di Sonia Ricci, presidente di Anbi Lazio<\/strong> e commissario dei Consorzi della<br>provincia di Latina &#8211; dopo la conferenza stampa di ieri durante la quale, in Regione , sono stati presentati 26 progetti di coefficientamento energetico dei Consorzi di bonifica del Lazio, finanziati con oltre 5 milioni di euro del POR FESR (azione 4.1.1), nell\u2019ambito del programma Lazio Green. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Gli interventi<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<strong>Per la prima volta i Consorzi di Bonifica possono accedere a queste risorse \u2013 ha aggiunto la Presidente di Anbi Lazio <\/strong>\u2013 si tratta di un importante risultato che potr\u00e0 essere un punto di partenza per poter in futuro cogliere simili opportunit\u00e0&#8221;. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">I presenti<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alla conferenza hanno preso parte,  le proprie attivit\u00e0<\/strong>, i Presidenti e i Commissari dei Consorzi, Niccol\u00f2 Sacchetti, Gianluca Pezzotti, Stefania Ruffo. Con loro l\u2019assessore Agricoltura, Promozione della Filiera e della Cultura del Cibo, Ambiente e Risorse Naturali della Regione Lazio, Enrica Onorati, con il proprio direttore Mauro Lasagna, ed il presidente Anci Lazio, Riccardo Varone. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Presenti anche tutti i direttori delle strutture consortili con il direttore di Anbi Lazio, Andrea Renna che commenta \u201cDobbiamo ringraziare la Regione Lazio, in particolare il Capo di Gabinetto Albino Ruberti<\/strong>, per la sfida che ha voluto lanciare un anno fa su questo tema\u201d. Fu infatti proprio Ruberti \u2013 che convoc\u00f2 una apposita riunione per prospettare l\u2019opportunit\u00e0 di utilizzare i finanziamenti del Fondo Europeo di Sviluppo Regionale per sostenere le attivit\u00e0 dei Consorzi di Bonifica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> \u201c<strong>Una sfida che grazie a tutti i<br>colleghi ed i nostri ingegneri e tecnici abbiamo dimostrato di saper vincere ha aggiunto Renna <\/strong>ringraziando Ruberti ma anche la struttura dell\u2019assessore Onorati e di Lazio Innova. Gli interventi sono a tutela dell\u2019ambiente: la riduzione dei consumi energetici, l\u2019incremento della capacit\u00e0 di autoproduzione di energia da fonte rinnovabile, l\u2019installazione di impianti di<br>cogenerazione e trigenerazione ad alto rendimento, l\u2019implementazione di sistemi di<br>monitoraggio e di gestione energetica, la realizzazione di reti di teleriscaldamento e<br>teleraffrescamento per la distribuzione di energia all\u2019interno dei comprensori interessati.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cuore di ognuno dei progetti, finanziati con i soldi messi a disposizione dall\u2019Europa, sono i principi alla base dell\u2019efficientamento energetico,<\/strong> ovvero interventi che permettono di ridurre i livelli dei consumi e di tagliare gli sprechi, ottimizzando l\u2019uso delle fonti di approvvigionamento e l\u2019impiego dell\u2019energia.Anbi Lazio ha ricevuto testimonianza di come sia cambiato il modo di porsi e lavorare da Onorati, Varone e Lasagna. E\u2019 cambiato il passo, la sinergia si \u00e8 tradotta in fatti e non parole. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Noi dobbiamo essere una parte attiva con le Istituzioni in primis con la Regione Lazio \u2013 hanno concluso Ricci e Renna<\/strong> \u2013 perch\u00e9 la salvaguardia idrogeologica del territorio riguarda tutti noi cos\u00ec come la garanzia dell\u2019irrigazione per le produzioni agricole che permettono di salvaguardare imprese e reddito garantendo qualit\u00e0 e rintracciabilit\u00e0. Il clima \u00e8 cambiato con questo anche il nostro modo di comunicare, raccontare cosa facciamo, far comprendere che oggi pi\u00f9 di prima occorre un Patto per il Suolo non come slogan ma come esempio virtuoso di fare sistema per difendere territorio e ambiente&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cCome sistema Anbi Lazio abbiamo dimostrato sinergia, coesione e pragmatismo\u201d. Questo il commento di Sonia Ricci, presidente di Anbi Lazio<\/p>\n","protected":false},"author":18,"featured_media":42361,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[6279,5603,5234,537,93,513,562,10155],"class_list":["post-53845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-albino-ruberti","tag-ambi-lazio","tag-andrea-renna","tag-bonifica","tag-frosinone","tag-latina","tag-regione-lazio","tag-sonia-ricci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Progetti Por, Anbi Lazio: sfida vinta grazie alla Regione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Progetti Por, Anbi Lazio: sfida vinta grazie alla Regione\" \/>\n<meta property=\"og:description\" content=\"\u201cCome sistema Anbi Lazio abbiamo dimostrato sinergia, coesione e pragmatismo\u201d. Questo il commento di Sonia Ricci, presidente di Anbi Lazio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-27T13:19:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-28T11:18:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/ricci-renna.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"759\" \/>\n\t<meta property=\"og:image:height\" content=\"519\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Progetti Por, Anbi Lazio: sfida vinta grazie alla Regione\",\"datePublished\":\"2021-02-27T13:19:27+00:00\",\"dateModified\":\"2021-02-28T11:18:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/\"},\"wordCount\":519,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/ricci-renna.jpg\",\"keywords\":[\"albino ruberti\",\"ambi lazio\",\"andrea renna\",\"bonifica\",\"Frosinone\",\"latina\",\"regione lazio\",\"sonia ricci\"],\"articleSection\":[\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/\",\"name\":\"Progetti Por, Anbi Lazio: sfida vinta grazie alla Regione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/ricci-renna.jpg\",\"datePublished\":\"2021-02-27T13:19:27+00:00\",\"dateModified\":\"2021-02-28T11:18:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/ricci-renna.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/ricci-renna.jpg\",\"width\":759,\"height\":519,\"caption\":\"La presidente di Anbi Lazio Sonia Ricci e il direttore Andrea Renna\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti Por, Anbi Lazio: sfida vinta grazie alla Regione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/27\\\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Progetti Por, Anbi Lazio: sfida vinta grazie alla Regione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/","og_locale":"it_IT","og_type":"article","og_title":"Progetti Por, Anbi Lazio: sfida vinta grazie alla Regione","og_description":"\u201cCome sistema Anbi Lazio abbiamo dimostrato sinergia, coesione e pragmatismo\u201d. Questo il commento di Sonia Ricci, presidente di Anbi Lazio","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2021-02-27T13:19:27+00:00","article_modified_time":"2021-02-28T11:18:47+00:00","og_image":[{"width":759,"height":519,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/ricci-renna.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Progetti Por, Anbi Lazio: sfida vinta grazie alla Regione","datePublished":"2021-02-27T13:19:27+00:00","dateModified":"2021-02-28T11:18:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/"},"wordCount":519,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/ricci-renna.jpg","keywords":["albino ruberti","ambi lazio","andrea renna","bonifica","Frosinone","latina","regione lazio","sonia ricci"],"articleSection":["Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/","name":"Progetti Por, Anbi Lazio: sfida vinta grazie alla Regione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/ricci-renna.jpg","datePublished":"2021-02-27T13:19:27+00:00","dateModified":"2021-02-28T11:18:47+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/ricci-renna.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/ricci-renna.jpg","width":759,"height":519,"caption":"La presidente di Anbi Lazio Sonia Ricci e il direttore Andrea Renna"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Progetti Por, Anbi Lazio: sfida vinta grazie alla Regione"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/27\/progetti-por-anbi-lazio-sfida-vinta-grazie-alla-regione\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/53845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=53845"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/53845\/revisions"}],"predecessor-version":[{"id":53848,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/53845\/revisions\/53848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/42361"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=53845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=53845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=53845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}