{"id":53770,"date":"2021-02-26T12:39:51","date_gmt":"2021-02-26T11:39:51","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=53770"},"modified":"2021-02-26T12:41:06","modified_gmt":"2021-02-26T11:41:06","slug":"agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/","title":{"rendered":"Agricoltura, dalla Regione 5 milioni di euro per il coefficientamento energetico dei consorzi di bonifica del Lazio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Sono stati presentati oggi, a Roma nella sede della Regione Lazio, durante una conferenza stampa in diretta Facebook<\/strong> sulla pagina istituzionale, i 26 progetti di coefficientamento energetico dei Consorzi di bonifica, finanziati con oltre 5 milioni di euro del POR FESR (azione 4.1.1), nell\u2019ambito del programma Lazio Green.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;appuntamento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Alla conferenza stampa sono intervenuti<\/strong> l\u2019assessore Agricoltura, Promozione della Filiera e della Cultura del Cibo, Ambiente e Risorse Naturali della Regione Lazio, Enrica Onorati, i Presidenti e i Commissari dei Consorzi, Niccol\u00f2 Sacchetti, Gianluca Pezzotti, Stefania Ruffo, la presidente Anbi Lazio, Sonia Ricci, il presidente Anci Lazio, Riccardo Varone.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Per la prima volta in Italia, i finanziamenti del Fondo Europeo di Sviluppo Regionale vengono usati per sostenere iniziative di questo tipo presentate dai consorzi di bonifica<\/strong> della nostra regione. Un progetto pilota dunque, unico nel suo genere, che coinvolge tutti i sistemi consortili del Lazio. Una sinergia che permette prima di tutto una serie di interventi a tutela dell\u2019ambiente: la riduzione dei consumi energetici, l\u2019incremento della capacit\u00e0 di autoproduzione di energia da fonte rinnovabile, l\u2019installazione di impianti di cogenerazione e trigenerazione ad alto rendimento, l\u2019implementazione di sistemi di monitoraggio e di gestione energetica, la realizzazione di reti di teleriscaldamento e teleraffrescamento per la distribuzione di energia all\u2019interno dei comprensori interessati.<br>Cuore di ognuno dei progetti, finanziati con i soldi messi a disposizione dall\u2019Europa, sono i principi alla base dell\u2019efficientamento energetico, ovvero interventi che permettono di ridurre i livelli dei consumi e di tagliare gli sprechi, ottimizzando l&#8217;uso delle fonti di approvvigionamento e l\u2019impiego dell&#8217;energia.\u00a0<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPer la prima volta in Italia &#8211; <strong>ha dichiarato l&#8217;Assessore Onorati &#8211; <\/strong>sperimentiamo un nuovo modello di fare sistema, destinando risorse del POR Fesr all&#8217;efficientamento energetico dei Consorzi di bonifica, a beneficio indiretto di tutti i Comuni del Lazio. Una operazione, voluta fortemente dalla Giunta Zingaretti, che porter\u00e0 non solo un risparmio sulle bollette dell\u2019energia elettrica, ma anche il recupero di risorse per realizzare altri interventi di manutenzione ordinaria. Dietro i 5 milioni di euro c\u2019\u00e8, quindi, una attenta operazione in termini di sostenibilit\u00e0 ambientale e un ritorno di investimento molto pi\u00f9 alto in termini di valore e di impatto sul territorio e sui Comuni del Lazio, a testimonianza che avere un patrimonio pubblico pi\u00f9 sostenibile passa anche per un uso efficiente delle risorse economiche a disposizione, in coerenza anche con il Green New Deal europeo&#8221;.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono stati presentati oggi, a Roma nella sede della Regione Lazio, durante una conferenza stampa in diretta Facebook sulla pagina<\/p>\n","protected":false},"author":18,"featured_media":13757,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[669,1368,562],"class_list":["post-53770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-economia","tag-agricoltura","tag-enrica-onorati","tag-regione-lazio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Agricoltura, dalla Regione 5 milioni di euro per il coefficientamento energetico dei consorzi di bonifica del Lazio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agricoltura, dalla Regione 5 milioni di euro per il coefficientamento energetico dei consorzi di bonifica del Lazio\" \/>\n<meta property=\"og:description\" content=\"Sono stati presentati oggi, a Roma nella sede della Regione Lazio, durante una conferenza stampa in diretta Facebook sulla pagina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-26T11:39:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-26T11:41:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/enrica-onorati-regione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"607\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Agricoltura, dalla Regione 5 milioni di euro per il coefficientamento energetico dei consorzi di bonifica del Lazio\",\"datePublished\":\"2021-02-26T11:39:51+00:00\",\"dateModified\":\"2021-02-26T11:41:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/\"},\"wordCount\":420,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/enrica-onorati-regione.jpg\",\"keywords\":[\"agricoltura\",\"Enrica Onorati\",\"regione lazio\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/\",\"name\":\"Agricoltura, dalla Regione 5 milioni di euro per il coefficientamento energetico dei consorzi di bonifica del Lazio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/enrica-onorati-regione.jpg\",\"datePublished\":\"2021-02-26T11:39:51+00:00\",\"dateModified\":\"2021-02-26T11:41:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/enrica-onorati-regione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/enrica-onorati-regione.jpg\",\"width\":607,\"height\":350,\"caption\":\"L'assessore regionale all'Agricoltura Enrica Onorati\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agricoltura, dalla Regione 5 milioni di euro per il coefficientamento energetico dei consorzi di bonifica del Lazio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/26\\\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Agricoltura, dalla Regione 5 milioni di euro per il coefficientamento energetico dei consorzi di bonifica del Lazio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/","og_locale":"it_IT","og_type":"article","og_title":"Agricoltura, dalla Regione 5 milioni di euro per il coefficientamento energetico dei consorzi di bonifica del Lazio","og_description":"Sono stati presentati oggi, a Roma nella sede della Regione Lazio, durante una conferenza stampa in diretta Facebook sulla pagina","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2021-02-26T11:39:51+00:00","article_modified_time":"2021-02-26T11:41:06+00:00","og_image":[{"width":607,"height":350,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/enrica-onorati-regione.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Agricoltura, dalla Regione 5 milioni di euro per il coefficientamento energetico dei consorzi di bonifica del Lazio","datePublished":"2021-02-26T11:39:51+00:00","dateModified":"2021-02-26T11:41:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/"},"wordCount":420,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/enrica-onorati-regione.jpg","keywords":["agricoltura","Enrica Onorati","regione lazio"],"articleSection":["*PRIMO PIANO*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/","name":"Agricoltura, dalla Regione 5 milioni di euro per il coefficientamento energetico dei consorzi di bonifica del Lazio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/enrica-onorati-regione.jpg","datePublished":"2021-02-26T11:39:51+00:00","dateModified":"2021-02-26T11:41:06+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/enrica-onorati-regione.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/enrica-onorati-regione.jpg","width":607,"height":350,"caption":"L'assessore regionale all'Agricoltura Enrica Onorati"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Agricoltura, dalla Regione 5 milioni di euro per il coefficientamento energetico dei consorzi di bonifica del Lazio"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/26\/agricoltura-dalla-regione-5-milioni-di-euro-per-il-coefficientamento-energetico-dei-consorzi-di-bonifica-del-lazio\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/53770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=53770"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/53770\/revisions"}],"predecessor-version":[{"id":53773,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/53770\/revisions\/53773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/13757"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=53770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=53770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=53770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}