{"id":52552,"date":"2021-02-04T11:59:38","date_gmt":"2021-02-04T10:59:38","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=52552"},"modified":"2021-02-04T12:00:42","modified_gmt":"2021-02-04T11:00:42","slug":"recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/","title":{"rendered":"Recupero e sviluppo, al via il progetto di Asi e Regione per il nuovo asse attrezzato sulla Morolense"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Un protocollo d\u2019intesa siglato tra Regione Lazio e l\u2019Asi <\/strong>di Frosinone per la riprogrammazione di fondi ministeriali che saranno utilizzati per la realizzazione del prolungamento del nuovo asse attrezzato sulla Morolense.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>L&#8217;appuntamento<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il progetto verr\u00e0 illustrato venerd\u00ec, <\/strong>nel corso di una conferenza stampa che si terr\u00e0 alle 11.30 presso la sede del Consorzio. <strong>Parteciperanno<\/strong> il presidente dell\u2019Asi Francesco De Angelis, il prefetto di Frosinone Ignazio Portelli, l\u2019assessore regionale alla Programmazione Economica, Bilancio Demanio e Patrimonio, Alessandra Sartore e il capo di Gabinetto del presidente della Regione Lazio, Albino Ruberti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L&#8217;opera servir\u00e0 anche da collegamento <\/strong>con il casello autostradale di Ferentino e la nuova stazione della Tav. <strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un protocollo d\u2019intesa siglato tra Regione Lazio e l\u2019Asi di Frosinone per la riprogrammazione di fondi ministeriali che saranno utilizzati<\/p>\n","protected":false},"author":18,"featured_media":34035,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[6279,7850,289,94,92,969,93],"class_list":["post-52552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-economia","tag-albino-ruberti","tag-alessandra-sartore","tag-asi","tag-ciociaria","tag-ferentino","tag-francesco-de-angelis","tag-frosinone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Recupero e sviluppo, al via il progetto di Asi e Regione per il nuovo asse attrezzato sulla Morolense - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recupero e sviluppo, al via il progetto di Asi e Regione per il nuovo asse attrezzato sulla Morolense\" \/>\n<meta property=\"og:description\" content=\"Un protocollo d\u2019intesa siglato tra Regione Lazio e l\u2019Asi di Frosinone per la riprogrammazione di fondi ministeriali che saranno utilizzati\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-04T10:59:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-04T11:00:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/Francesco-De-Angelis_14.40.59.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Recupero e sviluppo, al via il progetto di Asi e Regione per il nuovo asse attrezzato sulla Morolense\",\"datePublished\":\"2021-02-04T10:59:38+00:00\",\"dateModified\":\"2021-02-04T11:00:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/\"},\"wordCount\":129,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/Francesco-De-Angelis_14.40.59.jpeg\",\"keywords\":[\"albino ruberti\",\"Alessandra Sartore\",\"asi\",\"Ciociaria\",\"ferentino\",\"francesco de angelis\",\"Frosinone\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/\",\"name\":\"Recupero e sviluppo, al via il progetto di Asi e Regione per il nuovo asse attrezzato sulla Morolense - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/Francesco-De-Angelis_14.40.59.jpeg\",\"datePublished\":\"2021-02-04T10:59:38+00:00\",\"dateModified\":\"2021-02-04T11:00:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/Francesco-De-Angelis_14.40.59.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/Francesco-De-Angelis_14.40.59.jpeg\",\"width\":1024,\"height\":683,\"caption\":\"Il presidente del Consorzio Asi Francesco De Angelis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recupero e sviluppo, al via il progetto di Asi e Regione per il nuovo asse attrezzato sulla Morolense\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/02\\\/04\\\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Recupero e sviluppo, al via il progetto di Asi e Regione per il nuovo asse attrezzato sulla Morolense - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/","og_locale":"it_IT","og_type":"article","og_title":"Recupero e sviluppo, al via il progetto di Asi e Regione per il nuovo asse attrezzato sulla Morolense","og_description":"Un protocollo d\u2019intesa siglato tra Regione Lazio e l\u2019Asi di Frosinone per la riprogrammazione di fondi ministeriali che saranno utilizzati","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2021-02-04T10:59:38+00:00","article_modified_time":"2021-02-04T11:00:42+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/Francesco-De-Angelis_14.40.59.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Recupero e sviluppo, al via il progetto di Asi e Regione per il nuovo asse attrezzato sulla Morolense","datePublished":"2021-02-04T10:59:38+00:00","dateModified":"2021-02-04T11:00:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/"},"wordCount":129,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/Francesco-De-Angelis_14.40.59.jpeg","keywords":["albino ruberti","Alessandra Sartore","asi","Ciociaria","ferentino","francesco de angelis","Frosinone"],"articleSection":["*PRIMO PIANO*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/","name":"Recupero e sviluppo, al via il progetto di Asi e Regione per il nuovo asse attrezzato sulla Morolense - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/Francesco-De-Angelis_14.40.59.jpeg","datePublished":"2021-02-04T10:59:38+00:00","dateModified":"2021-02-04T11:00:42+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/Francesco-De-Angelis_14.40.59.jpeg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/Francesco-De-Angelis_14.40.59.jpeg","width":1024,"height":683,"caption":"Il presidente del Consorzio Asi Francesco De Angelis"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Recupero e sviluppo, al via il progetto di Asi e Regione per il nuovo asse attrezzato sulla Morolense"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/02\/04\/recupero-e-sviluppo-al-via-il-progetto-di-asi-e-regione-per-il-nuovo-asse-attrezzato-sulla-morolense\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/52552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=52552"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/52552\/revisions"}],"predecessor-version":[{"id":52555,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/52552\/revisions\/52555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/34035"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=52552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=52552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=52552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}