{"id":52382,"date":"2021-01-30T16:19:01","date_gmt":"2021-01-30T15:19:01","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=52382"},"modified":"2021-01-30T16:21:08","modified_gmt":"2021-01-30T15:21:08","slug":"marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/","title":{"rendered":"Marocchinate, Ruspandini: finalmente giornata e intitolazione strada. Ora avanti con Ddl in Senato"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8221;<strong>Finalmente le vittime delle violenze di cui si macchiarono nel corso della Seconda guerra mondiale il corpo di spedizione francese<\/strong> e in particolare di alcuni reparti a loro aggregati di marocchini, in Italia e nello specifico nelle citt\u00e0 della Ciociaria, le tristemente note marocchinate, potranno avere non solo una data per essere commemorate ma anche una strada intitolata alla loro memoria. Infatti, con una determina il comune di Ceccano, in provincia di Frosinone, ha voluto rendere omaggio a questa pagina di storia dimenticata&#8221;.  <strong>Lo dichiara il senatore di Fratelli d&#8217;Italia, Massimo Ruspandini<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;E&#8217; chiaro -aggiunge- che non si tratta di avviare un processo di revisionismo, quanto piuttosto di recuperare pagine della nostra storia nazionale strappate. E si tratta anche di un riconoscimento per quelle tantissime vittime che, indifese e inermi, furono travolte da una violenza ingiustificabile e barbara, che nulla aveva a che vedere con la guerra. Adesso mi auguro che questo possa essere da esempio sia per le tante altre citt\u00e0 della Ciociaria e sia per le restanti citt\u00e0 italiane perch\u00e9 questo dramma appartiene alla nostra storia nazionale e come tale va adeguatamente ricordato&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8221; E inoltre spero che tutto ci\u00f2 possa contribuire, finalmente, ad accelerare la discussione in Senato del nostro disegno di legge per l&#8217;istituzione di una giornata nazionale. Infine, desidero ringraziare chi ha lavorato a questo grande risultato, il consigliere comunale Daniele Massa, presidente provinciale di Giovent\u00f9 Nazionale, l&#8217;intero Consiglio comunale di Ceccano e il sindaco di Fdi di Ceccano Roberto Caligiore&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8221;Finalmente le vittime delle violenze di cui si macchiarono nel corso della Seconda guerra mondiale il corpo di spedizione francese<\/p>\n","protected":false},"author":18,"featured_media":1506,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[524,94,2961,4200,3527,569],"class_list":["post-52382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-ceccano","tag-ciociaria","tag-fdi","tag-marocchinate","tag-massimo-ruspandini","tag-senato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Marocchinate, Ruspandini: finalmente giornata e intitolazione strada. Ora avanti con Ddl in Senato - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marocchinate, Ruspandini: finalmente giornata e intitolazione strada. Ora avanti con Ddl in Senato\" \/>\n<meta property=\"og:description\" content=\"&#8221;Finalmente le vittime delle violenze di cui si macchiarono nel corso della Seconda guerra mondiale il corpo di spedizione francese\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-30T15:19:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-30T15:21:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/Massimo-Ruspandini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Marocchinate, Ruspandini: finalmente giornata e intitolazione strada. Ora avanti con Ddl in Senato\",\"datePublished\":\"2021-01-30T15:19:01+00:00\",\"dateModified\":\"2021-01-30T15:21:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/\"},\"wordCount\":261,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/Massimo-Ruspandini.jpg\",\"keywords\":[\"ceccano\",\"Ciociaria\",\"fdI\",\"marocchinate\",\"massimo ruspandini\",\"Senato\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/\",\"name\":\"Marocchinate, Ruspandini: finalmente giornata e intitolazione strada. Ora avanti con Ddl in Senato - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/Massimo-Ruspandini.jpg\",\"datePublished\":\"2021-01-30T15:19:01+00:00\",\"dateModified\":\"2021-01-30T15:21:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/Massimo-Ruspandini.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/Massimo-Ruspandini.jpg\",\"width\":670,\"height\":400,\"caption\":\"Il senatore Ruspandini\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marocchinate, Ruspandini: finalmente giornata e intitolazione strada. Ora avanti con Ddl in Senato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/30\\\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Marocchinate, Ruspandini: finalmente giornata e intitolazione strada. Ora avanti con Ddl in Senato - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/","og_locale":"it_IT","og_type":"article","og_title":"Marocchinate, Ruspandini: finalmente giornata e intitolazione strada. Ora avanti con Ddl in Senato","og_description":"&#8221;Finalmente le vittime delle violenze di cui si macchiarono nel corso della Seconda guerra mondiale il corpo di spedizione francese","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2021-01-30T15:19:01+00:00","article_modified_time":"2021-01-30T15:21:08+00:00","og_image":[{"width":670,"height":400,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/Massimo-Ruspandini.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Marocchinate, Ruspandini: finalmente giornata e intitolazione strada. Ora avanti con Ddl in Senato","datePublished":"2021-01-30T15:19:01+00:00","dateModified":"2021-01-30T15:21:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/"},"wordCount":261,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/Massimo-Ruspandini.jpg","keywords":["ceccano","Ciociaria","fdI","marocchinate","massimo ruspandini","Senato"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/","name":"Marocchinate, Ruspandini: finalmente giornata e intitolazione strada. Ora avanti con Ddl in Senato - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/Massimo-Ruspandini.jpg","datePublished":"2021-01-30T15:19:01+00:00","dateModified":"2021-01-30T15:21:08+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/Massimo-Ruspandini.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/Massimo-Ruspandini.jpg","width":670,"height":400,"caption":"Il senatore Ruspandini"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Marocchinate, Ruspandini: finalmente giornata e intitolazione strada. Ora avanti con Ddl in Senato"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/30\/marocchinate-ruspandini-finalmente-giornata-e-intitolazione-strada-ora-avanti-con-ddl-in-senato\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/52382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=52382"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/52382\/revisions"}],"predecessor-version":[{"id":52385,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/52382\/revisions\/52385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/1506"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=52382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=52382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=52382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}