{"id":52227,"date":"2021-01-26T14:55:10","date_gmt":"2021-01-26T13:55:10","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=52227"},"modified":"2021-01-26T14:55:11","modified_gmt":"2021-01-26T13:55:11","slug":"ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/","title":{"rendered":"Ruba le foto dai social di una 24enne di Sora e fa scoppiare una lite di gelosia con il fidanzato: denunciata 22enne"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Polizia di Stato di Sora, a conclusione di due diverse indagini, <strong>ha denunciato due ragazzi<\/strong>, rispettivamente di<strong> 22 anni lei e 27 anni lui<\/strong>.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ragazza, nata e residente a Cassino, come emerso dalle <strong>indagini dei poliziotti della Squadra Anticrimine<\/strong>, dovr\u00e0 rispondere di sostituzione di persona. Da circa un anno, infatti, <strong>&#8216;rubava&#8217; le foto dal profilo social di una 24enne sorana <\/strong>e le pubblicava su un falso profilo da lei creato su un altro social network, spacciandosi ovviamente per la sua vittima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il furto di identit\u00e0 \u00e8 stato scoperto quando il fidanzato della donna di Sora \u00e8 stato contattato per un chiarimento da un &#8216;pretendente&#8217; della sua amata, caduto nella trappola della 22enne. Il confronto tra i quattro giovani coinvolti ha permesso di svelare l&#8217;inganno: inutili le scuse, la vittima si \u00e8 rivolta alla Polizia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ventisettenne imbratta muri con spray<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Di danneggiamento da scritte murali \u00e8 stato invece accusato un giovane della citt\u00e0 volsca. <strong>I fatti risalgono al giugno 2020<\/strong>, quando il 27enne si \u00e8 reso protagonista dell\u2019imbrattamento di muri con delle bombolette di vernice spray.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un&#8217;accurata attivit\u00e0 di indagine, con il supporto della Polizia Scientifica e l\u2019estrapolazione dei fotogrammi dai sistemi di videosorveglianza in citt\u00e0, ha permesso alla Squadra Informativa del Commissariato di identificare l\u2019autore e denunciarlo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La polizia di Sora ha denunciato una ragazza per sostituzione di persona e un giovane di 27 anni per danneggiamento di muri<\/p>\n","protected":false},"author":18,"featured_media":52228,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2],"tags":[12337,94,245,510,8181,93,12338,291,2874,2791,6155],"class_list":["post-52227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cronaca","tag-anticrimine","tag-ciociaria","tag-denuncia","tag-facebook","tag-foto","tag-frosinone","tag-muri","tag-polizia","tag-profilo","tag-sostituzione","tag-spray"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ruba le foto dai social di una 24enne di Sora e fa scoppiare una lite di gelosia con il fidanzato: denunciata 22enne - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ruba le foto dai social di una 24enne di Sora e fa scoppiare una lite di gelosia con il fidanzato: denunciata 22enne\" \/>\n<meta property=\"og:description\" content=\"La polizia di Sora ha denunciato una ragazza per sostituzione di persona e un giovane di 27 anni per danneggiamento di muri\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-26T13:55:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-26T13:55:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/foto-social.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"451\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Ruba le foto dai social di una 24enne di Sora e fa scoppiare una lite di gelosia con il fidanzato: denunciata 22enne\",\"datePublished\":\"2021-01-26T13:55:10+00:00\",\"dateModified\":\"2021-01-26T13:55:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/\"},\"wordCount\":228,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/foto-social.jpg\",\"keywords\":[\"anticrimine\",\"Ciociaria\",\"denuncia\",\"facebook\",\"foto\",\"Frosinone\",\"muri\",\"polizia\",\"profilo\",\"sostituzione\",\"Spray\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/\",\"name\":\"Ruba le foto dai social di una 24enne di Sora e fa scoppiare una lite di gelosia con il fidanzato: denunciata 22enne - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/foto-social.jpg\",\"datePublished\":\"2021-01-26T13:55:10+00:00\",\"dateModified\":\"2021-01-26T13:55:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/foto-social.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/foto-social.jpg\",\"width\":800,\"height\":451,\"caption\":\"polizia postale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ruba le foto dai social di una 24enne di Sora e fa scoppiare una lite di gelosia con il fidanzato: denunciata 22enne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/26\\\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ruba le foto dai social di una 24enne di Sora e fa scoppiare una lite di gelosia con il fidanzato: denunciata 22enne - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/","og_locale":"it_IT","og_type":"article","og_title":"Ruba le foto dai social di una 24enne di Sora e fa scoppiare una lite di gelosia con il fidanzato: denunciata 22enne","og_description":"La polizia di Sora ha denunciato una ragazza per sostituzione di persona e un giovane di 27 anni per danneggiamento di muri","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2021-01-26T13:55:10+00:00","article_modified_time":"2021-01-26T13:55:11+00:00","og_image":[{"width":800,"height":451,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/foto-social.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Ruba le foto dai social di una 24enne di Sora e fa scoppiare una lite di gelosia con il fidanzato: denunciata 22enne","datePublished":"2021-01-26T13:55:10+00:00","dateModified":"2021-01-26T13:55:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/"},"wordCount":228,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/foto-social.jpg","keywords":["anticrimine","Ciociaria","denuncia","facebook","foto","Frosinone","muri","polizia","profilo","sostituzione","Spray"],"articleSection":["*PRIMO PIANO*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/","name":"Ruba le foto dai social di una 24enne di Sora e fa scoppiare una lite di gelosia con il fidanzato: denunciata 22enne - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/foto-social.jpg","datePublished":"2021-01-26T13:55:10+00:00","dateModified":"2021-01-26T13:55:11+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/foto-social.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/foto-social.jpg","width":800,"height":451,"caption":"polizia postale"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ruba le foto dai social di una 24enne di Sora e fa scoppiare una lite di gelosia con il fidanzato: denunciata 22enne"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/26\/ruba-le-foto-dai-social-di-una-24enne-di-sora-e-fa-scoppiare-una-lite-di-gelosia-con-il-fidanzato-denunciata-22enne\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/52227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=52227"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/52227\/revisions"}],"predecessor-version":[{"id":52229,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/52227\/revisions\/52229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/52228"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=52227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=52227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=52227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}