{"id":51283,"date":"2021-01-08T17:27:25","date_gmt":"2021-01-08T16:27:25","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=51283"},"modified":"2021-01-08T17:27:41","modified_gmt":"2021-01-08T16:27:41","slug":"cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/","title":{"rendered":"Cassino, riapre la scuola a  Sant\u2019Angelo in Theodice: sopralluogo del sindaco"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Luned\u00ec prossimo, 11 gennaio, i bambini delle cinque classi della scuola elementare di Sant\u2019Angelo in Theodice<\/strong> ritorneranno a frequentare le lezioni nell\u2019edificio di corso Trieste totalmente ristrutturato e rimesso a nuovo. Per i pi\u00f9 piccoli della scuola dell\u2019Infanzia, invece, se ne riparler\u00e0 tra un paio di settimane, il tempo necessario per sistemare lo spazio interno del pianterreno e l\u2019area esterna dello stesso edificio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Questa mattina \u00e8 stato effettuato un sopralluogo, presenti alcune mamme rappresentanti delle classi nonch\u00e9 la presidente del consiglio di Istituto. C\u2019erano il sindaco, Enzo Salera,<\/strong> l\u2019assessore alla Pubblica Istruzione, Concetta Tamburrini, i consiglieri Fausto Salera e Riccardo Consales, la dirigente scolastica, Vincenza Simeone, il dirigente dell\u2019Area Tecnica che ha diretto i lavori, ing. Mario Lastoria, i titolari dell\u2019impresa esecutrice dei lavori \u201cAppalti e Servizi srl\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019intervento dell\u2019importo di 450 mila euro (di cui 50 mila per l\u2019antincendio) ha riguardato il miglioramento sismico della struttura scolastica composta di due parti: l\u2019una in muratura, interessata dal miglioramento sismico; l\u2019altra in cemento armato per l\u2019adeguamento sismico. Rifatti ex novo gli impianti elettrici e il sistema di prevenzione incendi.&nbsp; Naturalmente si \u00e8 proceduto alla tinteggiatura sia interna che esterna e all\u2019abbattimento delle barriere architettoniche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E\u2019 in corso di ultimazione una piattaforma elevatrice dal piano terra a quello superiore.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le mamme presenti hanno preso atto dell\u2019ottimo lavoro svolto e, vedendo di persona, si sono rassicurate anche rispetto ad ingiustificate voci allarmistiche circa il pericolo di una fantomatica \u201cbuca\u201d pericolosa per i bambini.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<strong>Sono davvero soddisfatto \u2013 ha detto in Sindaco \u2013 per il buon lavoro fatto<\/strong> che ci permette di riconsegnare alla comunit\u00e0 scolastica un edificio al passo con i tempi, messo in sicurezza a tutela dei nostri bambini e degli operatori scolastici\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019assessore ai Lavori Pubblici, l\u2019ing. Francesco Carlino, dal canto suo ci ha tenuto ad evidenziare che \u201crispetto al progetto iniziale sono state apportate, grazie alle economie di gara, anche delle migliorie. Cosa possibile quando l\u2019unico obiettivo cui ci si lascia guidare \u00e8 l\u2019interesse degli utenti\u201d:<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luned\u00ec prossimo, 11 gennaio, i bambini delle cinque classi della scuola elementare di Sant\u2019Angelo in Theodice ritorneranno a frequentare le<\/p>\n","protected":false},"author":18,"featured_media":51284,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,38],"tags":[216,94,3273,93,227,367,117],"class_list":["post-51283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-scuola","tag-cassino","tag-ciociaria","tag-enzo-salera","tag-frosinone","tag-lavori","tag-scuola","tag-sindaco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cassino, riapre la scuola a Sant\u2019Angelo in Theodice: sopralluogo del sindaco - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cassino, riapre la scuola a Sant\u2019Angelo in Theodice: sopralluogo del sindaco\" \/>\n<meta property=\"og:description\" content=\"Luned\u00ec prossimo, 11 gennaio, i bambini delle cinque classi della scuola elementare di Sant\u2019Angelo in Theodice ritorneranno a frequentare le\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-08T16:27:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-08T16:27:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/salera-enzo-cassino-sindaco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"761\" \/>\n\t<meta property=\"og:image:height\" content=\"492\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Cassino, riapre la scuola a Sant\u2019Angelo in Theodice: sopralluogo del sindaco\",\"datePublished\":\"2021-01-08T16:27:25+00:00\",\"dateModified\":\"2021-01-08T16:27:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/\"},\"wordCount\":355,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/salera-enzo-cassino-sindaco.jpg\",\"keywords\":[\"Cassino\",\"Ciociaria\",\"enzo salera\",\"Frosinone\",\"lavori\",\"scuola\",\"Sindaco\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Scuola\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/\",\"name\":\"Cassino, riapre la scuola a Sant\u2019Angelo in Theodice: sopralluogo del sindaco - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/salera-enzo-cassino-sindaco.jpg\",\"datePublished\":\"2021-01-08T16:27:25+00:00\",\"dateModified\":\"2021-01-08T16:27:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/salera-enzo-cassino-sindaco.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/salera-enzo-cassino-sindaco.jpg\",\"width\":761,\"height\":492},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cassino, riapre la scuola a Sant\u2019Angelo in Theodice: sopralluogo del sindaco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/08\\\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cassino, riapre la scuola a Sant\u2019Angelo in Theodice: sopralluogo del sindaco - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/","og_locale":"it_IT","og_type":"article","og_title":"Cassino, riapre la scuola a Sant\u2019Angelo in Theodice: sopralluogo del sindaco","og_description":"Luned\u00ec prossimo, 11 gennaio, i bambini delle cinque classi della scuola elementare di Sant\u2019Angelo in Theodice ritorneranno a frequentare le","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2021-01-08T16:27:25+00:00","article_modified_time":"2021-01-08T16:27:41+00:00","og_image":[{"width":761,"height":492,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/salera-enzo-cassino-sindaco.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Cassino, riapre la scuola a Sant\u2019Angelo in Theodice: sopralluogo del sindaco","datePublished":"2021-01-08T16:27:25+00:00","dateModified":"2021-01-08T16:27:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/"},"wordCount":355,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/salera-enzo-cassino-sindaco.jpg","keywords":["Cassino","Ciociaria","enzo salera","Frosinone","lavori","scuola","Sindaco"],"articleSection":["*PRIMO PIANO*","Scuola"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/","name":"Cassino, riapre la scuola a Sant\u2019Angelo in Theodice: sopralluogo del sindaco - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/salera-enzo-cassino-sindaco.jpg","datePublished":"2021-01-08T16:27:25+00:00","dateModified":"2021-01-08T16:27:41+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/salera-enzo-cassino-sindaco.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/salera-enzo-cassino-sindaco.jpg","width":761,"height":492},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Cassino, riapre la scuola a Sant\u2019Angelo in Theodice: sopralluogo del sindaco"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/08\/cassino-riapre-la-scuola-a-santangelo-in-theodice-sopralluogo-del-sindaco\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/51283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=51283"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/51283\/revisions"}],"predecessor-version":[{"id":51285,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/51283\/revisions\/51285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/51284"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=51283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=51283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=51283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}