{"id":51231,"date":"2021-01-07T12:14:33","date_gmt":"2021-01-07T11:14:33","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=51231"},"modified":"2021-01-07T12:18:23","modified_gmt":"2021-01-07T11:18:23","slug":"mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/","title":{"rendered":"Mastrangeli: vaccinarsi \u00e8 una scelta di assoluto altruismo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Una scelta di altruismo, di amore verso se stessi e verso il prossimo. A dirlo \u00e8 il <strong>presidente dell\u2019Ordine dei Farmacisti della provincia di Frosinone, Riccardo Mastrangeli<\/strong>, che nella giornata di ieri si \u00e8 sottoposto alla <strong>vaccinazione anti-Covid <\/strong>in quanto appartenente alle categorie che prima delle altre devono immunizzarsi.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le osservazioni del presidente dell&#8217;Ordine dei farmacisti<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Quest\u2019emergenza straordinaria \u2013 sottolinea Mastrangeli &#8211; ha avuto un forte impatto a livello globale, e ci ha anche coinvolti in prima persona. Non solo sul personale, noi farmacisti, abbiamo avuto un cambio radicale delle nostre abitudini e del nostro stile di vita, ma soprattutto professionalmente <strong>abbiamo dovuto confrontarci quotidianamente con una nuova realt\u00e0 che le nostre generazioni non avevano mai conosciuto <\/strong>ma avuto solo tramandato in racconto. \u00a0Ormai da quasi un anno tutti insieme, farmacisti collaboratori, ospedalieri, titolari di farmacie e parafarmacie, colleghi impegnati nell\u2019industria farmaceutica<strong> abbiamo fatto emergere dal nostro profondo forze ed energie inaspettate che ci hanno permesso e ci permettono tutt\u2019ora di far fronte alla pandemia<\/strong>, ricordando sempre che a causa del Covid ci hanno lasciato ben 23 colleghi e nella nostra provincia abbiamo un vuoto ancora difficile ad essere compreso pienamente per la perdita del carissimo Dottor Francesco Paolo Ferraro&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/riccardo-mastrangeli-frosinone.jpg\" alt=\"riccardo mastrangeli frosinone il corriere della provincia\" class=\"wp-image-4504\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/riccardo-mastrangeli-frosinone.jpg 400w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/riccardo-mastrangeli-frosinone-150x150.jpg 150w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/riccardo-mastrangeli-frosinone-300x300.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption> Riccardo Mastrangeli<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Io mi sono vaccinato ieri insieme a tanti colleghi <\/strong>poich\u00e9, grazie ad un accordo con la Regione Lazio, siamo tra i primi ad essere immunizzati in quanto la nostra \u2018mission\u2019 \u00e8 quella di assistere e dare servizi ai nostri pazienti e clienti \u2018in presenza\u2019, e non da remoto. Sul web \u2013 prosegue il presidente dell\u2019Ordine &#8211; leggiamo quotidianamente di paure, scetticismi ed irragionevolezze che ci fanno pensare a rigurgiti di oscurantismo medievale con anni di evoluzione scientifica attaccati da pensieri deliranti; essendo i farmacisti soprattutto uomini di scienza \u2013 e mi piace sempre ricordare che il farmacista \u00e8 anche l\u2019operatore sanitario con il pi\u00f9 alto numero di contatti ogni giorno con la gente \u2013 dobbiamo essere noi di esempio alla popolazione parlando con competenza dell\u2019unico strumento che abbiamo ora per porre fine alla pandemia, sapendo bene che il vaccino \u00e8 sicuro e che tutte le fasi di ricerca sono state svolte con grande seriet\u00e0 rispettando i tempi necessari&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Vaccinarci e vaccinarsi \u2013 conclude Mastrangeli &#8211; \u00e8 una scelta di assoluto altruismo ed amore non solo per i nostri cari ma soprattutto per le comunit\u00e0 che assistiamo, e, ribadisco ancora, \u00e8 l\u2019unica barriera che possiamo erigere contro il coronavirus e i danni che esso sta causando ad ogni livello&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il presidente dell&#8217;Ordine dei Farmacisti di Frosinone Riccardo Mastrangeli si \u00e8 sottoposto alla vaccinazione anti-Covid<\/p>\n","protected":false},"author":18,"featured_media":51232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[8337,8916,93,12210,1871,2033,12209],"class_list":["post-51231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-salute","tag-coronavirus","tag-covid","tag-frosinone","tag-immunizzare","tag-ordine-dei-farmacisti","tag-riccardo-mastrangeli","tag-vaccinazione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mastrangeli: vaccinarsi \u00e8 una scelta di assoluto altruismo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mastrangeli: vaccinarsi \u00e8 una scelta di assoluto altruismo\" \/>\n<meta property=\"og:description\" content=\"Il presidente dell&#039;Ordine dei Farmacisti di Frosinone Riccardo Mastrangeli si \u00e8 sottoposto alla vaccinazione anti-Covid\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-07T11:14:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-07T11:18:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/vaccino-mastrangeli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"763\" \/>\n\t<meta property=\"og:image:height\" content=\"668\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Mastrangeli: vaccinarsi \u00e8 una scelta di assoluto altruismo\",\"datePublished\":\"2021-01-07T11:14:33+00:00\",\"dateModified\":\"2021-01-07T11:18:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/\"},\"wordCount\":413,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/vaccino-mastrangeli.jpg\",\"keywords\":[\"coronavirus\",\"covid\",\"Frosinone\",\"immunizzare\",\"ordine dei farmacisti\",\"riccardo mastrangeli\",\"vaccinazione\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Salute e Benessere\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/\",\"name\":\"Mastrangeli: vaccinarsi \u00e8 una scelta di assoluto altruismo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/vaccino-mastrangeli.jpg\",\"datePublished\":\"2021-01-07T11:14:33+00:00\",\"dateModified\":\"2021-01-07T11:18:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/vaccino-mastrangeli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/vaccino-mastrangeli.jpg\",\"width\":763,\"height\":668,\"caption\":\"Riccardo Mastrangeli si \u00e8 sottoposto alla vaccinazione anti-Covid\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mastrangeli: vaccinarsi \u00e8 una scelta di assoluto altruismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/01\\\/07\\\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mastrangeli: vaccinarsi \u00e8 una scelta di assoluto altruismo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/","og_locale":"it_IT","og_type":"article","og_title":"Mastrangeli: vaccinarsi \u00e8 una scelta di assoluto altruismo","og_description":"Il presidente dell'Ordine dei Farmacisti di Frosinone Riccardo Mastrangeli si \u00e8 sottoposto alla vaccinazione anti-Covid","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2021-01-07T11:14:33+00:00","article_modified_time":"2021-01-07T11:18:23+00:00","og_image":[{"width":763,"height":668,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/vaccino-mastrangeli.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Mastrangeli: vaccinarsi \u00e8 una scelta di assoluto altruismo","datePublished":"2021-01-07T11:14:33+00:00","dateModified":"2021-01-07T11:18:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/"},"wordCount":413,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/vaccino-mastrangeli.jpg","keywords":["coronavirus","covid","Frosinone","immunizzare","ordine dei farmacisti","riccardo mastrangeli","vaccinazione"],"articleSection":["*PRIMO PIANO*","Salute e Benessere"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/","name":"Mastrangeli: vaccinarsi \u00e8 una scelta di assoluto altruismo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/vaccino-mastrangeli.jpg","datePublished":"2021-01-07T11:14:33+00:00","dateModified":"2021-01-07T11:18:23+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/vaccino-mastrangeli.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/01\/vaccino-mastrangeli.jpg","width":763,"height":668,"caption":"Riccardo Mastrangeli si \u00e8 sottoposto alla vaccinazione anti-Covid"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Mastrangeli: vaccinarsi \u00e8 una scelta di assoluto altruismo"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/01\/07\/mastrangeli-vaccinarsi-scelta-di-assoluto-altruismo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/51231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=51231"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/51231\/revisions"}],"predecessor-version":[{"id":51236,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/51231\/revisions\/51236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/51232"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=51231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=51231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=51231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}