{"id":50481,"date":"2020-12-22T09:16:58","date_gmt":"2020-12-22T08:16:58","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=50481"},"modified":"2020-12-22T17:19:51","modified_gmt":"2020-12-22T16:19:51","slug":"fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/","title":{"rendered":"Fondi per aree ex-Casmez, Federlazio: ottima notizia ma servono tempi rapidi"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;E&#8217; una buona notizia l\u2019approvazione in Commissione Bilancio della Camera dell\u2019emendamento che prevede per la provincia di Frosinone 135 milioni di euro destinati alle aree della ex-Cassa per il Mezzogiorno\u201d, <strong>Lo evidenzia il Direttore della Federlazio di Frosinone Roberto Battisti.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Dio solo sa quanto vi sia bisogno in questo momento di cogliere qualsiasi opportunit\u00e0 per far affluire risorse su un territorio duramente provato dalla crisi economica innestata dalla pandemia. E\u2019 la dimostrazione che quando i rappresentanti politici del territorio riescono a fare squadra al di l\u00e0 dell\u2019appartenenza partitica, i risultati si possono ottenere. Ma l\u2019approvazione dell\u2019emendamento \u00e8 solo un punto di partenza\u201d, prosegue il Direttore Battisti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cOra ci sar\u00e0 la parte pi\u00f9 importante, che \u00e8 rappresentata dalla traduzione, in tempi rapidi e senza lungaggini estenuanti, di quelle risorse in progetti concreti e utili per la ripartenza. Dallo stanziamento di risorse alla produzione degli effetti concreti il passo purtroppo non \u00e8 breve, come l\u2019esperienza ci ha insegnato, e noi dobbiamo cercare di ridurre il pi\u00f9 possibile questo intervallo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;E&#8217; una buona notizia l\u2019approvazione in Commissione Bilancio della Camera dell\u2019emendamento che prevede per la provincia di Frosinone 135 milioni<\/p>\n","protected":false},"author":18,"featured_media":7677,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,5],"tags":[94,1015,93,2826],"class_list":["post-50481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-economia","tag-ciociaria","tag-federlazio","tag-frosinone","tag-roberto-battisti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fondi per aree ex-Casmez, Federlazio: ottima notizia ma servono tempi rapidi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fondi per aree ex-Casmez, Federlazio: ottima notizia ma servono tempi rapidi\" \/>\n<meta property=\"og:description\" content=\"&#8220;E&#8217; una buona notizia l\u2019approvazione in Commissione Bilancio della Camera dell\u2019emendamento che prevede per la provincia di Frosinone 135 milioni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-22T08:16:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-22T16:19:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/roberto-battisti-federlazio-e1551885246195.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Fondi per aree ex-Casmez, Federlazio: ottima notizia ma servono tempi rapidi\",\"datePublished\":\"2020-12-22T08:16:58+00:00\",\"dateModified\":\"2020-12-22T16:19:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/\"},\"wordCount\":182,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/roberto-battisti-federlazio-e1551885246195.jpg\",\"keywords\":[\"Ciociaria\",\"Federlazio\",\"Frosinone\",\"roberto battisti\"],\"articleSection\":[\"*SLIDE*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/\",\"name\":\"Fondi per aree ex-Casmez, Federlazio: ottima notizia ma servono tempi rapidi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/roberto-battisti-federlazio-e1551885246195.jpg\",\"datePublished\":\"2020-12-22T08:16:58+00:00\",\"dateModified\":\"2020-12-22T16:19:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/roberto-battisti-federlazio-e1551885246195.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/roberto-battisti-federlazio-e1551885246195.jpg\",\"width\":632,\"height\":437,\"caption\":\"Il direttore di Federlazio Roberto Battisti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fondi per aree ex-Casmez, Federlazio: ottima notizia ma servono tempi rapidi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/22\\\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fondi per aree ex-Casmez, Federlazio: ottima notizia ma servono tempi rapidi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/","og_locale":"it_IT","og_type":"article","og_title":"Fondi per aree ex-Casmez, Federlazio: ottima notizia ma servono tempi rapidi","og_description":"&#8220;E&#8217; una buona notizia l\u2019approvazione in Commissione Bilancio della Camera dell\u2019emendamento che prevede per la provincia di Frosinone 135 milioni","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-12-22T08:16:58+00:00","article_modified_time":"2020-12-22T16:19:51+00:00","og_image":[{"width":632,"height":437,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/roberto-battisti-federlazio-e1551885246195.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Fondi per aree ex-Casmez, Federlazio: ottima notizia ma servono tempi rapidi","datePublished":"2020-12-22T08:16:58+00:00","dateModified":"2020-12-22T16:19:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/"},"wordCount":182,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/roberto-battisti-federlazio-e1551885246195.jpg","keywords":["Ciociaria","Federlazio","Frosinone","roberto battisti"],"articleSection":["*SLIDE*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/","name":"Fondi per aree ex-Casmez, Federlazio: ottima notizia ma servono tempi rapidi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/roberto-battisti-federlazio-e1551885246195.jpg","datePublished":"2020-12-22T08:16:58+00:00","dateModified":"2020-12-22T16:19:51+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/roberto-battisti-federlazio-e1551885246195.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/roberto-battisti-federlazio-e1551885246195.jpg","width":632,"height":437,"caption":"Il direttore di Federlazio Roberto Battisti"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Fondi per aree ex-Casmez, Federlazio: ottima notizia ma servono tempi rapidi"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/22\/fondi-per-aree-ex-casmez-federlazio-ottima-notizia-ma-servono-tempi-rapidi\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/50481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=50481"}],"version-history":[{"count":6,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/50481\/revisions"}],"predecessor-version":[{"id":50529,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/50481\/revisions\/50529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/7677"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=50481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=50481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=50481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}