{"id":50374,"date":"2020-12-20T05:02:16","date_gmt":"2020-12-20T04:02:16","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=50374"},"modified":"2020-12-20T05:02:17","modified_gmt":"2020-12-20T04:02:17","slug":"frosinone-solidiamo-premiati-oltre-mille-studenti","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/","title":{"rendered":"Frosinone, Solidiamo: premiati oltre mille studenti"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si \u00e8 tenuta presso il centro Forum la <strong>cerimonia inaugurale dell&#8217;edizione 2020 di Solidiamo FormAzione. <\/strong>Hanno ricevuto il riconoscimento, complessivamente, <strong>1030 ragazze e ragazzi<\/strong>: <strong>330 con borse di studio in denaro, mentre 700 di loro saranno destinatari di un premio<\/strong> (una card prepagata da spendere nelle librerie Ubik e Mondadori bookstore di Frosinone e nelle agenzie 3i Travel, Spaziani viaggi, Benedetti viaggi e crociere, Lepintours &amp; Marocco, Elpica viaggi).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">I presenti<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Erano presenti, presso la sala della Protezione civile, il sindaco Nicola Ottaviani, l&#8217;assessore Riccardo Mastrangeli, il presidente del consiglio comunale Adriano Piacentini, i consiglieri Corrado Renzi, Debora Patrizi, Sara Bruni. Con loro, i dirigenti degli istituti superiori e delle medie: Monica Fontana, Patrizia Carfagna, Antonia Carlini, Erminia Gnagni, Fabio Giona, Mara Bufalini, Edina Furlan, Tiziana Lunghi in rappresentanza dell&#8217;Angeloni, Loredana Testiera per Campo Coni. Gli alunni \u2013 uno per istituto \u2013 hanno raccontato la propria esperienza scolastica personale, anche nel periodo della pandemia, e i propri progetti per il futuro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Da domani il ritiro dei premi alla villa<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il ritiro \u201cfisico\u201d delle borse di studio e dei premi, secondo il programma fornito dalle scuole, avverr\u00e0 presso la Villa Comunale a partire da luned\u00ec, nel massimo rispetto delle disposizioni in materiale di distanziamento e prevenzione. Il 21, dalle 13 alle 16.30, toccher\u00e0 ai comprensivi; dalle 17 alle 19, sar\u00e0 invece la volta di Angeloni, Brunelleschi-Da Vinci, Volta e Bragaglia. Il 22, dalle 14 alle 19, Turriziani e Maccari; infine, il 23 dicembre, dalle 10 alle 14, il Severi.<br><br>Il progetto, nato nel 2012 per iniziativa del sindaco Nicola Ottaviani, prevede l\u2019erogazione di borse di studio e premi in favore degli alunni pi\u00f9 meritevoli, valutati sotto il profilo dell&#8217;impegno e del reddito familiare, delle Scuole Medie e Superiori di Frosinone grazie a un fondo costituito mediante il taglio del 50% delle indennit\u00e0 di funzione di Sindaco, Assessori e Presidente del Consiglio comunale e dei gettoni di presenza dei Consiglieri comunali.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ottaviani: la grande resilienza degli studenti<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;In un periodo come quello presente, dominato dall\u2019emergenza sanitaria, i giovani \u2013 ha dichiarato il sindaco, Nicola Ottaviani \u2013 potrebbero avanzare tutte le giustificazioni possibili per prendere le distanze dallo studio. Eppure, ancora una volta, nella nostra citt\u00e0, gli studenti hanno dimostrato grande capacit\u00e0 di resilienza, coraggio e determinazione nel realizzare i propri sogni, portando a termine il proprio percorso formativo. Ci\u00f2 non sarebbe stato possibile senza il sostegno delle famiglie, dei dirigenti, dei docenti e di tutto il personale non docente che, giorno dopo giorno, all\u2019interno degli istituti del nostro territorio, hanno lavorato affinch\u00e9 ogni studente raggiungesse il traguardo che l\u2019intera comunit\u00e0 celebra oggi. Queste ragazze e questi ragazzi, insieme ai loro dirigenti e insegnanti, costituiscono la prova dell\u2019esistenza di un\u2019Italia efficiente, che consolida, con il proprio operato, i valori della coesione sociale&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"403\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/nicola-ottaviani-roma-e1554740208411.jpg\" alt=\"nicola ottaviani sindaco frosinone il corriere della provincia\" class=\"wp-image-9550\" \/><figcaption>Il sindaco di Frosinone Nicola Ottaviani<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Il progetto Solidiamo \u2013 ha concluso il sindaco &#8211; \u00e8 rivolto esclusivamente ai residenti nel capoluogo, proprio perch\u00e9, essendo finanziato attraverso le indennit\u00e0 e i gettoni degli amministratori comunali, risulta coperto, di fatto, solo con le risorse e i tributi provenienti dai cittadini della nostra comunit\u00e0 locale, valorizzando quindi il senso della solidariet\u00e0 collettiva. Il dato riguardante il numero di cittadini nati in altri Paesi che, ogni anno, si aggiudicano la borsa o i premi di Solidiamo si aggira sul 15\/20% del totale dei partecipanti al progetto: ci\u00f2, infine, d\u00e0 la misura del ruolo importante dell\u2019istituzione scolastica nell\u2019integrazione e nella costruzione di una classe dirigente aperta, dinamica e pronta ad affrontare la complessit\u00e0 delle sfide future&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 tenuta presso il centro Forum la cerimonia inaugurale dell&#8217;edizione 2020 di Solidiamo: premiati oltre 1000 studenti<\/p>\n","protected":false},"author":18,"featured_media":50375,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[94,93,639,1205,6105,379],"class_list":["post-50374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-ciociaria","tag-frosinone","tag-nicola-ottaviani","tag-premi","tag-solidiamo","tag-studenti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, Solidiamo: premiati oltre mille studenti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, Solidiamo: premiati oltre mille studenti\" \/>\n<meta property=\"og:description\" content=\"Si \u00e8 tenuta presso il centro Forum la cerimonia inaugurale dell&#039;edizione 2020 di Solidiamo: premiati oltre 1000 studenti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-20T04:02:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-20T04:02:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/solidiamo-2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Frosinone, Solidiamo: premiati oltre mille studenti\",\"datePublished\":\"2020-12-20T04:02:16+00:00\",\"dateModified\":\"2020-12-20T04:02:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/\"},\"wordCount\":574,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/solidiamo-2020.jpg\",\"keywords\":[\"Ciociaria\",\"Frosinone\",\"nicola ottaviani\",\"Premi\",\"Solidiamo\",\"studenti\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/\",\"name\":\"Frosinone, Solidiamo: premiati oltre mille studenti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/solidiamo-2020.jpg\",\"datePublished\":\"2020-12-20T04:02:16+00:00\",\"dateModified\":\"2020-12-20T04:02:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/solidiamo-2020.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/solidiamo-2020.jpg\",\"width\":768,\"height\":520,\"caption\":\"L'edizione 2020 di Solidiamo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, Solidiamo: premiati oltre mille studenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/20\\\/frosinone-solidiamo-premiati-oltre-mille-studenti\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, Solidiamo: premiati oltre mille studenti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, Solidiamo: premiati oltre mille studenti","og_description":"Si \u00e8 tenuta presso il centro Forum la cerimonia inaugurale dell'edizione 2020 di Solidiamo: premiati oltre 1000 studenti","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-12-20T04:02:16+00:00","article_modified_time":"2020-12-20T04:02:17+00:00","og_image":[{"width":768,"height":520,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/solidiamo-2020.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Frosinone, Solidiamo: premiati oltre mille studenti","datePublished":"2020-12-20T04:02:16+00:00","dateModified":"2020-12-20T04:02:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/"},"wordCount":574,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/solidiamo-2020.jpg","keywords":["Ciociaria","Frosinone","nicola ottaviani","Premi","Solidiamo","studenti"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/","name":"Frosinone, Solidiamo: premiati oltre mille studenti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/solidiamo-2020.jpg","datePublished":"2020-12-20T04:02:16+00:00","dateModified":"2020-12-20T04:02:17+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/solidiamo-2020.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/solidiamo-2020.jpg","width":768,"height":520,"caption":"L'edizione 2020 di Solidiamo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, Solidiamo: premiati oltre mille studenti"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/20\/frosinone-solidiamo-premiati-oltre-mille-studenti\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/50374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=50374"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/50374\/revisions"}],"predecessor-version":[{"id":50376,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/50374\/revisions\/50376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/50375"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=50374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=50374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=50374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}