{"id":49724,"date":"2020-12-05T12:55:31","date_gmt":"2020-12-05T11:55:31","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=49724"},"modified":"2020-12-05T13:41:46","modified_gmt":"2020-12-05T12:41:46","slug":"incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/","title":{"rendered":"Incontro tra Pd e ministro Amendola, Fantini: grandi opportunit\u00e0 per il territorio dal Next Generation Eu"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>&#8220;L\u2019incontro di oggi inaugura un ciclo di iniziative online ideato con la segreteria provinciale per coinvolgere attori istituzionali, realt\u00e0 politiche e associative, sigle sindacal<\/strong>i e tutta una serie di soggetti rappresentativi della societ\u00e0 civile al fine di ascoltare le istanze che provengono del nostro territorio in questo difficile momento. Abbiamo aperto questa serie di incontri parlando di Europa. <strong>Cos\u00ec il segretario provinciale del Partito Democratico Luca Fantini in occasione dell\u2019incontro \u2018Next Generation Eu, opportunit\u00e0 e prospettive per il nostro territorio\u2019.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Il motivo \u00e8 semplice: dal piano europeo per la ripresa e dal prossimo Quadro Finanziario Pluriennale provengono le risorse e le speranze pi\u00f9 concrete per attuare un vero cambiamento, per operare una radicale transizione verde e digitale e per attuare una svolta senza precedenti. <strong>Mi permetto di dire &#8211; evidenzia Fantini che il successo di questo piano \u00e8 un risultato straordinario voluto fortemente dal nostro Governo<\/strong>. Il mio grazie al Ministro Amendola per aver chiarito quelle che sono le grandi opportunit\u00e0, anche per la nostra provincia, derivanti dall\u2019attuazione del Piano Europeo per la Ripresa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201c<strong>Dall\u2019approvazione del Bilancio e dal Recovery Fund \u2013 ha detto durante la diretta il Ministro Amendola <\/strong>&#8211; provengono risorse essenziali per la transizione verde e digitale, per lo sviluppo dei territori e per la coesione sociale. L\u2019Italia avr\u00e0 209 miliardi da Next Generation Eu e circa 100 miliardi dal Bilancio europeo: soldi per l\u2019agricoltura, per i Fondi coesione, per il lavoro, la sicurezza, l\u2019istruzione. Abbiamo due grandi possibilit\u00e0 sulle quali lavorare per il rilancio del Paese e dei territori. Regioni e Comuni avranno un ruolo centrale per l\u2019individuazione delle priorit\u00e0 del Piano nazionale di Ripresa e Resilienza\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;L\u2019incontro di oggi inaugura un ciclo di iniziative online ideato con la segreteria provinciale per coinvolgere attori istituzionali, realt\u00e0 politiche<\/p>\n","protected":false},"author":18,"featured_media":49728,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[94,3067,3880,12000,98,12001],"class_list":["post-49724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-ciociaria","tag-la-provincia-quotidiano","tag-luca-fantini","tag-ministro-amendola","tag-pd","tag-piano-europeo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Incontro tra Pd e ministro Amendola, Fantini: grandi opportunit\u00e0 per il territorio dal Next Generation Eu - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incontro tra Pd e ministro Amendola, Fantini: grandi opportunit\u00e0 per il territorio dal Next Generation Eu\" \/>\n<meta property=\"og:description\" content=\"&#8220;L\u2019incontro di oggi inaugura un ciclo di iniziative online ideato con la segreteria provinciale per coinvolgere attori istituzionali, realt\u00e0 politiche\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-05T11:55:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-05T12:41:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/Luca-Fantini-Amendola-800x445-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Incontro tra Pd e ministro Amendola, Fantini: grandi opportunit\u00e0 per il territorio dal Next Generation Eu\",\"datePublished\":\"2020-12-05T11:55:31+00:00\",\"dateModified\":\"2020-12-05T12:41:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/\"},\"wordCount\":291,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/Luca-Fantini-Amendola-800x445-1.jpg\",\"keywords\":[\"Ciociaria\",\"La provincia quotidiano\",\"Luca Fantini\",\"Ministro amendola\",\"Pd\",\"Piano europeo\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/\",\"name\":\"Incontro tra Pd e ministro Amendola, Fantini: grandi opportunit\u00e0 per il territorio dal Next Generation Eu - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/Luca-Fantini-Amendola-800x445-1.jpg\",\"datePublished\":\"2020-12-05T11:55:31+00:00\",\"dateModified\":\"2020-12-05T12:41:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/Luca-Fantini-Amendola-800x445-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/Luca-Fantini-Amendola-800x445-1.jpg\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incontro tra Pd e ministro Amendola, Fantini: grandi opportunit\u00e0 per il territorio dal Next Generation Eu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/05\\\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Incontro tra Pd e ministro Amendola, Fantini: grandi opportunit\u00e0 per il territorio dal Next Generation Eu - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/","og_locale":"it_IT","og_type":"article","og_title":"Incontro tra Pd e ministro Amendola, Fantini: grandi opportunit\u00e0 per il territorio dal Next Generation Eu","og_description":"&#8220;L\u2019incontro di oggi inaugura un ciclo di iniziative online ideato con la segreteria provinciale per coinvolgere attori istituzionali, realt\u00e0 politiche","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-12-05T11:55:31+00:00","article_modified_time":"2020-12-05T12:41:46+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/Luca-Fantini-Amendola-800x445-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Incontro tra Pd e ministro Amendola, Fantini: grandi opportunit\u00e0 per il territorio dal Next Generation Eu","datePublished":"2020-12-05T11:55:31+00:00","dateModified":"2020-12-05T12:41:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/"},"wordCount":291,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/Luca-Fantini-Amendola-800x445-1.jpg","keywords":["Ciociaria","La provincia quotidiano","Luca Fantini","Ministro amendola","Pd","Piano europeo"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/","name":"Incontro tra Pd e ministro Amendola, Fantini: grandi opportunit\u00e0 per il territorio dal Next Generation Eu - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/Luca-Fantini-Amendola-800x445-1.jpg","datePublished":"2020-12-05T11:55:31+00:00","dateModified":"2020-12-05T12:41:46+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/Luca-Fantini-Amendola-800x445-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/Luca-Fantini-Amendola-800x445-1.jpg","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Incontro tra Pd e ministro Amendola, Fantini: grandi opportunit\u00e0 per il territorio dal Next Generation Eu"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/05\/incontro-tra-pd-e-ministro-amendola-fantini-grandi-opportunita-per-il-territorio-dal-piano-europeo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/49724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=49724"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/49724\/revisions"}],"predecessor-version":[{"id":49729,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/49724\/revisions\/49729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/49728"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=49724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=49724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=49724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}