{"id":49513,"date":"2020-12-01T15:31:56","date_gmt":"2020-12-01T14:31:56","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=49513"},"modified":"2020-12-01T15:45:07","modified_gmt":"2020-12-01T14:45:07","slug":"cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/","title":{"rendered":"Cassino, &#8216;Welcome to Italy&#8217;: 5  consiglieri chiedono che il Comune si costituisca parte civile per danno d&#8217;immagine"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;<strong>Nei giorni scorsi il GIP del Tribunale di Cassino, dottoressa Vittoria Sodani, ha disposto il rinvio a giudizio per 22 indagati, <\/strong>ora imputati, nell\u2019indagine denominata &#8216;Welcome to Italy&#8217;, fissando l\u2019udienza del 13 aprile 2021, dinanzi al Tribunale Penale di Cassino. La notizia del rinvio a giudizio ha destato ancora una volta grande risalto mediatico, dopo quelle del febbraio 2017, allorquando la Procura della Repubblica richiedeva la proroga del termine per le indagini, e quella dell\u2019ottobre 2019, a seguito dell\u2019 avviso di conclusione delle indagini&#8221;.<strong>  <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lo evidenziano i consiglieri comunali Giuseppe Golini Petrarcone, Francesco Evangelista, Massimiliano Mignanelli, Luca Fardelli e Salvatore Fontana, <\/strong>sollecitando l&#8217;inserimento di uno specifico punto all&#8217;ordine del giorno del consiglio comunale per richiedere la costituzione di parte civile del Comune nei confronti degli imputati.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"> <strong>&#8220;Il clamore destato dalle risultanze di dette indagini &#8211; fanno notare &#8211; \u00e8 da ricondurre non solo alla gravit\u00e0 dei reati contestati,<\/strong> ma anche al coinvolgimento degli odierni imputati, alcuni dei quali hanno ricoperto ruoli di primaria importanza e responsabilit\u00e0 nel Comune di Cassino, nonch\u00e9 in enti ad esso collegati. Di tale viceda  &#8211; argomentano &#8211; si \u00e8 occupata  non solo la stampa e gli organi di informazione locali, ma anche&nbsp; quotidiani a tiratura nazionale (V. \u201cLa Repubblica\u201d del 28\/11\/2020). <strong> Il clamore suscitato da queste notizie &#8211; proseguono &#8211; nuoce oltremodo all\u2019immagine della Citt\u00e0 di Cassino,&nbsp;<\/strong> ed inevitabilmente alle istituzioni che la rappresentano, non senza avere delle ripercussioni sul tessuto economico del territorio&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;I danni d\u2019immagine alla nostra citt\u00e0 sono aggravati dalle altre notizie di questi giorni su altre due inchieste<\/strong> che vedono coinvolti 12 indagati, fra cui un consigliere comunale, per reati di falso nella presentazione di una lista risultata vincente nella competizione elettorale comunale del 2019 e di corruzione elettorale, sempre riferita a quella tornata elettorale&#8221;. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;invito<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Per procedere alla costituzione di parte civile &#8211;  concludono  &#8211; l\u2019unico organo competente e deputato \u00e8 il Consiglio Comunale di Cassino<\/strong>. Per questo chiediamo al Presidente del Consiglio Comunale&nbsp; la convocazione del prossimo Consiglio Comunale, inserendo come primo punto all\u2019ordine del giorno: discussione e votazione sula costituzione di parte civile del Comune di Cassino come parte lesa e danneggiata nel procedimento penale fissato per il prossimo 13 aprile 2021 nei confronti dei 22 imputati dell\u2019indagine  Welcome to Italy&#8221;. <\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Nei giorni scorsi il GIP del Tribunale di Cassino, dottoressa Vittoria Sodani, ha disposto il rinvio a giudizio per 22<\/p>\n","protected":false},"author":18,"featured_media":20143,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[216,94,93,3510,3858,5498,3843,6815],"class_list":["post-49513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-cassino","tag-ciociaria","tag-frosinone","tag-giuseppe-golini-petrarcone","tag-luca-fardelli","tag-massimiliano-mignanelli","tag-salvatore-fontana","tag-welcome-to-italy"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cassino, &#039;Welcome to Italy&#039;: 5 consiglieri chiedono che il Comune si costituisca parte civile per danno d&#039;immagine - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cassino, &#039;Welcome to Italy&#039;: 5 consiglieri chiedono che il Comune si costituisca parte civile per danno d&#039;immagine\" \/>\n<meta property=\"og:description\" content=\"&#8220;Nei giorni scorsi il GIP del Tribunale di Cassino, dottoressa Vittoria Sodani, ha disposto il rinvio a giudizio per 22\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-01T14:31:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-01T14:45:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/fardelli-petrarcone-fontana-mignanelli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Cassino, &#8216;Welcome to Italy&#8217;: 5 consiglieri chiedono che il Comune si costituisca parte civile per danno d&#8217;immagine\",\"datePublished\":\"2020-12-01T14:31:56+00:00\",\"dateModified\":\"2020-12-01T14:45:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/\"},\"wordCount\":392,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/fardelli-petrarcone-fontana-mignanelli.jpg\",\"keywords\":[\"Cassino\",\"Ciociaria\",\"Frosinone\",\"Giuseppe Golini Petrarcone\",\"Luca Fardelli\",\"Massimiliano Mignanelli\",\"Salvatore Fontana\",\"Welcome to Italy\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/\",\"name\":\"Cassino, 'Welcome to Italy': 5 consiglieri chiedono che il Comune si costituisca parte civile per danno d'immagine - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/fardelli-petrarcone-fontana-mignanelli.jpg\",\"datePublished\":\"2020-12-01T14:31:56+00:00\",\"dateModified\":\"2020-12-01T14:45:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/fardelli-petrarcone-fontana-mignanelli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/fardelli-petrarcone-fontana-mignanelli.jpg\",\"width\":960,\"height\":540,\"caption\":\"Fardelli, Petrarcone, Mignanelle e Fontana\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cassino, &#8216;Welcome to Italy&#8217;: 5 consiglieri chiedono che il Comune si costituisca parte civile per danno d&#8217;immagine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/12\\\/01\\\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cassino, 'Welcome to Italy': 5 consiglieri chiedono che il Comune si costituisca parte civile per danno d'immagine - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/","og_locale":"it_IT","og_type":"article","og_title":"Cassino, 'Welcome to Italy': 5 consiglieri chiedono che il Comune si costituisca parte civile per danno d'immagine","og_description":"&#8220;Nei giorni scorsi il GIP del Tribunale di Cassino, dottoressa Vittoria Sodani, ha disposto il rinvio a giudizio per 22","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-12-01T14:31:56+00:00","article_modified_time":"2020-12-01T14:45:07+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/fardelli-petrarcone-fontana-mignanelli.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Cassino, &#8216;Welcome to Italy&#8217;: 5 consiglieri chiedono che il Comune si costituisca parte civile per danno d&#8217;immagine","datePublished":"2020-12-01T14:31:56+00:00","dateModified":"2020-12-01T14:45:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/"},"wordCount":392,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/fardelli-petrarcone-fontana-mignanelli.jpg","keywords":["Cassino","Ciociaria","Frosinone","Giuseppe Golini Petrarcone","Luca Fardelli","Massimiliano Mignanelli","Salvatore Fontana","Welcome to Italy"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/","name":"Cassino, 'Welcome to Italy': 5 consiglieri chiedono che il Comune si costituisca parte civile per danno d'immagine - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/fardelli-petrarcone-fontana-mignanelli.jpg","datePublished":"2020-12-01T14:31:56+00:00","dateModified":"2020-12-01T14:45:07+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/fardelli-petrarcone-fontana-mignanelli.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/fardelli-petrarcone-fontana-mignanelli.jpg","width":960,"height":540,"caption":"Fardelli, Petrarcone, Mignanelle e Fontana"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Cassino, &#8216;Welcome to Italy&#8217;: 5 consiglieri chiedono che il Comune si costituisca parte civile per danno d&#8217;immagine"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/12\/01\/cassino-welcome-to-italy-5-consiglieri-chiedono-che-il-comune-si-costituisca-parte-civile-per-danno-dimmagine\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/49513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=49513"}],"version-history":[{"count":9,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/49513\/revisions"}],"predecessor-version":[{"id":49522,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/49513\/revisions\/49522"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=49513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=49513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=49513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}