{"id":49215,"date":"2020-11-25T16:58:45","date_gmt":"2020-11-25T15:58:45","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=49215"},"modified":"2020-11-25T17:00:55","modified_gmt":"2020-11-25T16:00:55","slug":"violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/","title":{"rendered":"Violenze sulle donne, Ruspandini (FdI): la giornata internazionale sia occasione per ricordare &#8216;marocchinate&#8217;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cLa Giornata internazionale per l\u2019eliminazione delle violenze sulle donne sia anche l\u2019occasione per ricordare quelle migliaia di donne stuprate e uccise nel corso della Seconda guerra mondiale dalle truppe coloniali francesi aggregate agli Alleati&#8221;.<strong> Lo dichiara il senatore di Fratelli d\u2019Italia, Massimo Ruspandini.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le tristi e note \u2018marocchinate\u2019 raccontano il dramma di tantissime donne vittime della brutalit\u00e0 e della violenza di uomini senza scrupoli e senza dignit\u00e0<\/strong>, che inferirono su chi non poteva difendersi dalla loro bestialit\u00e0. Per troppo tempo, e ancora oggi, questa triste e drammatica pagina di storia nazionale \u00e8 stata tenuta nascosta, sacrificata sull\u2019altare del politicamente corretto e del conformismo dilagante marchiando addirittura d\u2019infamia queste donne. <strong>In questa Giornata credo che sia necessario e doveroso ricordare anche questo dramma subito da migliaia di donne italiane <\/strong>e per fare in modo che non si continui pi\u00f9 nell\u2019ignobile rimozione di questi tragici eventi che dura da oltre mezzo secolo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa Giornata internazionale per l\u2019eliminazione delle violenze sulle donne sia anche l\u2019occasione per ricordare quelle migliaia di donne stuprate e<\/p>\n","protected":false},"author":18,"featured_media":48732,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[94,2961,93,3527,11906,3642,3923],"class_list":["post-49215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-ciociaria","tag-fdi","tag-frosinone","tag-massimo-ruspandini","tag-narocchinate","tag-senatore","tag-violenza-sulle-donne"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Violenze sulle donne, Ruspandini (FdI): la giornata internazionale sia occasione per ricordare &#039;marocchinate&#039; - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Violenze sulle donne, Ruspandini (FdI): la giornata internazionale sia occasione per ricordare &#039;marocchinate&#039;\" \/>\n<meta property=\"og:description\" content=\"\u201cLa Giornata internazionale per l\u2019eliminazione delle violenze sulle donne sia anche l\u2019occasione per ricordare quelle migliaia di donne stuprate e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-25T15:58:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-25T16:00:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/ruspandini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"663\" \/>\n\t<meta property=\"og:image:height\" content=\"434\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Violenze sulle donne, Ruspandini (FdI): la giornata internazionale sia occasione per ricordare &#8216;marocchinate&#8217;\",\"datePublished\":\"2020-11-25T15:58:45+00:00\",\"dateModified\":\"2020-11-25T16:00:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/\"},\"wordCount\":170,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/ruspandini.jpg\",\"keywords\":[\"Ciociaria\",\"fdI\",\"Frosinone\",\"massimo ruspandini\",\"narocchinate\",\"senatore\",\"Violenza sulle donne\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/\",\"name\":\"Violenze sulle donne, Ruspandini (FdI): la giornata internazionale sia occasione per ricordare 'marocchinate' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/ruspandini.jpg\",\"datePublished\":\"2020-11-25T15:58:45+00:00\",\"dateModified\":\"2020-11-25T16:00:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/ruspandini.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/ruspandini.jpg\",\"width\":663,\"height\":434},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Violenze sulle donne, Ruspandini (FdI): la giornata internazionale sia occasione per ricordare &#8216;marocchinate&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/25\\\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Violenze sulle donne, Ruspandini (FdI): la giornata internazionale sia occasione per ricordare 'marocchinate' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/","og_locale":"it_IT","og_type":"article","og_title":"Violenze sulle donne, Ruspandini (FdI): la giornata internazionale sia occasione per ricordare 'marocchinate'","og_description":"\u201cLa Giornata internazionale per l\u2019eliminazione delle violenze sulle donne sia anche l\u2019occasione per ricordare quelle migliaia di donne stuprate e","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-11-25T15:58:45+00:00","article_modified_time":"2020-11-25T16:00:55+00:00","og_image":[{"width":663,"height":434,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/ruspandini.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Violenze sulle donne, Ruspandini (FdI): la giornata internazionale sia occasione per ricordare &#8216;marocchinate&#8217;","datePublished":"2020-11-25T15:58:45+00:00","dateModified":"2020-11-25T16:00:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/"},"wordCount":170,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/ruspandini.jpg","keywords":["Ciociaria","fdI","Frosinone","massimo ruspandini","narocchinate","senatore","Violenza sulle donne"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/","name":"Violenze sulle donne, Ruspandini (FdI): la giornata internazionale sia occasione per ricordare 'marocchinate' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/ruspandini.jpg","datePublished":"2020-11-25T15:58:45+00:00","dateModified":"2020-11-25T16:00:55+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/ruspandini.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/ruspandini.jpg","width":663,"height":434},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Violenze sulle donne, Ruspandini (FdI): la giornata internazionale sia occasione per ricordare &#8216;marocchinate&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/25\/violenze-sulle-donne-ruspandini-fdi-la-giornata-internazionale-sia-occasione-per-ricordare-marocchinate\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/49215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=49215"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/49215\/revisions"}],"predecessor-version":[{"id":49219,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/49215\/revisions\/49219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/48732"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=49215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=49215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=49215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}