{"id":49075,"date":"2020-11-24T14:50:27","date_gmt":"2020-11-24T13:50:27","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=49075"},"modified":"2020-11-25T12:20:37","modified_gmt":"2020-11-25T11:20:37","slug":"camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/","title":{"rendered":"Camera di Commercio Frosinone-Latina, eletta la nuova giunta"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Oggi si \u00e8 riunito a Latina presso la Sala Mignano della Camera di Commercio il <strong>Consiglio Camerale<\/strong>&nbsp;per l\u2019elezione della nuova Giunta.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"580\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/acampora-giovanni-la-provincia-1024x580.jpg\" alt=\"\" class=\"wp-image-47473\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/acampora-giovanni-la-provincia-1024x580.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/acampora-giovanni-la-provincia-300x170.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/acampora-giovanni-la-provincia-768x435.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/acampora-giovanni-la-provincia.jpg 1265w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento del presidente<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cSi apre il primo capitolo di un nuovo libro \u2013 commenta il Presidente Acampora &#8211; Oggi inizia il lavoro di una squadra che abbiamo voluto altamente qualificata e rappresentativa<\/strong> di tutte le imprese, nella pi\u00f9 ampia condivisione con il sistema associativo. Il percorso che ci ha portato a questo risultato non \u00e8 stato certamente facile, ma \u00e8 frutto della condivisione d\u2019intenti da parte di tutte le associazioni, in un gioco di squadra che vedr\u00e0 organizzazioni insieme ad altre importanti realt\u00e0 associative fornire il proprio apporto di competenze e professionalit\u00e0 nella gestione di organismi partecipati quali la costituenda Azienda Speciale unica in cui, in particolare, Confagricoltura dovr\u00e0 ricoprire un ruolo strategico per le politiche camerali&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Questa Giunta si dimostrer\u00e0 affiatata e unita nell\u2019attuazione delle linee strategiche camerali e sapr\u00e0 muoversi in stretta collaborazione<\/strong> non solo con le associazioni datoriali, le organizzazioni sindacali, le associazioni dei consumatori e gli ordini professionali, ma anche con tutte le istituzioni, perch\u00e9 solo cos\u00ec sar\u00e0 possibile incidere positivamente sul sistema economico dei nostri territori. Ci metteremo subito al lavoro, dato l\u2019eccezionalit\u00e0 del momento che ci impone scelte rapide ed incisive, per inaugurare una stagione nuova e contribuire alla costruzione di una nuova fase di sviluppo; occorre mettere in campo una serie di progetti e bisogna farlo con la pi\u00f9 ampia partecipazione e condivisione possibile, ciascuno sar\u00e0 portatore di idee e di contributi operativi per la crescita del sistema imprenditoriale nel rispetto dei diversi settori produttivi che contraddistinguono le due provincie. Solo con un modello di governance condiviso, inclusivo, innovativo e partecipativo, che necessariamente deve superare le legittime ambizioni e campanilismi vari puntando sul lavoro e le competenze, potremmo mettere in campo iniziative a tutela delle nostre imprese e del nostro territorio\u201d.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ecco i membri<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Questa la squadra che accompagner\u00e0 il Presidente Giovanni Acampora:  D\u2019Amico Guido (Confimprese) \u2013 Servizi alle imprese; Di Cecca Salvatore (Confcommercio Lazio Sud) \u2013 Altri settori; Marini Paolo (Unindustria) \u2013 Industria; Peduto Cosimo (Confesercenti) \u2013 Commercio; Proia Giovanni (CNA) \u2013 Artigianato; Scappaticci Cristina (Coldiretti) \u2013 Agricoltura; Cianfrocca Luciano (Federlazio) \u2013 Settore trasporti e spedizioni;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Con l\u2019elezione della Giunta \u00e8 stata completata la procedura di costituzione degli organi dell\u2019Ente camerale<\/strong> che rimarranno in carica per il quinquennio 2020-2025 e che a breve si riuniranno per la programmazione dell\u2019attivit\u00e0 per l\u2019anno 2021, con l\u2019adozione del programma pluriennale di attivit\u00e0 e il bilancio preventivo, atti di programmazione generale in cui saranno individuati i progetti e le iniziative da realizzare a sostegno delle imprese dei territori di Frosinone e Latina.<br><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Oggi si \u00e8 riunito a Latina presso la Sala Mignano della Camera di Commercio il Consiglio Camerale&nbsp;per l\u2019elezione della nuova<\/p>\n","protected":false},"author":18,"featured_media":49102,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[849,93,256,513,8166],"class_list":["post-49075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-economia","tag-camera-commercio","tag-frosinone","tag-giunta","tag-latina","tag-pontino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Camera di Commercio Frosinone-Latina, eletta la nuova giunta - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camera di Commercio Frosinone-Latina, eletta la nuova giunta\" \/>\n<meta property=\"og:description\" content=\"Oggi si \u00e8 riunito a Latina presso la Sala Mignano della Camera di Commercio il Consiglio Camerale&nbsp;per l\u2019elezione della nuova\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-24T13:50:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-25T11:20:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/Giunta-camerale-696x464-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"464\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Camera di Commercio Frosinone-Latina, eletta la nuova giunta\",\"datePublished\":\"2020-11-24T13:50:27+00:00\",\"dateModified\":\"2020-11-25T11:20:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/\"},\"wordCount\":446,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/Giunta-camerale-696x464-1.jpg\",\"keywords\":[\"Camera Commercio\",\"Frosinone\",\"giunta\",\"latina\",\"pontino\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/\",\"name\":\"Camera di Commercio Frosinone-Latina, eletta la nuova giunta - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/Giunta-camerale-696x464-1.jpg\",\"datePublished\":\"2020-11-24T13:50:27+00:00\",\"dateModified\":\"2020-11-25T11:20:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/Giunta-camerale-696x464-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/Giunta-camerale-696x464-1.jpg\",\"width\":696,\"height\":464},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camera di Commercio Frosinone-Latina, eletta la nuova giunta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/24\\\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Camera di Commercio Frosinone-Latina, eletta la nuova giunta - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/","og_locale":"it_IT","og_type":"article","og_title":"Camera di Commercio Frosinone-Latina, eletta la nuova giunta","og_description":"Oggi si \u00e8 riunito a Latina presso la Sala Mignano della Camera di Commercio il Consiglio Camerale&nbsp;per l\u2019elezione della nuova","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-11-24T13:50:27+00:00","article_modified_time":"2020-11-25T11:20:37+00:00","og_image":[{"width":696,"height":464,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/Giunta-camerale-696x464-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Camera di Commercio Frosinone-Latina, eletta la nuova giunta","datePublished":"2020-11-24T13:50:27+00:00","dateModified":"2020-11-25T11:20:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/"},"wordCount":446,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/Giunta-camerale-696x464-1.jpg","keywords":["Camera Commercio","Frosinone","giunta","latina","pontino"],"articleSection":["*PRIMO PIANO*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/","name":"Camera di Commercio Frosinone-Latina, eletta la nuova giunta - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/Giunta-camerale-696x464-1.jpg","datePublished":"2020-11-24T13:50:27+00:00","dateModified":"2020-11-25T11:20:37+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/Giunta-camerale-696x464-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/Giunta-camerale-696x464-1.jpg","width":696,"height":464},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Camera di Commercio Frosinone-Latina, eletta la nuova giunta"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/24\/camera-di-commercio-frosinone-latina-eletta-la-nuova-giunta\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/49075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=49075"}],"version-history":[{"count":11,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/49075\/revisions"}],"predecessor-version":[{"id":49183,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/49075\/revisions\/49183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/49102"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=49075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=49075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=49075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}