{"id":48217,"date":"2020-11-09T12:40:41","date_gmt":"2020-11-09T11:40:41","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=48217"},"modified":"2020-11-09T18:00:13","modified_gmt":"2020-11-09T17:00:13","slug":"ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/","title":{"rendered":"Ecosistema urbano, Frosinone 72esima provincia in Italia nella classifica di Legambiente"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Legambiente ha pubblicato Ecosistema urbano 2020, lo studio sulle performance ambientali e vivibilit\u00e0 dei capoluoghi<\/strong> su dati 2019. Il dossier esamina informazioni fornite da amministrazioni e altre fonti e i punteggi vengono assegnati sulla base di 18 indicatori in sei aree tematiche: aria, acqua, rifiuti, mobilit\u00e0, ambiente urbano, energia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;analisi<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La situazione per i capoluoghi del Lazio non \u00e8 delle migliori a partire da Roma <\/strong>che per il secondo anno consecutivo \u00e8 all\u201989esima\u00a0posizione generale, in fondo alla classica per le scarse performance ambientali; peggio, nel Lazio fa solo Latina 98esima.<strong> Rieti \u00e8 38esima Viterbo \u00e8 in 71esima\u00a0posizione, mentre Frosinone si attesta alla 72esima<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nella Capitale sono scarsi i risultati nella gestione del ciclo dei rifiuti, con una raccolta differenziata che arriva al 45,5% e che sale di appena 2,6 punti percentuali negli ultimi 4 anni, si contrae gravemente la diffusione del porta a porta e la produzione pro-capite di rifiuti continua ad essere tra le pi\u00f9 alte in Italia. A un trasporto pubblico in condizioni disarmanti, con mezzi sempre pi\u00f9 lenti e un servizio pubblico in profonda crisi, consegue un\u2019aumento delle vetture immatricolate (+17mila&nbsp;negli ultimi 5 anni) e una qualit\u00e0 dell\u2019aria scarsa con Biossido di Azoto (NO2) in eccesso, 43,5 microgrammi per metro cubo di aria, su tale parametro Roma \u00e8 al quintultimo posto nazionale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa capitale \u00e8 piantata in fondo alla classifica tra le citt\u00e0 italiane per le sue pessime performance ambientali \u2013 <strong>commenta Roberto Scacchi presidente di Legambiente Lazio \u2013<\/strong> A Roma ci sono i numeri di una gestione terribile dei rifiuti che ha portato, negli ultimi quattro anni, a una crescita della differenziata ridicola, a una riduzione nella diffusione del porta a porta e a nessun impianto di gestione dell\u2019economia circolare. La condizione del trasporto pubblico \u00e8 poi al tracollo, non in grado di garantire distanziamento come vediamo quotidianamente, con le troppe auto in circolazione \u00e8 sempre scarsa qualit\u00e0 dell\u2019aria. Per una svolta positiva bisogna costruire un\u2019idea di futuro della capitale che ponga concretamente lo sviluppo sostenibile come pietra angolare dei prossimi anni, per affrontare le sfide dell\u2019emergenza sanitaria, della crisi economica e della crisi climatica, ponendo la vivibilit\u00e0 e l\u2019ambiente al centro delle scelte\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>In classifica migliorano sia Rieti sia Frosinone soprattutto grazie all\u2019aumento della percentuale di differenziata che a Rieti arriva al 56,8% e a Frosinone al 71,1%.<\/strong> Dal capitolo acqua e gestione del servizio idrico altre note negative per Roma che con 165 litri\/abitante\/anno ha il pi\u00f9 alto livello di consumi idrici nel Lazio e tra i pi\u00f9 alti in Italia, e resta eccessiva anche la dispersione dell\u2019acqua nelle tubature colabrodo con il 38% a Roma e provincia.<strong> Sono invece gravissimi i numeri della dispersione a Frosinone e provincia <\/strong>dove si perde nelle reti colabrodo il 77,8% dell\u2019acqua immessa, peggior dato nazionale assoluto; cos\u00ec come a Latina e provincia, terza assoluta in Italia con 70,3% di dispersione, entrambe le situazioni sono in colpevole peggioramento nell\u2019ultimo anno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cSe ci sono segni positivi in alcuni capoluoghi del Lazio, dove vediamo finalmente crescere le percentuali di differenziata, \u00e8 sempre pi\u00f9 grave la situazione della dispersione idrica<\/strong> nelle reti colabrodo in provincia di Latina e Frosinone dove \u2013 conclude Scacchi \u2013 su 5 litri di acqua potabile immessi nelle reti, si perdono negli acquedotti colabrodo quasi 4 litri, numeri scandalosi che peggiorano colpevolmente. Oggi per\u00f2 premiamo anche 3 Best Practices ambientali nel Lazio, perch\u00e9 da queste straordinarie esperienze si possa partire nella salvaguardia del territorio, nello sviluppo sostenibile e nell\u2019economia circolare e civile\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Legambiente ha pubblicato Ecosistema urbano 2020, lo studio sulle performance ambientali e vivibilit\u00e0 dei capoluoghi su dati 2019. Il dossier<\/p>\n","protected":false},"author":18,"featured_media":48218,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[179,94,11723,93,10561,174],"class_list":["post-48217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-acqua","tag-ciociaria","tag-ecosistema-urbano","tag-frosinone","tag-la-provincia-quotidfiano","tag-legambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ecosistema urbano, Frosinone 72esima provincia in Italia nella classifica di Legambiente - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecosistema urbano, Frosinone 72esima provincia in Italia nella classifica di Legambiente\" \/>\n<meta property=\"og:description\" content=\"Legambiente ha pubblicato Ecosistema urbano 2020, lo studio sulle performance ambientali e vivibilit\u00e0 dei capoluoghi su dati 2019. Il dossier\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-09T11:40:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-09T17:00:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/legambiente-bis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"823\" \/>\n\t<meta property=\"og:image:height\" content=\"477\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Ecosistema urbano, Frosinone 72esima provincia in Italia nella classifica di Legambiente\",\"datePublished\":\"2020-11-09T11:40:41+00:00\",\"dateModified\":\"2020-11-09T17:00:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/\"},\"wordCount\":578,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/legambiente-bis.jpg\",\"keywords\":[\"acqua\",\"Ciociaria\",\"ecosistema urbano\",\"Frosinone\",\"la provincia quotidfiano\",\"Legambiente\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/\",\"name\":\"Ecosistema urbano, Frosinone 72esima provincia in Italia nella classifica di Legambiente - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/legambiente-bis.jpg\",\"datePublished\":\"2020-11-09T11:40:41+00:00\",\"dateModified\":\"2020-11-09T17:00:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/legambiente-bis.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/legambiente-bis.jpg\",\"width\":823,\"height\":477},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecosistema urbano, Frosinone 72esima provincia in Italia nella classifica di Legambiente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/09\\\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ecosistema urbano, Frosinone 72esima provincia in Italia nella classifica di Legambiente - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/","og_locale":"it_IT","og_type":"article","og_title":"Ecosistema urbano, Frosinone 72esima provincia in Italia nella classifica di Legambiente","og_description":"Legambiente ha pubblicato Ecosistema urbano 2020, lo studio sulle performance ambientali e vivibilit\u00e0 dei capoluoghi su dati 2019. Il dossier","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-11-09T11:40:41+00:00","article_modified_time":"2020-11-09T17:00:13+00:00","og_image":[{"width":823,"height":477,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/legambiente-bis.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Ecosistema urbano, Frosinone 72esima provincia in Italia nella classifica di Legambiente","datePublished":"2020-11-09T11:40:41+00:00","dateModified":"2020-11-09T17:00:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/"},"wordCount":578,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/legambiente-bis.jpg","keywords":["acqua","Ciociaria","ecosistema urbano","Frosinone","la provincia quotidfiano","Legambiente"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/","name":"Ecosistema urbano, Frosinone 72esima provincia in Italia nella classifica di Legambiente - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/legambiente-bis.jpg","datePublished":"2020-11-09T11:40:41+00:00","dateModified":"2020-11-09T17:00:13+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/legambiente-bis.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/legambiente-bis.jpg","width":823,"height":477},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ecosistema urbano, Frosinone 72esima provincia in Italia nella classifica di Legambiente"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/09\/ecosistema-urbano-frosinone-72esima-provincia-in-italia-nella-classifica-di-legambiente\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/48217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=48217"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/48217\/revisions"}],"predecessor-version":[{"id":48219,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/48217\/revisions\/48219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/48218"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=48217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=48217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=48217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}