{"id":47909,"date":"2020-11-04T13:04:26","date_gmt":"2020-11-04T12:04:26","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=47909"},"modified":"2020-11-04T14:55:16","modified_gmt":"2020-11-04T13:55:16","slug":"nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/","title":{"rendered":"Nuovo manager Asl, Buschini augura buon lavoro a Pierpaola D&#8217;Alessandro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>&#8220;Rivolgo i miei auguri di buon lavoro al neo direttore generale della Asl di Frosinone, Pierpaola D&#8217;Alessandro.<\/strong> Ritengo che la Regione Lazio abbia fatto un&#8217;ottima scelta, ovvero quella di puntare su una donna competente, per la quale parla il suo curriculum, con spiccate qualit\u00e0 dirigenziali e una chiara attitudine a favorire lo spirito di squadra e la condivisione&#8221;. <strong>Cos\u00ec  il Presidente del Consiglio regionale del Lazio, Mauro Buschini.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;La dottoressa D&#8217;Alessandro \u00e8 ben consapevole del lavoro che va portato avanti per la Provincia di Frosinone,<\/strong> conosce gi\u00e0 l&#8217;azienda e in questi mesi ha gi\u00e0 individuato eccellenze e criticit\u00e0 sulle quali intervenire. Abbiamo gi\u00e0 sperimentato le sue doti manageriali e umane durante la prima ondata del covid, sono certo che sapr\u00e0 dialogare con il territorio, a partire dai sindaci, che vanno messi nelle migliori condizioni di affrontare le tante difficolt\u00e0 per contrastare il virus&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Occorre, oggi pi\u00f9 che mai, un grande lavoro di innovazione per favorire il potenziamento dell&#8217;offerta sanitaria territoriale che metta i cittadini al centro di ogni processo. <\/strong>Finalmente, grazie al lavoro di questi anni, si \u00e8 conclusa la fase commissariale della regione in tema di sanit\u00e0. Si \u00e8 aperta la fase degli investimenti, delle assunzioni e del potenziamento dell&#8217;offerta. Occorrer\u00e0 individuare una serie di priorit\u00e0 sulle quali intervenire, a partire dal decongestionamento dei Pronto soccorso e dall&#8217;abbattimento delle liste di attesa. I medici e tutti gli operatori sanitari &#8211; conclude &#8211; stanno profondendo sforzi immani, sar\u00e0 fondamentale metterli nelle giuste condizioni per lavorare al meglio per il bene della nostra comunit\u00e0&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Rivolgo i miei auguri di buon lavoro al neo direttore generale della Asl di Frosinone, Pierpaola D&#8217;Alessandro. Ritengo che la<\/p>\n","protected":false},"author":18,"featured_media":47919,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[958,329,94,415,93,11667],"class_list":["post-47909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salute","tag-asl-frosinone","tag-buschini","tag-ciociaria","tag-dalessandro","tag-frosinone","tag-manager"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nuovo manager Asl, Buschini augura buon lavoro a Pierpaola D&#039;Alessandro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuovo manager Asl, Buschini augura buon lavoro a Pierpaola D&#039;Alessandro\" \/>\n<meta property=\"og:description\" content=\"&#8220;Rivolgo i miei auguri di buon lavoro al neo direttore generale della Asl di Frosinone, Pierpaola D&#8217;Alessandro. Ritengo che la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-04T12:04:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-04T13:55:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/manager-buschini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"719\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Nuovo manager Asl, Buschini augura buon lavoro a Pierpaola D&#8217;Alessandro\",\"datePublished\":\"2020-11-04T12:04:26+00:00\",\"dateModified\":\"2020-11-04T13:55:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/\"},\"wordCount\":270,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/manager-buschini.jpg\",\"keywords\":[\"Asl Frosinone\",\"Buschini\",\"Ciociaria\",\"D'Alessandro\",\"Frosinone\",\"manager\"],\"articleSection\":[\"Salute e Benessere\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/\",\"name\":\"Nuovo manager Asl, Buschini augura buon lavoro a Pierpaola D'Alessandro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/manager-buschini.jpg\",\"datePublished\":\"2020-11-04T12:04:26+00:00\",\"dateModified\":\"2020-11-04T13:55:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/manager-buschini.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/manager-buschini.jpg\",\"width\":719,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuovo manager Asl, Buschini augura buon lavoro a Pierpaola D&#8217;Alessandro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/11\\\/04\\\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nuovo manager Asl, Buschini augura buon lavoro a Pierpaola D'Alessandro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/","og_locale":"it_IT","og_type":"article","og_title":"Nuovo manager Asl, Buschini augura buon lavoro a Pierpaola D'Alessandro","og_description":"&#8220;Rivolgo i miei auguri di buon lavoro al neo direttore generale della Asl di Frosinone, Pierpaola D&#8217;Alessandro. Ritengo che la","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-11-04T12:04:26+00:00","article_modified_time":"2020-11-04T13:55:16+00:00","og_image":[{"width":719,"height":400,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/manager-buschini.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Nuovo manager Asl, Buschini augura buon lavoro a Pierpaola D&#8217;Alessandro","datePublished":"2020-11-04T12:04:26+00:00","dateModified":"2020-11-04T13:55:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/"},"wordCount":270,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/manager-buschini.jpg","keywords":["Asl Frosinone","Buschini","Ciociaria","D'Alessandro","Frosinone","manager"],"articleSection":["Salute e Benessere"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/","name":"Nuovo manager Asl, Buschini augura buon lavoro a Pierpaola D'Alessandro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/manager-buschini.jpg","datePublished":"2020-11-04T12:04:26+00:00","dateModified":"2020-11-04T13:55:16+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/manager-buschini.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/11\/manager-buschini.jpg","width":719,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Nuovo manager Asl, Buschini augura buon lavoro a Pierpaola D&#8217;Alessandro"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/11\/04\/nuovo-manager-asl-buschini-augura-buon-lavoro-a-pierpaola-dalessandro\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/47909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=47909"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/47909\/revisions"}],"predecessor-version":[{"id":47911,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/47909\/revisions\/47911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/47919"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=47909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=47909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=47909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}