{"id":47388,"date":"2020-10-25T08:48:08","date_gmt":"2020-10-25T07:48:08","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=47388"},"modified":"2020-10-25T09:02:57","modified_gmt":"2020-10-25T08:02:57","slug":"valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/","title":{"rendered":"Valle del Sacco, Arpa certifica  criticit\u00e0 e lungaggini. Magliocchetti: subito un commissario straordinario"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;<strong>L\u2019Arpa ha pubblicato in queste ore, sul proprio sito istituzionale, il Rapporto 2019 di tutte le attivit\u00e0 svolte nel corso dello scorso anno<\/strong>, anche per mezzo di tabelle di dati e grafici, in ordine al controllo della qualit\u00e0 delle acque di balneazione, come pure delle risorse idriche superficiali e sotterranee, a beneficio dei cittadini, degli Enti locali e della Regione&#8221;. <strong>Lo evidenzia Danilo Magliocchetti, capogrupppo della Lega al comune di Frosinone. <\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"429\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/valle-sacco-e1548415408392.jpg\" alt=\"valle sacco inquinamento il corriere della provincia\" class=\"wp-image-5501\" \/><figcaption>Valle del Sacco e inquinamento<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Analogamente, \u00e8 l&#8217;ARPA Lazio a supportare la Regione nelle attivit\u00e0 di monitoraggio della qualit\u00e0 dell\u2019aria <\/strong>con la gestione della rete regionale di centraline di rilevamento fisse, con la realizzazione di campagne periodiche effettuate con mezzi mobili nelle zone del territorio regionale potenzialmente critiche, con l&#8217;uso di modelli di simulazioni di dispersione degli inquinanti, attraverso i quali garantisce la valutazione della qualit\u00e0 dell&#8217;aria sull&#8217;intero territorio regionale e la sua previsione a diverse cadenze temporali&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Ebbene, dalla lettura delle 114 pagine del rapporto emerge<\/strong>, in maniera chiara ed inequivocabile, peraltro un concetto noto, ma certificato anche da questo importante<strong> documento, come la Valle del Sacco costituisca ancora una enorme criticit\u00e0 ambientale ed il relativo processo di bonifica proceda con una lentezza disarmante&#8221;.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;A tal fine, due sono i punti particolarmente significati evidenziati dal rapporto.Uno a pag. 19, al punto sulle valutazioni della qualit\u00e0 dell\u2019aria, laddove \u00e8 scritto chiaramente anche per mezzo dei grafici che &#8216;<em>L\u2019Agglomerato di Roma e la Valle del Sacco sono le aree pi\u00f9 critiche: l\u2019Agglomerato di Roma registra superamenti dei valori limite di O3 e di NO2 mentre nella Valle del Sacco si registrano superamenti, oltre che per l\u2019O3, anche per il PM10 e il benzo(a)pirene. Relativamente all\u2019O3 la criticit\u00e0 riguarda tutte le zone del territorio regionale<\/em>La Valle del Sacco quindi risulta l\u2019unica, rispetto ad agglomerato di Roma, Zona Appenninica e Litoranea, a registrare ben 3 criticit\u00e0 per i superamenti di legge per PM 10, Ozono e Benzo Pirene.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;In ogni caso, dal Rapporto emerge una situazione di criticit\u00e0 per la Valle del Sacco anche per PM2.5 e Biossido di Azoto&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Ma vi \u00e8 di pi\u00f9, al Capitolo dedicato al monitoraggio del suolo a pag. 68, laddove si rileva che oltre la met\u00e0 dei siti oggetto di procedimento di bonifica, risulta localizzato nella provincia di Roma, seguita dalla provincia di Frosinone con il 21%, il Rapporto evidenzia questa situazione relativa al 2019 circa l\u2019iter del processo di bonifica&#8221;.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"445\" height=\"316\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/tabella-valle-del-sacco.jpg\" alt=\"\" class=\"wp-image-47390\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/tabella-valle-del-sacco.jpg 445w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/tabella-valle-del-sacco-300x213.jpg 300w\" sizes=\"auto, (max-width: 445px) 100vw, 445px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Come \u00e8 agevole constatare, nella valle del Sacco oltre ad essere presente il secondo numero di siti da bonificare <\/strong>dopo Roma, ne sono stati tuttavia conclusi appena 5, rispetto ai 51 di Latina e Viterbo e i 49 di Roma.Da questi dati incontestabili appare dunque, manifesta e certificata, la criticit\u00e0 ambientale della Valle del Sacco e la lentezza elefantiaca dei vari processi di bonifica. Per questo torno a richiedere con forza la nomina di un Commissario straordinario, che si occupi, in via esclusiva, dell\u2019indispensabile bonifica della Valle del Sacco&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Di questo passo occorreranno almeno altri 20 anni prima di poter apprezzare qualche risultato concreto.<strong> Il territorio, i Comuni e le attivit\u00e0 imprenditoriali non possono permettersi pi\u00f9 queste lungaggini burocratiche&#8221;.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;L\u2019Arpa ha pubblicato in queste ore, sul proprio sito istituzionale, il Rapporto 2019 di tutte le attivit\u00e0 svolte nel corso<\/p>\n","protected":false},"author":18,"featured_media":24085,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[520,633,537,94,858,93,295,809],"class_list":["post-47388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-ambiente","tag-arpa","tag-bonifica","tag-ciociaria","tag-danilo-magliocchetti","tag-frosinone","tag-lega","tag-valle-del-sacco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Valle del Sacco, Arpa certifica criticit\u00e0 e lungaggini. Magliocchetti: subito un commissario straordinario - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valle del Sacco, Arpa certifica criticit\u00e0 e lungaggini. Magliocchetti: subito un commissario straordinario\" \/>\n<meta property=\"og:description\" content=\"&#8220;L\u2019Arpa ha pubblicato in queste ore, sul proprio sito istituzionale, il Rapporto 2019 di tutte le attivit\u00e0 svolte nel corso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-25T07:48:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-25T08:02:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/danilo-magliocchetti-1-634x445.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"411\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Valle del Sacco, Arpa certifica criticit\u00e0 e lungaggini. Magliocchetti: subito un commissario straordinario\",\"datePublished\":\"2020-10-25T07:48:08+00:00\",\"dateModified\":\"2020-10-25T08:02:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/\"},\"wordCount\":531,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/danilo-magliocchetti-1-634x445.jpg\",\"keywords\":[\"ambiente\",\"arpa\",\"bonifica\",\"Ciociaria\",\"danilo magliocchetti\",\"Frosinone\",\"Lega\",\"valle del sacco\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/\",\"name\":\"Valle del Sacco, Arpa certifica criticit\u00e0 e lungaggini. Magliocchetti: subito un commissario straordinario - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/danilo-magliocchetti-1-634x445.jpg\",\"datePublished\":\"2020-10-25T07:48:08+00:00\",\"dateModified\":\"2020-10-25T08:02:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/danilo-magliocchetti-1-634x445.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/danilo-magliocchetti-1-634x445.jpg\",\"width\":630,\"height\":411},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valle del Sacco, Arpa certifica criticit\u00e0 e lungaggini. Magliocchetti: subito un commissario straordinario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/25\\\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Valle del Sacco, Arpa certifica criticit\u00e0 e lungaggini. Magliocchetti: subito un commissario straordinario - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/","og_locale":"it_IT","og_type":"article","og_title":"Valle del Sacco, Arpa certifica criticit\u00e0 e lungaggini. Magliocchetti: subito un commissario straordinario","og_description":"&#8220;L\u2019Arpa ha pubblicato in queste ore, sul proprio sito istituzionale, il Rapporto 2019 di tutte le attivit\u00e0 svolte nel corso","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-10-25T07:48:08+00:00","article_modified_time":"2020-10-25T08:02:57+00:00","og_image":[{"width":630,"height":411,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/danilo-magliocchetti-1-634x445.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Valle del Sacco, Arpa certifica criticit\u00e0 e lungaggini. Magliocchetti: subito un commissario straordinario","datePublished":"2020-10-25T07:48:08+00:00","dateModified":"2020-10-25T08:02:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/"},"wordCount":531,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/danilo-magliocchetti-1-634x445.jpg","keywords":["ambiente","arpa","bonifica","Ciociaria","danilo magliocchetti","Frosinone","Lega","valle del sacco"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/","name":"Valle del Sacco, Arpa certifica criticit\u00e0 e lungaggini. Magliocchetti: subito un commissario straordinario - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/danilo-magliocchetti-1-634x445.jpg","datePublished":"2020-10-25T07:48:08+00:00","dateModified":"2020-10-25T08:02:57+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/danilo-magliocchetti-1-634x445.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/danilo-magliocchetti-1-634x445.jpg","width":630,"height":411},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Valle del Sacco, Arpa certifica criticit\u00e0 e lungaggini. Magliocchetti: subito un commissario straordinario"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/25\/valle-del-sacco-arpa-certifica-criticita-e-lungaggini-magliocchetti-subito-un-commissario-straordinario\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/47388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=47388"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/47388\/revisions"}],"predecessor-version":[{"id":47392,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/47388\/revisions\/47392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/24085"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=47388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=47388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=47388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}